{"id":9877,"date":"2011-10-25T17:42:57","date_gmt":"2011-10-25T15:42:57","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=9877"},"modified":"2011-10-25T17:48:46","modified_gmt":"2011-10-25T15:48:46","slug":"corona-de-flores","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/corona-de-flores\/","title":{"rendered":"Corona de flores"},"content":{"rendered":"<p style=\"text-align: justify;\">\u00a1Otro m\u00e1s!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Y van tres.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Con <a href=\"http:\/\/elblogdejaviercalvo.blogspot.com\/\">Javier Calvo<\/a> ya son tres los autores espa\u00f1oles contempor\u00e1neos cuya obra huele. Y duele.<\/p>\n<p style=\"text-align: justify;\">\n<figure id=\"attachment_9878\" aria-describedby=\"caption-attachment-9878\" style=\"width: 357px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/10\/0l3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9878\" title=\"Javier Calvo\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/10\/0l3.jpg\" alt=\"\" width=\"357\" height=\"500\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/10\/0l3.jpg 357w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/10\/0l3-214x300.jpg 214w\" sizes=\"auto, (max-width: 357px) 100vw, 357px\" \/><\/a><figcaption id=\"caption-attachment-9878\" class=\"wp-caption-text\">Danger. Activo t\u00f3xico<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Huele a detritus, a descomposici\u00f3n, a sangre seca y cuajarones coagulados, a ambientes enrarecidos, a moho, a carne p\u00fatrida. Huele a mierda diarreica y cagalitrosa.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Novelas que duelen. Duele leerlas. Hasta el punto de que, a veces, hay que apartar los ojos de un p\u00e1rrafo especialmente escabroso. Duele tanto que acabas riendo. Por no llorar. Por no enloquecer. Porque lo grotesco y lo bizarro, es lo que tienen.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Novelas que, por la noche, cuando las ves en la mesilla de noche, esper\u00e1ndote, las sientes como una amenaza. Como una condena. Una condena, eso s\u00ed, que desde que pasas la primera p\u00e1gina, ya no admite aplazamientos, pr\u00f3rrogas o excarcelaciones.<\/p>\n<p style=\"text-align: justify;\">\n<figure id=\"attachment_9879\" aria-describedby=\"caption-attachment-9879\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/10\/09h3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9879\" title=\"Corona de flores calvo\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/10\/09h3-300x134.jpg\" alt=\"\" width=\"300\" height=\"134\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/10\/09h3-300x134.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/10\/09h3-1024x458.jpg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/10\/09h3.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-9879\" class=\"wp-caption-text\">La exposici\u00f3n genera adicci\u00f3n. La adicci\u00f3n conlleva efectos secundarios<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Porque la obra de Javier Calvo, como ocurre con la de <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2010\/06\/el-humo-en-la-botella\/\">Juan Ram\u00f3n Biedma<\/a> y la de <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2011\/05\/las-ninas-perdidas\/\">Cristina Fallar\u00e1s<\/a>, tambi\u00e9n es adictiva, enganch\u00e1ndote desde el primer pico, como hero\u00edna mal cortada, peor mezclada y tan corrompida que convierte cada viaje en una pesadilla con rumbo al infierno, hacia el final de la noche.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Est\u00e1 claro, por tanto, que no voy a recomendarte que leas esta novela. Te aprecio y te tengo cari\u00f1o. As\u00ed que no. Si lo haces, si la compras, si la lees; ser\u00e1 bajo tu propia responsabilidad.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><em>\u201cEl sol no derrama su luz enferma sobre las aguas grises. Las gaviotas no sueltan sus chillidos malhumorados por en encima de la Muralla de Mar. La tormenta ha convertido la calle de las Tapias en una marisma llena de remolinos traicioneros donde giran ratas muertas\u201d.<\/em><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00bfOs gusta el paisaje?<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Pues que conste que estamos en Barcelona. En el siglo XIX. La que fuera Ciudad de los Prodigios, narrada por Calvo, se convierte en una ciudad hostil, tenebrosa, sucia y amedrentadora. Una ciudad en la que el Asesino de la Esperanza est\u00e1 sembrando el terror. Y en la que un follet\u00edn conquista el encogido coraz\u00f3n de los habitantes de una ciudad a la deriva, acosada por la brutalidad de unas fuerzas policiales que no se sabe de qu\u00e9 lado est\u00e1n.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Y hay m\u00e9dicos, en esta historia. M\u00e9dicos que dar\u00edan la raz\u00f3n a qui\u00e9nes defend\u00edan que el c\u00e9lebre Jack el Destripador ten\u00eda que ser un galeno seducido por el lado oscuro.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u201cCorona de flores\u201d es una novela que supura fetidez. Por la noche, sin embargo, no pod\u00eda soltar su absorbente historia hasta que el sue\u00f1o me venc\u00eda y el libro se me ca\u00eda de las manos. Despu\u00e9s, las im\u00e1genes descritas por Calvo, sus s\u00e1dicos personajes y la interpretaci\u00f3n literaria de sus sue\u00f1os, me provocaban pesadillas.<\/p>\n<p style=\"text-align: justify;\">\n<figure id=\"attachment_9880\" aria-describedby=\"caption-attachment-9880\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/10\/09\u00f11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9880\" title=\"Corona de flores Calvo\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/10\/09\u00f11.jpg\" alt=\"\" width=\"510\" height=\"287\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/10\/09\u00f11.jpg 510w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/10\/09\u00f11-300x168.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><\/a><figcaption id=\"caption-attachment-9880\" class=\"wp-caption-text\">Pues s\u00ed. As\u00ed que quedas, mismamente, al leerla...<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Y al d\u00eda siguiente, al tomar el primer caf\u00e9 de la ma\u00f1ana, los amigos me miraban con mala cara y me preguntaban si todo iba bien\u2026<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">A\u00fan as\u00ed, con todo y con eso, \u00bfser\u00edas capaz de leerla?<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">T\u00fa mismo\/a<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens Espinosa de los Monteros.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">En <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2008\/10\/25\/\">2008<\/a>, <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2009\/10\/25\/\">2009<\/a> y <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2010\/10\/25\/\">2010<\/a>, tambi\u00e9n blogueamos, aunque m\u00e1s sosegadamente&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Otro m\u00e1s! Y van tres. Con Javier Calvo ya son tres los autores espa\u00f1oles contempor\u00e1neos cuya obra huele. Y duele. Huele a detritus, a descomposici\u00f3n, a sangre seca y cuajarones coagulados, a ambientes enrarecidos, a moho, a carne p\u00fatrida. Huele a mierda diarreica y cagalitrosa. Novelas que duelen. Duele leerlas. Hasta el punto de que, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[5520,5522,5521,469,21],"class_list":["post-9877","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","tag-corona-de-flores","tag-corona-de-flores-calvo","tag-javier-calvo","tag-mondadori","tag-negra-y-criminal"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/9877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=9877"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/9877\/revisions"}],"predecessor-version":[{"id":9882,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/9877\/revisions\/9882"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=9877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=9877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=9877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}