{"id":888,"date":"2008-12-27T12:59:42","date_gmt":"2008-12-27T11:59:42","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=888"},"modified":"2008-12-27T13:30:03","modified_gmt":"2008-12-27T12:30:03","slug":"deambulando-por-damasco","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/deambulando-por-damasco\/","title":{"rendered":"DEAMBULANDO POR DAMASCO"},"content":{"rendered":"<h4 style=\"text-align: justify;\">Eso estoy haciendo: deambular por Damasco. Primero, mis disculpas. Aqu&#8217;i no funciona ninguna de mis conexiones inalambricas, con lo que ni Twitter ni nada. Segundo, las comas, los acentos, etc. Un teclado desconocido, ya saben.<\/h4>\n<h4 style=\"text-align: justify;\">\u00a0<\/h4>\n<h4 style=\"text-align: justify;\">Llegue de madrugada y estaba Daniel en el aeropuerto de Damasco. Un afectuoso saludo despues, ya estabamos charlando como si no hubieran pasado cuatro anios desdela ultima\u00a0vez que nos vimos, despelotados de risa por el valor del presidente de Iran, dando un mensaje navidenio a los fieles musulmanes de Inglaterra en una fiesta cristiana.<\/h4>\n<h4 style=\"text-align: justify;\">\u00a0<\/h4>\n<h4 style=\"text-align: justify;\">Estoy en un hotel distinto a los otros companieros de viaje sirio. Hotel Europa. Encajado entre un dedalo de calles que el chofer tardo diez minutos en encontrar. Dormi bien, me desperte tarde y, claro, me eche a la calle. Hoy no tengo\u00a0prevista visita alguna asi que el objetivo, como me decia mi Alter a traves de\u00a0SMS, es deambular por las calles del viejo Damasco y dejarme impregnar por el ambiente de\u00a0la que pasa por ser la ciudad permanentemente habitada mas antigua del mundo. Y eso imprime caracter. Estas calles han sido pateadas por millones de personas desde hace miles de anios, sin solucion de continuidad. Y eso se nota.<\/h4>\n<h4 style=\"text-align: justify;\">Para desayunar me fui al Bazar de la ciudad\u00a0vieja. Habia prometido comerme alli un helado de pistacho en una cafeteria muy especial. Y lo hice. Junto a un par de croissanes y de cafes. Que de\u00a0inanicion no voy a perecer, creanme. Y me puse a escribir. A mano. En esos cuadernos que tanto me gustan. Y\u00a0pronto me sali del bazar. Que yahabra tiempo. Hoy es dia recorrer el Damasco de a pie,\u00a0el Damasco consuetudinario a sus habitantes. Sin museos\u00a0ni grandes monumentos. Eso ya, maniana. Y para eso, me gusta utilizar un truco conmigo mismo: buscar objetos de la vida normal en tiendas normales.<\/h4>\n<h4 style=\"text-align: justify;\">Nada de los tipicos regalos u objetos turisticos que, como digo, ya habra tiempo de todo ello. Me gusta buscar fixo, papel celo para pegar en mis cuadernos etiquetas, entradas y demas. Y no es facil encontrar fixo cuando no tienes ni pajolera ideade arabe. Pero asi entras en las tiendas, curioseas e intentas comunicarte con el dependiente. O un adaptador para la la electricidad y los enchufes, de tres agujeritos finos. Antes me traia todo esto desde casa. Ahora, cuando vengo a un viaje tranquilo, con tiempo libre, que son los que me gustan, me dedico a buscar esos objetos tranquilamente. Me gusta entrar en las tiendas y ver que compra la gente. Me gusta pasear por los mercados y ver que comen. Por deformacion profesional, me gusta entrar en los Bancos y ver los terminales y ordenadores. Y, por supuesto, me gusta entrar en las librer&#8217;ias. Y para eso tengo una excusa negrocriminal&#8230; que otro dia les cuento.<\/h4>\n<h4 style=\"text-align: justify;\">Me gusta escuchar lo que la gente escucha en la radio. El cadena Dial de Damasco. O a sus tertulianos. Aunque reconozco que con el arabe radiado me pasa como con el aleman: siempre tengo la sensacion de que me esta cayendo una bronca por algo, como siel modelo de Federico Jimenez Losantos cabreado como una mona se hubiese expandido por el mundo musulman.<\/h4>\n<h4 style=\"text-align: justify;\">Amigos, siento no contarles nada sobre la Gran Mezquita o el Museo Arqueologico. Si me pillo un buen cibercafe, maniana y pasado. De momento, me estoy dedicando a deambular por las calles de Damasco, sin horarios, sin objetivo, sin pretensiones. Me gusta ver las caras de la gente y sortear el infernal trafico de las grande avenidas, en las que los semaforos brillan por su ausencia. Ahi reconozco ser un cobarde. Para cruzar, me espero a que venga un lugarenio y me situo detras de el, como si fuera un escudo humano que me proteja de los coches-bala. Y hago lo que el hace. Si es un temerario, me acojono. Si es un conservador, me desespero esperando. Pero yo, como los ninios chicos: pegadito a mi protector \ud83d\ude42<\/h4>\n<h4 style=\"text-align: justify;\">Les dejo. Empieza\u00a0a ser hora de comer. Me volvi para mi barrio, par ubicarme, que luego anochece temprano y me pierdo fijo. Mis dos referencias son la vieja estacion de tren donde se filmo la llegada de Lawernce de Arabia a Damasco en la pelicula de David Lean, despues, un asadero de pollos, la calle de las librerias y una mezquita. A ver si despues, por la noche, todo sigue en su sitio.<\/h4>\n<h4 style=\"text-align: justify;\">PD.- El tipo del ciber me mira mal. Perdonen que no responda a sus comentarios. Pero no dejen de hacerlos, que no saben como se agradecen al conectar un rato con el mundanal ruido. Un abrazo para todos.<\/h4>\n<h4 style=\"text-align: justify;\">Jesus Lens, deambulando por las calles de Damasco.<\/h4>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<h3 style=\"text-align: justify;\">PD II.- Leo lo de Gaza y el bombardeo de Israel&#8230; y se me ponen los pelos de punta. Uf. Como decia antes, esperemos que la comunidad chiita de Siria y, sobre todo, Hezbola en Beirut esten tranquilos. Navidad sangrienta. Que pena de esta parte del mundo, siempre tenida de sangre, maldita. Que pena, Palestina, desangrada. Que pena. Mi solidaridad con las familias de esos doscientos muertos. Que horror. Ahora casi que salir a pasear es ingrato, como un insulto a esas personas que ahora sufren. No se. Ya les cuento despues.\u00a0\u00a0<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Eso estoy haciendo: deambular por Damasco. Primero, mis disculpas. Aqu&#8217;i no funciona ninguna de mis conexiones inalambricas, con lo que ni Twitter ni nada. Segundo, las comas, los acentos, etc. Un teclado desconocido, ya saben. \u00a0 Llegue de madrugada y estaba Daniel en el aeropuerto de Damasco. Un afectuoso saludo despues, ya estabamos charlando como [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[24],"tags":[213,212,243,24],"class_list":["post-888","post","type-post","status-publish","format-standard","hentry","category-viajes","tag-damasco","tag-siria","tag-viajar","tag-viajes"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=888"}],"version-history":[{"count":4,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/888\/revisions"}],"predecessor-version":[{"id":890,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/888\/revisions\/890"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}