{"id":879,"date":"2008-12-25T12:39:36","date_gmt":"2008-12-25T11:39:36","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=879"},"modified":"2008-12-25T13:05:43","modified_gmt":"2008-12-25T12:05:43","slug":"liblogs-yerma-en-el-libano","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/liblogs-yerma-en-el-libano\/","title":{"rendered":"LIBLOGS: YERMA EN EL L\u00cdBANO"},"content":{"rendered":"<p style=\"text-align: justify;\">Hay libros que, por el momento personal y vital en que los lees, se te incrustan en la piel y, adem\u00e1s de provocarte muchas y variadas sensaciones, te dejan una huella indeleble de por vida. A m\u00ed me ha pasado con \u00abYerma\u00bb, le\u00eddo de un tir\u00f3n en una tarde de invierno y cuyo recuerdo me viene acompa\u00f1ando desde entonces, como espada de Damocles que pende sobre mi cabeza.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2008\/12\/_0142.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-881 aligncenter\" title=\"Yerma\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2008\/12\/_0142.jpg\" alt=\"\" width=\"500\" height=\"337\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2008\/12\/_0142.jpg 500w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2008\/12\/_0142-300x202.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Hace un par de noches, cansado, roto, volv\u00eda a casa en taxi. El conductor ten\u00eda ganas de charlar y me pregunt\u00f3 por las Navidades. Le dije que las pasar\u00eda en el L\u00edbano y, como un resorte, me volvi\u00f3 a preguntar: <em>\u00ab\u00bfEs usted soldado?\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Me qued\u00e9 de una pieza. \u00bfSoldado? Pues no. Un simple turista. El hombre no volvi\u00f3 a hablar, me dej\u00f3 en casa y me dese\u00f3 felices navidades. Al d\u00eda siguiente, una amiga me preguntaba si estaba nervioso por mi inminente viaje. <em>\u00abNo\u00bb<\/em>, le contest\u00e9. <em>\u00abNi nervioso, ni ansioso, ni expectante, ni excitado.\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Y me sent\u00ed yermo. Vac\u00edo. Fue entonces cuando me decid\u00ed a escribir las palabras de esa entrada tan gratamente recibida y comentada: <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=850\"><span style=\"color: #ff0000;\"><strong>\u00abL\u00edbano: escapar viajando\u00bb<\/strong><\/span><\/a>. Un texto que es duro de escribir&#8230; si sientes todas y cada una de las palabras y las sensaciones que en \u00e9l se reflejan, como a m\u00ed me pasaba.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Hasta ahora, pr\u00e1cticamente no le he prestado atenci\u00f3n al destino de este viaje. L\u00edbano. He mirado la p\u00e1gina del Ministerio de Asuntos Exteriores y, de hacerle caso, lo mejor ser\u00eda no poner all\u00ed un pie. Recuerdo que, cuando empez\u00f3 la \u00faltima guerra libanesa, hace unos meses, con el ego\u00edsmo propio de los viajeros, pens\u00e9 para mis adentros que era una pena, que ya hab\u00eda otro pa\u00eds que, de momento, se hab\u00eda convertido en destino vetado. Y, sin embargo, apenas unos meses despu\u00e9s, all\u00e1 me voy. Al L\u00edbano.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Ya les he contado que la \u00abculpa\u00bb de todo la tiene <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=798\"><span style=\"color: #ff0000;\"><strong>Daniel<\/strong><\/span><\/a>. Y a \u00e9l me encomiendo, l\u00f3gicamente, para culminar un viaje bonito, ilustrativo y satisfactorio. Dec\u00eda que quer\u00eda aprovechar este viaje para reflexionar sobre tantas y tantas cosas de mi vida, pasada, presente y futura. Otra amiga (siempre son las mujeres las que ponen el dedo en la llaga) me dec\u00eda que me dejase de tonter\u00edas y que aprovechara el viaje para disfrutar, pasarlo bien, ser receptivo a los compa\u00f1eros que me encuentre por el camino, descubrir nuevos paisajes y, sencillamente, gozar con las bondades de una oportunidad \u00fanica: viajar a un destino tan atractivo como complicado. Viajar.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2008\/12\/_0311.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-883 aligncenter\" title=\"Viajar\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2008\/12\/_0311.jpg\" alt=\"\" width=\"312\" height=\"450\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2008\/12\/_0311.jpg 312w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2008\/12\/_0311-208x300.jpg 208w\" sizes=\"auto, (max-width: 312px) 100vw, 312px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Por eso me gust\u00f3 tanto, al llegar a casa, encontrar el mensaje de otra excelente c\u00f3mplice que, desde la distancia, ya me va conociendo sobradamente. Un mensaje repleto de buenos augurios, que se concretaban en la siguiente m\u00e1xima de Tuc\u00eddides: <strong><em>\u00abEl secreto de la felicidad no est\u00e1 en hacer siempre lo que se quiere, sino en querer siempre lo que se hace. El secreto de la felicidad est\u00e1 en la libertad, y el secreto de la libertad, en el coraje\u00bb<\/em><\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Yerma se cas\u00f3 porque quer\u00eda tener un hijo. Y no consigui\u00f3 concebirlo. Y su vida fue un infierno. Y la de su marido. No hab\u00eda otra cosa que le importara que no fuera la sequedad de su vientre. Y as\u00ed consumi\u00f3 su existencia. Y, por fin, cuando comprendi\u00f3 que jam\u00e1s se quedar\u00eda pre\u00f1ada, no se resign\u00f3 y, en vez de procurar construir una vida en torno a su esposo, lo asesin\u00f3. El fatalismo de los personajes de Garc\u00eda Lorca, la autodestrucci\u00f3n, el sufrimiento, la muerte&#8230; todo ello tan nuestro&#8230; no. Hay que rebelarse.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Cuando escribo estas l\u00edneas me quedan menos de cuatro horas para emprender mi viaje. He de preparar el petate, comer y salir para la estaci\u00f3n de autobuses. Es verdad que, si lo pienso, no es irme al L\u00edbano, ahora lo que quiero hacer. Pero no es menos cierto que, como lo voy a hacer, lo estoy empezando a querer.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">S\u00ed. Ya estoy nervioso. Me falta un visado para Siria que suplo con una carta de una agencia de viajes, escrita en \u00e1rabe, y que no s\u00e9 si me dar\u00e1 problemas en Estambul, donde hago escala. S\u00ed. Ya ando revisando los billetes y los itinerarios. S\u00ed. Ya ando eligiendo qu\u00e9 lecturas me van a acompa\u00f1ar. S\u00ed. Ya voy notando esas mariposas en las tripas que me dicen que s\u00ed. Que quiero viajar. Que dejo cosas atr\u00e1s, pero que me esperan muchas m\u00e1s por ah\u00ed delante. Estos d\u00edas, en Oriente. Y a la vuelta, claro. Libertad para irme. Y para volver. Coraje para apretar los dientes&#8230; y seguir de frente.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2008\/12\/_0261.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-882 aligncenter\" title=\"Yerma\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2008\/12\/_0261.jpg\" alt=\"\" width=\"263\" height=\"420\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2008\/12\/_0261.jpg 263w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2008\/12\/_0261-187x300.jpg 187w\" sizes=\"auto, (max-width: 263px) 100vw, 263px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Perdonen que haya usado la excusa de los Liblogs y de \u00abYerma\u00bb para hablar de m\u00ed, pero, por un lado, es la grandeza de la literatura: conseguir integrarse en nuestra vida. Y, por otro, \u00bfqu\u00e9 podr\u00eda decir yo sobre \u00abYerma\u00bb que no se haya dicho ya, hasta la saciedad, por centenares de estudiosos y especialistas de la obra lorquiana?<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Haciendo de la necesidad virtud, un c\u00e1lido abrazo viajero y mediterr\u00e1neo para todos.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens Espinosa de los Monteros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hay libros que, por el momento personal y vital en que los lees, se te incrustan en la piel y, adem\u00e1s de provocarte muchas y variadas sensaciones, te dejan una huella indeleble de por vida. A m\u00ed me ha pasado con \u00abYerma\u00bb, le\u00eddo de un tir\u00f3n en una tarde de invierno y cuyo recuerdo me [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[37,24],"tags":[258,69,37,44,97,24,257],"class_list":["post-879","post","type-post","status-publish","format-standard","hentry","category-liblogs","category-viajes","tag-federico-garcia-lorca","tag-libano","tag-liblogs","tag-poesia","tag-teatro","tag-viajes","tag-yerma"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=879"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/879\/revisions"}],"predecessor-version":[{"id":884,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/879\/revisions\/884"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}