{"id":8146,"date":"2011-02-15T18:41:07","date_gmt":"2011-02-15T16:41:07","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=8146"},"modified":"2011-02-15T18:41:07","modified_gmt":"2011-02-15T16:41:07","slug":"cityville-cuestion-de-estilo","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/cityville-cuestion-de-estilo\/","title":{"rendered":"CITYVILLE, CUESTI\u00d3N DE ESTILO"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>\u00bfVeis como seguir\u00edamos encontr\u00e1ndonos en IDEAL? Hoy publicamos este art\u00edculo, sobre un jueguecito que arrasa en Internet\u2026 \u00bfnos habremos vuelto locos o t\u00fa tambi\u00e9n cosechas, abres comercios y expandes tu ciudad?<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong><em>\ud83d\ude42<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">David quer\u00eda poner una lavander\u00eda en la parcela libre que hab\u00eda en mi ciudad, pero le dije que nones. Que por mucha pasta que dejara, y no teniendo nada en contra de un negocio tan higi\u00e9nico como imprescindible, prefer\u00eda instalar una sucursal de su franquicia de librer\u00edas, llamada IDEAL, por cierto.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">El alcalde de Danville me insist\u00eda en que la lavander\u00eda era un negocio mejor. Y yo no lo dudaba, pero prefer\u00eda la librer\u00eda. Por afinidad personal y, tambi\u00e9n, por cuesti\u00f3n de est\u00e9tica. De estilo.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Yo no s\u00e9 cu\u00e1ntos de vosotros tendr\u00e9is vuestra propia ciudad, a trav\u00e9s del Facebook, pero ya somos m\u00e1s de cien millones de personas las que jugamos al Citiville, un juego que, a tres meses de las elecciones municipales, cobra todo su sentido.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/barackyourself1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8147\" title=\"Cityville\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/barackyourself1.jpg\" alt=\"\" width=\"486\" height=\"720\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/barackyourself1.jpg 486w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/barackyourself1-202x300.jpg 202w\" sizes=\"auto, (max-width: 486px) 100vw, 486px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Por ejemplo, en mi ciudad, Makumba, he abierto dos muelles que proveen de productos y mercader\u00eda los negocios de la localidad, por lo que la huerta ya no es tan necesaria como hasta ahora. Eso de plantar, cosechar y almacenar consume mucha energ\u00eda, la verdad, y los especuladores inmobiliarios claman por esos espacios para construir apartamentos, una inversi\u00f3n mucho m\u00e1s rentable. Pero yo, paso. Mi ciudad es como es gracias a las cosechas de ma\u00edz, ar\u00e1ndanos y calabazas as\u00ed que, no les voy a dar la espalda a mis ra\u00edces. Y por muchos productos que vengan de China, Dubai o Estados Unidos, como los tomatitos caseros, nada de nada.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Otra caracter\u00edstica de mi ciudad: no renuncio a los edificios de ladrillo t\u00edpicos de mi particular Little Italy ni quiero cementar mi paseo mar\u00edtimo con grandes torres de apartamentos. Adem\u00e1s, creo que imitar\u00e9 la justicia redistributiva de Cristina, que en su Plan de Reordenaci\u00f3n Urbana ha llevado las huertas, granjas y almacenes a los barrios de rascacielos y ha dejado las canchas deportivas, bibliotecas y museos en las zonas modestas de su ciudad. \u00a1Eso es estilo!<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/08.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-8148\" title=\"Cityville\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/08-300x240.png\" alt=\"\" width=\"300\" height=\"240\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/08-300x240.png 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/08.png 514w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Sin embargo, mi Makumba es un caos. He de reconocerlo. Ha experimentado un r\u00e1pido crecimiento y los edificios y negocios est\u00e1n api\u00f1ados en las parcelas, amontonados. Apenas hay zonas verdes. Por eso espero la ayuda y asesoramiento de David, cuya referida Danville es un ejemplo a seguir de desarrollo urban\u00edstico sostenible y peatonal, lleno de \u00e1rboles y jardines, monumentos, estatuas y flores de buen gusto. De momento, la zona de expansi\u00f3n de mi ciudad sigue vac\u00eda, esperando una buena y acertada intervenci\u00f3n que aleje el fantasma de la contaminaci\u00f3n de ciudades como Madrid, estos d\u00edas convertida en la c\u00e9lebre Poisonville narrada por Hammett en sus novelas negras.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/09r4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8149\" title=\"Cityville\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/09r4.jpg\" alt=\"\" width=\"475\" height=\"318\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/09r4.jpg 475w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/09r4-300x200.jpg 300w\" sizes=\"auto, (max-width: 475px) 100vw, 475px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Por cuanto a los negocios, me sorprende que mi asesor en franquicias me urja a montar un cine. Pero me gusta. Va contra el signo de los tiempos. Y, aunque tengo ofertas casi irrechazables para invertir el efectivo disponible en la caja del ayuntamiento en aventuras empresariales de r\u00e1pido crecimiento, estoy ahorrando para construir una cancha de baloncesto.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Lo que dec\u00eda al principio: cuesti\u00f3n de estilo. Y modelo de ciudad. Lo que, extrapol\u00e1ndolo a nuestras pr\u00f3ximas elecciones municipales, deber\u00eda hacernos reflexionar, m\u00e1s all\u00e1 de caras, nombres y siglas. \u00bfQu\u00e9 modelo de ciudad nos ofrecen, unos y otros?<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens Espinosa de los Monteros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfVeis como seguir\u00edamos encontr\u00e1ndonos en IDEAL? Hoy publicamos este art\u00edculo, sobre un jueguecito que arrasa en Internet\u2026 \u00bfnos habremos vuelto locos o t\u00fa tambi\u00e9n cosechas, abres comercios y expandes tu ciudad? \ud83d\ude42 David quer\u00eda poner una lavander\u00eda en la parcela libre que hab\u00eda en mi ciudad, pero le dije que nones. Que por mucha pasta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[4334,4335,1678,4336,4246,4338,4339,6,4337],"class_list":["post-8146","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-cityville","tag-danville","tag-david","tag-david-danville","tag-elecciones-municipales","tag-juegos-zynga","tag-municipales-2011","tag-opinion","tag-zynga"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/8146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=8146"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/8146\/revisions"}],"predecessor-version":[{"id":8150,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/8146\/revisions\/8150"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=8146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=8146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=8146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}