{"id":8137,"date":"2011-02-14T23:23:31","date_gmt":"2011-02-14T21:23:31","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=8137"},"modified":"2011-02-15T09:47:14","modified_gmt":"2011-02-15T07:47:14","slug":"cine-dentro-del-cine","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/cine-dentro-del-cine\/","title":{"rendered":"CINE DENTRO DEL CINE"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Antes de cambiar nuevamente de puesto de trabajo, dejamos ultimado este proyecto, que arranca el martes 15. Le hemos puesto todo el cari\u00f1o y la dedicaci\u00f3n. Espero que lo sig\u00e1is con mimo y detenimiento.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">AulaCine CajaGranada presenta, el primer semestre de 2011, un ciclo muy especial: \u201cCine dentro del Cine\u201d, a trav\u00e9s del que queremos mostrar c\u00f3mo los cineastas han reflexionado sobre su propio oficio, desde un punto de vista tanto art\u00edstico como industrial y comercial.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/06.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8138\" title=\"Cine dentro del cine\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/06.png\" alt=\"\" width=\"322\" height=\"210\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/06.png 322w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/06-300x195.png 300w\" sizes=\"auto, (max-width: 322px) 100vw, 322px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">La selecci\u00f3n de t\u00edtulos realizada nos sirve para tener una visi\u00f3n amplia, completa y diferente sobre la esencia y el ejercicio del propio cine: qu\u00e9 es y qu\u00e9 deber\u00eda ser. De d\u00f3nde viene y hacia d\u00f3nde va. Y hacia d\u00f3nde deber\u00eda ir.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">El ciclo se organiza en torno a tres ejes tem\u00e1ticos sucesivos y complementarios:<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">En primer lugar, el cine como arte, como profesi\u00f3n, como pasi\u00f3n; de cara a los propios cineastas y, en consecuencia, lo que el cine supuso para los espectadores. El cine como refugio, como v\u00eda de escape, como liberaci\u00f3n, como adicci\u00f3n; de cara a los aficionados. Por \u00faltimo, el cine como negocio, como industria, como f\u00e1brica de estrellas, pero tambi\u00e9n como front\u00f3n en el que se estrellan los sue\u00f1os.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/09r3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8139\" title=\"El crep\u00fasculo de los dioses\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/09r3.jpg\" alt=\"\" width=\"350\" height=\"277\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/09r3.jpg 350w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/09r3-300x237.jpg 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Con este ciclo queremos resaltar las relaciones del cine con la vida real, c\u00f3mo se influyen mutuamente y c\u00f3mo el cine, muchas veces, puede ser m\u00e1s importante que la propia existencia, colaborando a transformarla y a hacerla un poquito mejor.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">La selecci\u00f3n hecha incluye pel\u00edculas de \u00e9pocas muy distintas, directores muy variados y filmograf\u00edas muy diferentes.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Un ciclo que, dadas las muchas lecturas que tiene y las m\u00faltiples posibilidades que ofrece, nos va a permitir abordar variadas perspectivas sobre el arte total, el arte m\u00e1s definitorio del siglo XX. Una mezcla de arte y negocio convertida en una todopoderosa industria que ha favorecido una colonizaci\u00f3n cultural sin precedentes a trav\u00e9s de la difusi\u00f3n en Technicolor de un American Way of Life tan arrasador como te\u00f3ricamente incuestionable.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Este cuadernillo se ha confeccionado siguiendo el orden de exhibici\u00f3n de las pel\u00edculas en el Teatro CajaGranada.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/Enric52.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8142  aligncenter\" title=\"Cine dentro del cine\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/Enric52-210x300.jpg\" alt=\"\" width=\"210\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/Enric52-210x300.jpg 210w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/Enric52-717x1024.jpg 717w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/Enric52.jpg 738w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00a1Advertencia!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Las rese\u00f1as que componen esta publicaci\u00f3n contienen datos relevantes sobre la trama de las pel\u00edculas. Si el espectador a\u00fan no las ha visto, aunque la mayor\u00eda de ellas son cl\u00e1sicos del cine de todos los tiempos, le recomendamos que no lea estas rese\u00f1as hasta despu\u00e9s de su visionado. <span style=\"color: #ff0000;\">(<\/span><a href=\"http:\/\/www.memoriadeandalucia.com\/opencms\/export\/sites\/default\/CajaGranada\/recursos\/documentos\/GuiaAulaCine_febrero-junio_20116M.pdf\"><span style=\"color: #ff0000;\"><strong>AQU\u00cd<\/strong><\/span><\/a><span style=\"color: #ff0000;\"><strong> <\/strong>puedes descargar la Gu\u00eda completa del Ciclo, que hemos preparado los responsables de AulaCine)<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/09l4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8140\" title=\"Facebook\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/02\/09l4.jpg\" alt=\"\" width=\"200\" height=\"183\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y, antes de terminar, una petici\u00f3n: el d\u00eda de proyecci\u00f3n de la pel\u00edcula, <a href=\"http:\/\/www.facebook.com\/pages\/Centro-Cultural-CajaGRANADA-y-Memoria-de-Andalucia\/284846750688\">en el Facebook del Centro Cultural CajaGRANADA<\/a> aparecer\u00e1 un enlace con las rese\u00f1as que ten\u00e9is aqu\u00ed impresas, a partir de las que organizaremos un Cine F\u00f3rum virtual al que os invitamos a sumaros, esperando vuestros comentarios, cr\u00edticas y reflexiones.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antes de cambiar nuevamente de puesto de trabajo, dejamos ultimado este proyecto, que arranca el martes 15. Le hemos puesto todo el cari\u00f1o y la dedicaci\u00f3n. Espero que lo sig\u00e1is con mimo y detenimiento. AulaCine CajaGranada presenta, el primer semestre de 2011, un ciclo muy especial: \u201cCine dentro del Cine\u201d, a trav\u00e9s del que queremos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[3685,3686,4319],"class_list":["post-8137","post","type-post","status-publish","format-standard","hentry","category-cine","tag-aulacine","tag-aulacine-cajagranada","tag-cine-dentro-del-cine"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/8137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=8137"}],"version-history":[{"count":4,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/8137\/revisions"}],"predecessor-version":[{"id":8144,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/8137\/revisions\/8144"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=8137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=8137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=8137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}