{"id":7848,"date":"2011-01-03T13:57:13","date_gmt":"2011-01-03T11:57:13","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=7848"},"modified":"2011-01-03T14:29:39","modified_gmt":"2011-01-03T12:29:39","slug":"pan","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/pan\/","title":{"rendered":"PAN"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>\u00bfQu\u00e9 tal un Cuentito para seguir comenzando el a\u00f1o? A ver qu\u00e9 os parece esta peque\u00f1a pieza de orfebrer\u00eda artesanal, casero, casero&#8230;<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><em>.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Era domingo 2 de enero por la ma\u00f1ana. Mi santo. Hab\u00eda le\u00eddo el primer IDEAL del a\u00f1o 2011, cargado de contenido, mientras desayunaba en \u201cEl Madero\u201d, como casi todos los fines de semana. Antes de volver a casa, fui por el pan.<\/p>\n<p style=\"text-align: justify;\">Estaba reci\u00e9n horneada y decir que ol\u00eda que alimentaba ser\u00eda hacerle flaca justicia a esa barra de pan, tan tostadita y curruscante, justo como a m\u00ed me gusta. Estaba tan crujiente que el pan exig\u00eda, a voces, ejecutar ese rito que todos hemos cumplimentado alguna vez: arrancarle la tetilla y comerla mientras caminas por la calle, con gula, placer y delectaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Estaba ya ech\u00e1ndole mano al extremo m\u00e1s puntiagudo de la barra cuando un peque\u00f1o demonio me meti\u00f3 una idea en la cabeza: \u201cresiste la tentaci\u00f3n un par de minutos m\u00e1s, acelera el paso y reg\u00e1late a ti mismo una rebanada de pan reci\u00e9n hecho, con aceite y el jam\u00f3n ib\u00e9rico que te sobr\u00f3 en Nochevieja\u201d.<\/p>\n<p style=\"text-align: justify;\">Listo, el condenado demonio. Conoci\u00e9ndome, sab\u00eda que si me com\u00eda la tetilla me entrar\u00edan remordimientos por los excesos cometidos durante estas fechas y, al llegar a casa, me dar\u00eda por contento con el suculento y clandestino bocado de pan callejero.<\/p>\n<p style=\"text-align: justify;\">Sub\u00ed a casa en una volada, saqu\u00e9 el pan de la bolsa de papel en que ven\u00eda envuelto y lo dej\u00e9 sobre la encimera de la cocina para ir al ba\u00f1o a lavarme las manos,\u00a0manchadas con la tinta del peri\u00f3dico.<\/p>\n<p style=\"text-align: justify;\">La sorpresa lleg\u00f3 al volver a la cocina y encontrar con que a la barra le faltaba justo la tetilla m\u00e1s puntiaguda y apetecible.<\/p>\n<p style=\"text-align: justify;\">Lo que no tendr\u00eda que haberme extra\u00f1ado\u2026 de no ser porque vivo solo y esa ma\u00f1ana, en casa, no hab\u00eda un alma.<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 tal un Cuentito para seguir comenzando el a\u00f1o? A ver qu\u00e9 os parece esta peque\u00f1a pieza de orfebrer\u00eda artesanal, casero, casero&#8230; . Era domingo 2 de enero por la ma\u00f1ana. Mi santo. Hab\u00eda le\u00eddo el primer IDEAL del a\u00f1o 2011, cargado de contenido, mientras desayunaba en \u201cEl Madero\u201d, como casi todos los fines de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[31],"tags":[4120,930,4137,31],"class_list":["post-7848","post","type-post","status-publish","format-standard","hentry","category-relatos","tag-carlitos","tag-cuentos","tag-pan","tag-relatos"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/7848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=7848"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/7848\/revisions"}],"predecessor-version":[{"id":7850,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/7848\/revisions\/7850"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=7848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=7848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=7848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}