{"id":7605,"date":"2010-12-02T14:42:47","date_gmt":"2010-12-02T12:42:47","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=7605"},"modified":"2010-12-02T14:42:47","modified_gmt":"2010-12-02T12:42:47","slug":"la-playa-de-los-ahogados","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-playa-de-los-ahogados\/","title":{"rendered":"LA PLAYA DE LOS AHOGADOS"},"content":{"rendered":"<p style=\"text-align: justify;\">Vaya por delante que, para m\u00ed, Galicia es como una tierra m\u00edtica, imaginaria, fant\u00e1stica y fabulosa. Como Macondo para Garc\u00eda M\u00e1rquez o el condado de Yoknapatawpha para Faulkner, pero desde una perspectiva lectora. Galicia, desde sus bosques, su Camino de Santiago, su Prisciliano, sus Celtas, sus castros y su Santa Compa\u00f1a hasta, por supuesto, la Costa da Morte.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/12\/Cusco4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7606  aligncenter\" title=\"Costa da Morte\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/12\/Cusco4-300x198.jpg\" alt=\"\" width=\"300\" height=\"198\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/12\/Cusco4-300x198.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/12\/Cusco4.jpg 700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Por todo ello, las novelas radicadas en Galicia, para m\u00ed, tienen un valor a\u00f1adido, un plus especial que me predispone a su favor. Y, la verdad, no s\u00e9 por que he tardado tanto en leer \u201cLa playa de los ahogados\u201d, de Domingo Villar, m\u00e1xime cuando su debut literario, \u201cOjos de agua\u201d, me dej\u00f3 un inmejorable sabor de boca.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/12\/Enric2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7607  aligncenter\" title=\"La playa de los ahogados\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/12\/Enric2-192x300.jpg\" alt=\"\" width=\"192\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/12\/Enric2-192x300.jpg 192w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/12\/Enric2.jpg 600w\" sizes=\"auto, (max-width: 192px) 100vw, 192px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Hay aficionados al noir que est\u00e1n un poco hartos de los polic\u00edas y detectives de novela negra mediterr\u00e1nea que comen y beben bien y, adem\u00e1s, hacen gala de ello. Leo Caldas es uno de estos. Y es que la gastronom\u00eda se ha convertido en un arma de resistencia frente a la hegemon\u00eda yanqui de las hamburguesas y la comida basura, el bourbon y los bebedores solitarios. Nuestros personajes de novela negra prefieren el lac\u00f3n y la pata, los buenos caldos gallegos y tertulias como las del Sanedr\u00edn de sabios que se re\u00fane en el restaurante de referencia del protagonista.<\/p>\n<p style=\"text-align: justify;\">Un protagonista divorciado, s\u00ed. Pero que no anda llorando por las esquinas de cada p\u00e1gina de la novela, empap\u00e1ndose en alcohol o cultivando otro tipo de vicios o perversiones m\u00e1s siniestras. De hecho, a Leo Caldas se le conoce como \u201cEl patrullero de las Ondas\u201d por el programa de radio que hace todas las semanas y que le ha convertido en una estrella medi\u00e1tica cuya fama le precede all\u00e1 por donde va.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/12\/elsaenportada.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7608  aligncenter\" title=\"Domingo Villar\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/12\/elsaenportada-300x235.jpg\" alt=\"\" width=\"300\" height=\"235\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/12\/elsaenportada-300x235.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/12\/elsaenportada.jpg 318w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y tiene como compa\u00f1ero a Rafael Est\u00e9vez, un sujeto de Zaragoza al que le sigue costando muy mucho hacerse con las peculiaridades del ser gallego. Sobre todo en los interrogatorios a los sospechosos en los que cada pregunta es respondida con otra pregunta, por supuesto.<\/p>\n<p style=\"text-align: justify;\">En \u201cLa playa de los ahogados\u201d, ambos polic\u00edas han de investigar si la muerte del marinero Justo Castedo es un suicidio o hay algo m\u00e1s. Y para resolver el enigma de dicha muerte, adem\u00e1s de hablar con los vecinos del pueblo en que vivi\u00f3 Castedo, habr\u00e1 que ir hacia atr\u00e1s en el tiempo ya que hay fantasmas del pasado sin enterrar que, quiz\u00e1, est\u00e9n pidiendo justicia desde el M\u00e1s All\u00e1. \u00bfO ser\u00e1 desde el M\u00e1s Ac\u00e1?<\/p>\n<p style=\"text-align: justify;\">Una novela de personajes, con los ambientes muy bien descritos y con una trama dividida en dos tiempos, en dos \u00e9pocas, perfectamente hilada y conducida por un Domingo Villar que ha logrado lo m\u00e1s dif\u00edcil de conseguir con una segunda novela: responder a las enormes expectativas que hab\u00eda levantado con su debut literario.<\/p>\n<p style=\"text-align: justify;\">Ya esperamos la tercera. Y, desde luego, no tardaremos tanto en leerla como hemos tardado con \u00e9sta.<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas <strong><em>el Gallego en la distancia<\/em><\/strong>\u00a0Lens.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vaya por delante que, para m\u00ed, Galicia es como una tierra m\u00edtica, imaginaria, fant\u00e1stica y fabulosa. Como Macondo para Garc\u00eda M\u00e1rquez o el condado de Yoknapatawpha para Faulkner, pero desde una perspectiva lectora. Galicia, desde sus bosques, su Camino de Santiago, su Prisciliano, sus Celtas, sus castros y su Santa Compa\u00f1a hasta, por supuesto, la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[3981,3980,1867,3979,49,21],"class_list":["post-7605","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","tag-costa-da-morte","tag-domingo-villar","tag-galicia","tag-la-playa-de-los-ahogados","tag-libros","tag-negra-y-criminal"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/7605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=7605"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/7605\/revisions"}],"predecessor-version":[{"id":7609,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/7605\/revisions\/7609"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=7605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=7605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=7605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}