{"id":7512,"date":"2010-11-23T00:29:12","date_gmt":"2010-11-22T22:29:12","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=7512"},"modified":"2010-11-23T00:31:45","modified_gmt":"2010-11-22T22:31:45","slug":"esperanza-spalding-cierra-el-festival-de-jazz-de-granada","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/esperanza-spalding-cierra-el-festival-de-jazz-de-granada\/","title":{"rendered":"ESPERANZA SPALDING CIERRA EL FESTIVAL DE JAZZ DE GRANADA"},"content":{"rendered":"<p style=\"text-align: justify;\">No fue el mejor concierto del Festival, la verdad. Teatrera, egoc\u00e9ntrica y cargada de tonter\u00edas, como decimos en <a href=\"http:\/\/granadablogs.com\/bluenoirclubdejazz\/2010\/11\/22\/esperanza-spalding\/\">este Blue &amp; Noir<\/a>, Esperanza Spalding cerr\u00f3n un Festival de Jazz de Granada heterodoxo, mestizo y radicalmente contempor\u00e1neo que, sin embargo, s\u00ed fue arrasado y abrasado por Chano Dom\u00ednguez la noche del s\u00e1bado. Su \u00abPiano ib\u00e9rico\u00bb va a ser algo muy grande.<\/p>\n<p style=\"text-align: justify;\">\n<figure id=\"attachment_7513\" aria-describedby=\"caption-attachment-7513\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/11\/09q.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7513\" title=\"Esperanza Spalding\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/11\/09q-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/11\/09q-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/11\/09q-1024x682.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-7513\" class=\"wp-caption-text\">Foto: Jos\u00e9 Nieto<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Un Festival con m\u00fasicas de muchos estilos, desde el clasicismo de Joe Lovano a la mistura de Chano. De la \u00a0radicalidad de Nils Peter Molvaer al virtuosismo de Kurt\u00a0\u00a0Rosenwinkel. Un Festival de los que sirven para abrir la mente a trav\u00e9s del o\u00eddo y que, en su programa paralelo, cont\u00f3 con <a href=\"http:\/\/www.myspace.com\/parkerland_jazz\">Parkerland<\/a> y la <a href=\"http:\/\/www.granadabigband.com\/\">Big Band<\/a>, dos grupos muy grandes de Granada que demuestran que se pueden hacer muchas cosas en esta tierra.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Y nuestro Blog, <a href=\"http:\/\/granadablogs.com\/bluenoirclubdejazz\/\">este Blue and Noir<\/a> al que queremos dar continuidad y del que seguiremos contando noticias, al que os animamos a seguir. Ya no hay Festival de Jazz, hasta verano. Pero se van a hacer m\u00e1s cosas antes, ye ver\u00e9is. Y est\u00e1n los clubes. Y los bares. Los discos. Los libros. Las pel\u00edculas. Y est\u00e1 ese Bar Alegr\u00eda que tantas alegr\u00edas nos da (y alg\u00fan susto que otro)<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/11\/09\u00f1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7515\" title=\"Alhambra Especial\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/11\/09\u00f1.jpg\" alt=\"\" width=\"325\" height=\"325\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/11\/09\u00f1.jpg 325w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/11\/09\u00f1-150x150.jpg 150w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/11\/09\u00f1-300x300.jpg 300w\" sizes=\"auto, (max-width: 325px) 100vw, 325px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y est\u00e1n esas Alhambras Especiales y esas 1925 que sacian la sed de algo fr\u00edo despu\u00e9s de una buena dosis de m\u00fasica caliente. \u00a1Ay, la <a href=\"http:\/\/www.cervezasalhambra.es\/\">Cerveza Alhambra<\/a>, \u00a1qu\u00e9 nos gusta! Y ese Cuate, Pepe, al que hemos secuestrado tres semanas y al que devolvemos enterito y de una pieza, aunque algo perjudicado y muy infectado. De Jazz.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Porque el Club de Jazz Blue and Noir tiene sus puertas abiertas todo el a\u00f1o.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00a1Seguidnos!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas <em><strong>jazzeado<\/strong><\/em> Lens.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No fue el mejor concierto del Festival, la verdad. Teatrera, egoc\u00e9ntrica y cargada de tonter\u00edas, como decimos en este Blue &amp; Noir, Esperanza Spalding cerr\u00f3n un Festival de Jazz de Granada heterodoxo, mestizo y radicalmente contempor\u00e1neo que, sin embargo, s\u00ed fue arrasado y abrasado por Chano Dom\u00ednguez la noche del s\u00e1bado. Su \u00abPiano ib\u00e9rico\u00bb va [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[17],"tags":[3919,3920,3922,2374,1436,1490,3872,3887,117,17,3921],"class_list":["post-7512","post","type-post","status-publish","format-standard","hentry","category-musica","tag-3919","tag-alhambra-especial","tag-bar-alegria","tag-cervezas-alhambra","tag-conciertos","tag-esperanza-spalding","tag-festival-de-jazz-de-granada","tag-granada-big-band","tag-jazz","tag-musica","tag-parkerland"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/7512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=7512"}],"version-history":[{"count":4,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/7512\/revisions"}],"predecessor-version":[{"id":7519,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/7512\/revisions\/7519"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=7512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=7512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=7512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}