{"id":7446,"date":"2010-11-18T12:05:09","date_gmt":"2010-11-18T10:05:09","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=7446"},"modified":"2010-11-22T02:12:41","modified_gmt":"2010-11-22T00:12:41","slug":"sacudiendo-letras-los-segundos-cuentos","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/sacudiendo-letras-los-segundos-cuentos\/","title":{"rendered":"SACUDIENDO LETRAS: LOS SEGUNDOS CUENTOS"},"content":{"rendered":"<p style=\"text-align: justify;\">La convocatoria para el Sacudiendo letras del pasado mes ten\u00eda como lema: <strong><em>&#8211; Mam\u00e1, \u00bfesta noche tampoco hay nada para cenar?<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Y las propuestas que tenemos son las siguientes:<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong><em>Laberinto ciego<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Estoy temblando, incosciente y ajena a todo, tan solo sintiendo un dolor que oprime mis sentidos y hace que no pueda percibir nada que no sea mi propio tormento.No se el tiempo que permanezco en ese estado de embotamiento profundo, pero debe ser mucho porque se ha hecho oscuro y apenas veo el reflejo de una farola que entra por mi ventana.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Intento incorporarme con gran esfuerzo pero no puedo. El dolor es tan agudo que siento como si mis entra\u00f1as quisieran partirse en dos; la rigidez es ya una vieja conocida. Respiro hondo y me preparo para un nuevo intento de sobreponerme a mi tortura.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Durante un instante fijo mi vista en el cuarto, compa\u00f1ero de mis tormentos. Es apenas un cub\u00edculo, carece de comodidades y de adornos, pero es mi cuarto, el sitio donde no tengo que ser otra persona. Dejo que mi mente vuele sola y me olvido del mundo y hasta de mi misma.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">He debido dormirme porque no recuerdo nada desde mi recreo visual hasta el vocer\u00edo en la calle. Se me olvid\u00f3 que eran fiestas y ya es tarde para ir a mezclarme con el gent\u00edo. Siento envidia, mucha envidia de las risas que llegan como punzadas a mi atormentada cabeza.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">De repente noto que no estoy sola, ha sido un leve sonido o quiz\u00e1s un anhelo, pero me ha parecido notar un cuerpo c\u00e1lido a mi lado. Efectivamente, a mi lado, est\u00e1 mi peque\u00f1o, mi vida.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Me mira con ojitos ansiosos, creo que intenta saber qu\u00e9 me pasa. Pobre hijito mio,\u00a1 tan fr\u00e1gil y tan fuerte al mismo tiempo!. Saco fuerzas de flaqueza y me incorporo mientras \u00e9l fija sus ojitos curiosos en mi. Ahora que caigo, esta ma\u00f1ana no le puse su almuerzo, de hecho, \u00bfcu\u00e1nto hace que yo misma no como nada?, \u00bfser\u00e1 ese el dolor que siento por todo mi cuerpo?, \u00bfhambre?.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Se me olvid\u00f3 de nuevo. El m\u00e9dico me dijo como ir trampeando el d\u00eda a d\u00eda y yo me cre\u00ed muy lista, que \u00e9l exageraba, pero lo cierto es que el alzheimer est\u00e1 ganando la batalla. Las palabras de mi hijo me sacan de mis cavilaciones:<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">-Mam\u00e1, \u00bfesta noche tampoco hay nada para cenar?<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong><em>La fotogenia del d\u00eda<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">-Bajo m\u00ednimos&#8230; \u2013Me dijo&#8230; \u2013As\u00ed me siento&#8230;<\/p>\n<p style=\"text-align: justify;\">Mientras beb\u00eda un gin and tonic&#8230;<\/p>\n<p style=\"text-align: justify;\">Mi cerebro se fug\u00f3 detr\u00e1s de su biograf\u00eda, o de lo que al menos yo conoc\u00eda como tal.<\/p>\n<p style=\"text-align: justify;\">De pronto entr\u00f3 en la terraza del bar un negro albino vendiendo collares, anillos, sombreros, bolsos y un mont\u00f3n de mercanc\u00edas colgadas de su cuerpo.<\/p>\n<p style=\"text-align: justify;\">-Hola&#8230; \u2013Nos salud\u00f3 y su tono amistoso lo remat\u00f3 con una sonrisa contagiosa.<\/p>\n<p style=\"text-align: justify;\">-\u00bfQu\u00e9 tal un collar para la novia?<\/p>\n<p style=\"text-align: justify;\">No tengo&#8230; \u2013Contest\u00f3 mi amigo<\/p>\n<p style=\"text-align: justify;\">-\u00bfPara la esposa?&#8230;<\/p>\n<p style=\"text-align: justify;\">-Dios me libre&#8230; \u2013Agreg\u00f3, malhumorado y bebiendo un trago.<\/p>\n<p style=\"text-align: justify;\">-\u00bfY una amante?&#8230; \u2013Salen muy caras&#8230;<\/p>\n<p style=\"text-align: justify;\">-Pues entonces t\u00fa compra collar para estar listo cuando abras una puerta&#8230;<\/p>\n<p style=\"text-align: justify;\">-No, gracias&#8230;<\/p>\n<p style=\"text-align: justify;\">-\u00bfDe d\u00f3nde eres?, le pregunt\u00e9. Sin poder evitar una mirada en sus cicatrices faciales.<\/p>\n<p style=\"text-align: justify;\">-De Senegal&#8230; Su respuesta conten\u00eda todo el colorido de su tierra y en sus ojos el dolor del continente entero&#8230;<\/p>\n<p style=\"text-align: justify;\">-\u00bfY t\u00fa, compras?&#8230; \u2013No tengo mujer&#8230;<\/p>\n<p style=\"text-align: justify;\">-Perfecto&#8230; \u2013Remat\u00f3 el joven africano que luego supe se llamaba Mamadou.<\/p>\n<p style=\"text-align: justify;\">Lo mir\u00e9 alejarse agradecido con el d\u00eda y con la oportunidad que supo fabricarse.<\/p>\n<p style=\"text-align: justify;\">-\u00a1Qu\u00e9 calor de mierda!&#8230; \u2013Dijo mi amigo.<\/p>\n<p style=\"text-align: justify;\">Y en ese momento lo percib\u00ed como un escarabajo sitiado en su coprofagia.<\/p>\n<p style=\"text-align: justify;\">-Sabes, tienes raz\u00f3n&#8230;<\/p>\n<p style=\"text-align: justify;\">-Pues claro, el calor es una mierda, y este mundo, un caos. \u00bfLe\u00edste las noticias?<\/p>\n<p style=\"text-align: justify;\">-No me refer\u00eda a eso. Tienes raz\u00f3n. Est\u00e1s bajo m\u00ednimos y eres un t\u00edo t\u00f3xico.<\/p>\n<p style=\"text-align: justify;\">Cog\u00ed el collar de la mesa, dej\u00e9 un billete de cinco euros y me fui repasando nuestra historia en com\u00fan. No pod\u00eda entender c\u00f3mo hab\u00eda sido mi amigo por tantos a\u00f1os. Su vida era una mierda y la m\u00eda desped\u00eda un olor muy parecido.<\/p>\n<p style=\"text-align: justify;\">Ten\u00eda que comenzar de nuevo.<\/p>\n<p style=\"text-align: justify;\">En la esquina la vi. Era bonita. Su piel bronceada contrastaba con una media sonrisa igual a una puerta entreabierta&#8230; Decid\u00ed tocar.<\/p>\n<p style=\"text-align: justify;\">Hac\u00eda mucho que yo no me atrev\u00eda a piropear a una mujer en la calle.<\/p>\n<p style=\"text-align: justify;\">Hac\u00eda mucho que no ten\u00eda ganas de buscar aventura o lo que viniera despu\u00e9s. La muerte de mi mujer me hab\u00eda tenido sumido en una prolongada depresi\u00f3n y me sent\u00eda incapaz de ligar a nadie.<\/p>\n<p style=\"text-align: justify;\">Fui hacia ella.<\/p>\n<p style=\"text-align: justify;\">Iba recordando las cicatrices de Mamadou, que nos acaba de contar, se las hab\u00edan hecho en su pueblo por ser albino, y por lo tanto, un endemoniado.<\/p>\n<p style=\"text-align: justify;\">En la bolsa del pantal\u00f3n sent\u00ed el collar reci\u00e9n comprado; una tonter\u00eda, pens\u00e9.<\/p>\n<p style=\"text-align: justify;\">Pero las tonter\u00edas son como las llaves, sirven para abrir las puertas&#8230;<\/p>\n<p style=\"text-align: justify;\">Mi gran sonrisa era contagiosa. Como la del negro albino.<\/p>\n<p style=\"text-align: justify;\">Ella me recibi\u00f3 con otra tan parecida, que me pareci\u00f3 estar frente al espejo.<\/p>\n<p style=\"text-align: justify;\">Mis cicatrices hab\u00edan desaparecido&#8230;<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong><em>Sin t\u00edtulo<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">&#8211; Mam\u00e1, \u00bfesta noche tampoco hay nada para cenar?<\/p>\n<p style=\"text-align: justify;\">&#8211; \u00a1Calla, co\u00f1o, o te meto un par de hostias!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong><em>Sin t\u00edtulo II<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">&#8211; Ooh-la-la, pero Sarita, qu\u00e9 horror!<\/p>\n<p style=\"text-align: justify;\">Malos presagios. Cuando mam\u00e1 se afrancesaba quer\u00eda decir que estaba siendo superada por algo inimaginable, desorbitado.<\/p>\n<p style=\"text-align: justify;\">&#8211; Con lo que t\u00fa eras, Sarita, mon ch\u00e8rie. Vamos a tener que decirle a Edgar que entrene m\u00e1s el photoshop, lo vamos a necesitar. As\u00ed te quedar\u00e1s sin llamadas, o sea,\u2026 no, no, no s\u00e9 c\u00f3mo puedes hacerme esto. Ooh-la-la\u2026.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Durante a\u00f1os le hab\u00eda encantado ir de compras con mam\u00e1; ella ten\u00eda tan buen gusto, era tan elegante. Lo hac\u00edan casi cada mes, y llenaban armarios de prendas fabulosas que apenas se pon\u00eda dos o tres veces. Desde que ten\u00eda conciencia de s\u00ed misma sus amigas la ten\u00edan idealizada, con ese cuerpito tan esbelto, tan larguirucho, esa melena tan cuidada, esas u\u00f1as,\u2026 y esa vida de celebrity, de sesiones de fotos, anuncios y pasarelas. Era estupendo ser tan admirada. Era llegar al cole en el coche con Ferm\u00edn y estar rodeada de toda la clase, rodeada de preguntas, miradas, cuchicheos, envidia. As\u00ed se sent\u00eda: era la ni\u00f1a del glamour.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Despert\u00f3 a la vida con 18 a\u00f1os.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">A los diecis\u00e9is ya dispon\u00eda de dos buenas tetas (regalo de mam\u00e1 por su cumple), y una muy leve curvita entre cintura y caderas fruto de su pubertad, as\u00ed que aquello ya rozaba el delirio cuando sent\u00eda que muchos ojos se volv\u00edan a su paso.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Pero all\u00ed estaba, delante del espejo de aquel probador infame, comprobando que ya no cab\u00eda en la 36. \u00bfQu\u00e9 pod\u00eda hacer una chica de casi 18 a\u00f1os con una talla 38? No, no era capaz de imaginarlo\u2026. No, no, aquello era el fin!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Durante meses no quiso hablar, su mirada se hizo opaca, triste, se visti\u00f3 con ropas floj\u00edsimas para evitar su cuerpo, y en casa, a solas, se introdujo en una extra\u00f1a confusi\u00f3n de comida, dietas, batidos adelgazantes y v\u00f3mitos, muchos v\u00f3mitos\u2026. A veces sent\u00eda que deber\u00eda dejarse llevar, asumir la \u201cfoca\u201d en la que se hab\u00eda convertido y tratar de olvidarse de s\u00ed misma. Entonces se atiborraba a galletas y chocolate,\u2026. mmmm, c\u00f3mo le gustaba el chocolate\u2026. pero luego volv\u00eda a verse en alg\u00fan espejo y sus dedos, como un resorte, se introduc\u00edan en lo m\u00e1s profundo de su garganta para vomitar y vomitar.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">La encontraron en la calle, desmayada, sin aliento. La radio de la ambulancia emit\u00eda: mujer, joven, altura: casi metro ochenta. peso: unos cuarenta kilos\u2026.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Lo \u00faltimo que vio fue lo primero que record\u00f3 al despertar a su nueva vida: invierno, noche, cartones en el portal de una sucursal bancaria y una pregunta lanzada al aire: \u201cmam\u00e1 \u00bfesta noche tampoco hay nada para cenar?\u201d<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">&#8211; Sara, me llamo Sara \u2013 dijo.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">.<\/p>\n<p><strong><em>Mam\u00e1, \u00bfesta noche tampoco hay nada para cenar?<\/em><\/strong><\/p>\n<p>No s\u00e9 por qu\u00e9 segu\u00eda usando despertador cuando cada ma\u00f1ana mis ojos se abr\u00edan inevitablemente justo antes de que el reloj anunciara la hora ajustada. Las seis de la ma\u00f1ana era el momento preacordado para iniciar la media marat\u00f3n. Ni un minuto m\u00e1s tarde ser\u00eda apropiado para poder llegar a buen puerto. La tarea era mec\u00e1nica, pero el orden pod\u00eda ser inverso, lo \u00fanico importante era llegar a tiempo al trabajo. Prepararlo todo, recoger lo necesario, no olvidar ni un documento y levantar a mi hijo entre negativas para que antes de que reaccionara ya se encontrase metido en el coche camino de casa de sus abuelos.<\/p>\n<p>Las siete horas de jornada se pasaban volando, aderezadas con el estr\u00e9s recomendable y antes de que me diese cuenta ya me encontraba en casa como realizando los \u00faltimos cinco kil\u00f3metros antes de llegar a la meta. La tarde dedicada a las poco gratificantes tareas del hogar y con un poco de suerte a otras aficiones mejor estimadas, con descansos de por medio para la docencia, la maternidad, a grandes cucharadas y la amistad, o el culto al yo y al cuerpo en cantidades limitadas.<\/p>\n<p>Todo iba rodando como siempre cuando justo me siento a la mesa y una peque\u00f1a persona con identidad muy definida a pesar de sus cinco a\u00f1os de edad, decide utilizar su palabra de forma espont\u00e1nea para cuestionar:<\/p>\n<p>&#8211; Mam\u00e1, \u00bfesta noche tampoco hay nada de cenar?<\/p>\n<p>&#8211; \u00bfC\u00f3mo que nada de cenar?<\/p>\n<p>A la peque\u00f1a persona con identidad marcada le parec\u00eda \u201cnada\u201d aquellos can\u00f3nigos acompa\u00f1ados de un poco de queso y una pieza de fruta. La costumbre pasaba por usar cuchara y tenedor todas las noches y el haber resuelto el escaso tiempo para la cocina en suprimir un cubierto hab\u00eda llevado a mi hijo a cuestionar si el t\u00e9rmino \u201ccena\u201d tambi\u00e9n englobaba a aquellos alimentos que yo hab\u00eda presentado ante la mesa.<\/p>\n<p>Fue en ese preciso instante cuando decid\u00ed romper rutinas y horarios y responderle con una historia.<\/p>\n<p>&#8211; Te voy a contar algo hijo. \u00bfTe gusta el nombre de Teodoro?<\/p>\n<p>&#8211; \u00bfTeodoro mam\u00e1?, \u00a1qu\u00e9 nombre m\u00e1s feo!<\/p>\n<p>&#8211; Pues ver\u00e1s, aunque su nombre es muy feo seg\u00fan t\u00fa, su historia creo que te va a gustar.<\/p>\n<p>Teodoro trabajaba hace muchos, pero que muchos a\u00f1os en un taller de artesan\u00eda. Con apenas diez a\u00f1os dedicada m\u00e1s de diez horas diarias a la talla de la madera. Su oficio consist\u00eda en lijar y lijar madera para que los artesanos la tuvieran preparada a la hora de tallar las figuras encargadas por los diferentes conventos. Teodoro s\u00f3lo hac\u00eda dos comidas al d\u00eda. No ten\u00eda ni chocolate, ni dulces ni alimentos variados. S\u00f3lo pan, leche y con suerte algunas legumbres. Y cada noche cuando terminaba en el taller so\u00f1aba con el momento de llegar a casa para tomar como siempre, un trozo de pan tostado con un buen taz\u00f3n de leche caliente que su madre le preparaba cada d\u00eda. Todos y cada uno de los d\u00edas de la semana.<\/p>\n<p>&#8211; \u00a1Mam\u00e1 pobre ni\u00f1o!<\/p>\n<p>&#8211; Si hijo, creo que nosotros dos aunque hoy tengamos can\u00f3nigos en la mesa tenemos m\u00e1s suerte de la que ten\u00eda Teodoro \u00bfno crees?<\/p>\n<p>&#8211; Si, creo que si. \u00bfPero ma\u00f1ana har\u00e1s algo de cenar mam\u00e1?<\/p>\n<p>.<\/p>\n<div id=\"_mcePaste\"><strong>SECRETO CASTIGO<\/strong><\/div>\n<div><strong><br \/>\n<\/strong><\/div>\n<div id=\"_mcePaste\">Apret\u00f3 el bot\u00f3n.<\/div>\n<div><\/div>\n<div id=\"_mcePaste\">Ya estaba hecho, ya aquello circulaba por las ondas, camino a un receptor de cuya reacci\u00f3n no sab\u00eda qu\u00e9 esperar.<\/div>\n<div id=\"_mcePaste\">Cecilia era una mujer bella, resuelta, libre, que hab\u00eda vivido la vida a su modo, sin prejuicios, disfrutando cada minuto como su propia conciencia le hab\u00eda ido indicando.<\/div>\n<div><\/div>\n<div id=\"_mcePaste\">Con toda naturalidad viv\u00eda y dejaba vivir. Persona de pocas palabras. Nadie se hab\u00eda inmiscuido en su mundo sin permiso, del mismo modo que ella tampoco lo hab\u00eda hecho en el de los dem\u00e1s. Y sobre todo hab\u00eda disfrutado de los hombres, una pasi\u00f3n irrefrenable que le llenaba tardes y noches.<\/div>\n<div><\/div>\n<div id=\"_mcePaste\">Le gustaban como a quien le gusta el pan, a veces tierno, a veces tostado, a veces \u201cde molde\u201d,\u2026 todo lo desmigaba. Y nada la fren\u00f3 a consumirlo sin reparos. Lo disfrutaba, lo adoraba. Muchos eran los que hab\u00edan recorrido su piel, muchos.<\/div>\n<div><\/div>\n<div id=\"_mcePaste\">S\u00f3lo cuando su hijo se fue haciendo grande percibi\u00f3 sin temor una nueva sensaci\u00f3n en su existencia: \u201cel secreto\u201d. Ambos siempre se hab\u00edan tratado casi con monos\u00edlabos, pero viv\u00eda en la certeza de haberle transmitido una enorme ternura sin palabras.<\/div>\n<div><\/div>\n<div id=\"_mcePaste\">Ella siempre le prepar\u00f3 la cena con esmero, puntual, a tiempo para que despu\u00e9s \u00e9l pudiera conciliar el sue\u00f1o antes de las clases. Pero nunca cen\u00f3 con \u00e9l.<\/div>\n<div><\/div>\n<div id=\"_mcePaste\">&#8211;\tMam\u00e1, \u00bfqu\u00e9 hay all\u00ed? \u2013 le preguntaba \u00e9l se\u00f1al\u00e1ndole su habitaci\u00f3n.<\/div>\n<div><\/div>\n<div id=\"_mcePaste\">&#8211;\tNada, cari\u00f1o, s\u00f3lo mi cena. Date prisa, se hace tarde.<\/div>\n<div><\/div>\n<div id=\"_mcePaste\">Y cuando \u00e9l ya dorm\u00eda, ella se dedicaba a sus pasiones, a sus ilusiones, tras esa puerta que siempre permaneci\u00f3 cerrada a los ojos de su peque\u00f1o.<\/div>\n<div><\/div>\n<div id=\"_mcePaste\">Luego, cuando el paso de los a\u00f1os quiso que su cuerpo se ajara, que su deseo amainara pl\u00e1cidamente, que sus ansias no fueran bien correspondidas, que su hijo creciera y aprendiera, entonces lleg\u00f3 la distancia. Esa terrible distancia que ella sent\u00eda cada a\u00f1o como un pu\u00f1al cuando \u00e9l, al felicitarle su cumplea\u00f1os, le enviaba un atento regalo con un burlesco mensaje: \u201cMam\u00e1, \u00bfesta noche tampoco hay nada para cenar?\u201d<\/div>\n<div><\/div>\n<div id=\"_mcePaste\">Nunca le perdon\u00f3 su secreto, nunca hablaron de ello. Se sab\u00edan cercanos, se ten\u00edan cuando se necesitaban, pero entre ellos hab\u00eda una inmensidad de vac\u00edo, de monos\u00edlabos. Nunca la entendi\u00f3. Ni ella trat\u00f3 de explicarse.<\/div>\n<div><\/div>\n<div id=\"_mcePaste\">Aquel d\u00eda Cecilia cumpl\u00eda los setenta. Y s\u00f3lo entonces tuvo el valor de afrontar su mirada frente a frente. S\u00f3lo entonces tuvo el coraje de aproximarse a lo que m\u00e1s quer\u00eda del mundo, de poner palabras a las cosas, de explicar que su vida no hab\u00eda da\u00f1ado a nadie m\u00e1s que a s\u00ed misma.<\/div>\n<div><\/div>\n<div id=\"_mcePaste\">Por eso le envi\u00f3 aquel mensaje; por eso: \u201cCari\u00f1o, hoy te invito a cenar\u201d.<\/div>\n<div><\/div>\n<div id=\"_mcePaste\">Y se sent\u00f3 a esperar.<\/div>\n<div><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La convocatoria para el Sacudiendo letras del pasado mes ten\u00eda como lema: &#8211; Mam\u00e1, \u00bfesta noche tampoco hay nada para cenar? Y las propuestas que tenemos son las siguientes: Laberinto ciego Estoy temblando, incosciente y ajena a todo, tan solo sintiendo un dolor que oprime mis sentidos y hace que no pueda percibir nada que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3598],"tags":[930,31,3598],"class_list":["post-7446","post","type-post","status-publish","format-standard","hentry","category-sacudiendo-letras","tag-cuentos","tag-relatos","tag-sacudiendo-letras"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/7446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=7446"}],"version-history":[{"count":5,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/7446\/revisions"}],"predecessor-version":[{"id":7448,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/7446\/revisions\/7448"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=7446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=7446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=7446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}