{"id":7404,"date":"2010-11-09T10:37:28","date_gmt":"2010-11-09T08:37:28","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=7404"},"modified":"2010-11-09T10:37:28","modified_gmt":"2010-11-09T08:37:28","slug":"dudas-teologicas-caseras","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/dudas-teologicas-caseras\/","title":{"rendered":"DUDAS TEOL\u00d3GICAS CASERAS"},"content":{"rendered":"<p style=\"text-align: justify;\">La visita del Papa y su fugaz paso por tierras del norte de Espa\u00f1a me han dejado unas cuantas dudas.<\/p>\n<p style=\"text-align: justify;\">\u00bfEst\u00e1 realizada esta mujer?<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/11\/011.bmp\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7405  aligncenter\" title=\"Iracunda mujer\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/11\/011.bmp\" alt=\"\" width=\"468\" height=\"490\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\u00bfNo contribuye su esposo a su realizaci\u00f3n, estando por ah\u00ed, de picos pardos?<\/p>\n<p style=\"text-align: justify;\">\u00bfPor qu\u00e9, entonces, esa beligerancia gestual?<\/p>\n<p style=\"text-align: justify;\">\u00cdtem m\u00e1s: \u00bfpuede realizarse un hombre dentro del hogar? Porque, de las palabras del Papa, podr\u00eda inferirse que no.<\/p>\n<p style=\"text-align: justify;\">Si un hombre s\u00f3lo se puede realizar en el \u00e1mbito laboral, \u00bfqu\u00e9 pasa con los cuatro millones de parados que tiene este pa\u00eds? \u00bfTienen que ir al INEM a realizarse? O lo mismo han de hacer cursillos de reciclaje&#8230;<\/p>\n<p style=\"text-align: justify;\">A la hora del caf\u00e9 y el desayuno, \u00bfpodemos realizarnos, los currantes, en la cafeter\u00eda, leyendo la prensa y charlando con los amigos de f\u00fatbol y teolog\u00eda?<\/p>\n<p style=\"text-align: justify;\">Los jubilados, \u00bfhan de ir al Hogar del Pensionista para realizarse?<\/p>\n<p style=\"text-align: justify;\">Los estudiantes, \u00bfse realizan s\u00f3lo dentro de las aulas de los colegios, institutos y Universidades o tambi\u00e9n en el patio de juego del recreo?<\/p>\n<p style=\"text-align: justify;\">Cristiano Ronaldo, \u00bfse puede realizar en el Bernab\u00e9u o, siendo hombre (y metrosexual), s\u00f3lo se realiza cuando el Real Madrid juega como visitante, fuera de casa?<\/p>\n<p style=\"text-align: justify;\">En fin, que no ve\u00e1is la de dudas que me ha sugerido la venida del Papa&#8230;<\/p>\n<p style=\"text-align: justify;\">Espero que me saqu\u00e9is de la oscuridad en que me encuentro sumido.<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Dudoso Lens.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La visita del Papa y su fugaz paso por tierras del norte de Espa\u00f1a me han dejado unas cuantas dudas. \u00bfEst\u00e1 realizada esta mujer? \u00bfNo contribuye su esposo a su realizaci\u00f3n, estando por ah\u00ed, de picos pardos? \u00bfPor qu\u00e9, entonces, esa beligerancia gestual? \u00cdtem m\u00e1s: \u00bfpuede realizarse un hombre dentro del hogar? Porque, de las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[32,7],"tags":[32,3854,3855,3856,1120,3857,3859,3858],"class_list":["post-7404","post","type-post","status-publish","format-standard","hentry","category-humor","category-imagenes","tag-humor","tag-mujer-enfadada","tag-mujer-hogar","tag-mujer-realizada-en-el-hogar","tag-papa","tag-ratzinger","tag-realizacion-personal","tag-teologia-papal"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/7404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=7404"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/7404\/revisions"}],"predecessor-version":[{"id":7406,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/7404\/revisions\/7406"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=7404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=7404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=7404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}