{"id":5548,"date":"2010-04-24T09:41:55","date_gmt":"2010-04-24T08:41:55","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=5548"},"modified":"2010-04-24T09:41:55","modified_gmt":"2010-04-24T08:41:55","slug":"nadie-sabe-nada-de-gatos-persas","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/nadie-sabe-nada-de-gatos-persas\/","title":{"rendered":"NADIE SABE NADA DE GATOS PERSAS"},"content":{"rendered":"<p style=\"text-align: justify;\">Todos sabemos lo que es la m\u00fasica underground, \u00bfverdad? Al menos, creemos saberlo. Consultemos esa fuente de sabidur\u00eda y conocimiento popular llamado Wikipedia: <em>\u00abUnderground (subterr\u00e1neo en espa\u00f1ol) es un t\u00e9rmino ingl\u00e9s con el que se designa a los movimientos contraculturales que se consideran alternativos, paralelos, contrarios o ajenos a la cultura oficial (el mainstream). La palabra se utiliz\u00f3 por primera vez con este sentido (\u00abque se desarrolla al margen de la actividad p\u00fablica oficial\u00bb) para referirse a algunos movimientos de resistencia contra reg\u00edmenes represivos\u00bb.<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/04\/_0392.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5549 aligncenter\" title=\"Nadie sabe nada de gatos persas\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/04\/_0392.jpg\" alt=\"\" width=\"318\" height=\"450\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/04\/_0392.jpg 318w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/04\/_0392-212x300.jpg 212w\" sizes=\"auto, (max-width: 318px) 100vw, 318px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y, sin embargo, para saber qu\u00e9 es, de verdad, la m\u00fasica underground, hay que sacar una entrada para ir al cine. Para ver una pel\u00edcula. \u00abNadie sabe nada de gatos persas\u00bb. \u00bfTe suena? Acaba de ser estrenada. Y el lunes, en la sala, est\u00e1bamos tres personas. El cine iran\u00ed, es lo que tiene.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a1EH!<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a1ESPERA!<\/strong><\/p>\n<p style=\"text-align: justify;\">Espera un momento antes de abandonar esta lectura, por favor. Vamos a darle una oportunidad a los Gatos Persas, aunque no pienses ver la pel\u00edcula. Porque, a buen seguro, has le\u00eddo \u00abcine iran\u00ed\u00bb y un escalofr\u00edo ha recorrido tu espina dorsal. Es lo malo de los t\u00f3picos y los lugares comunes. Escuchar \u00abcine iran\u00ed\u00bb y pensar en largos, interminables y morosos planos secuencia de quince minutos es todo uno. Como escuchar \u00abcine espa\u00f1ol\u00bb e imaginar culos, tetas y Guerra Civil.<\/p>\n<figure id=\"attachment_5550\" aria-describedby=\"caption-attachment-5550\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/04\/_46.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5550\" title=\"Nadie sabe nada de gatos persas\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/04\/_46.jpg\" alt=\"S\u00ed. Esto tambi\u00e9n es cine iran\u00ed\" width=\"500\" height=\"333\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/04\/_46.jpg 600w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/04\/_46-300x200.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption id=\"caption-attachment-5550\" class=\"wp-caption-text\">S\u00ed. Esto tambi\u00e9n es cine iran\u00ed<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Pero los t\u00f3picos est\u00e1n para acabar con ellos y \u00abNadie sabe nada de gatos persas\u00bb es una inmejorable oportunidad de hacerlo. Es una pel\u00edcula joven y fresca en la que se cuenta las aventuras y desventuras de dos muchachos, chico y chica, por montar una banda de rock, por dar un concierto, por conseguir pasaportes y visados para tocar en el extranjero. Y en su empe\u00f1o cuentan con el apoyo y la complicidad de un hiperactivo man\u00e1ger que, en su moto, nos acompa\u00f1a por un Teher\u00e1n que nada tiene que ver con el que vemos en los documentales.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/04\/_45.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5551 aligncenter\" title=\"Nadie sabe nada de gatos persas\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/04\/_45.jpg\" alt=\"\" width=\"500\" height=\"333\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/04\/_45.jpg 600w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/04\/_45-300x200.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Un Teher\u00e1n bullicioso, urbano, moderno. Un Teher\u00e1n desportillado, viejo, ruidoso. Y vamos conociendo a los personajes que lo habitan, desde el falsificador de pasaportes a una pl\u00e9yade de m\u00fasicos de todos los estilos, del rap o el heavy Metal a la m\u00fasica tradicional persa.<\/p>\n<p style=\"text-align: justify;\">M\u00fasica underground. \u00bfPor el g\u00e9nero? Tambi\u00e9n. Pero, sobre todo, porque ser m\u00fasico en Ir\u00e1n es ser rebelde, contestatario y levantisco. Y la polic\u00eda est\u00e1 muy encima de los m\u00fasicos. Y, por tanto, \u00e9stos han de tocar y ensayar de la forma m\u00e1s discreta posible: en s\u00f3tanos que amortig\u00fcen el ruido, en terrazas y altillos, en establos (lo que puede conllevar que las vacas se depriman al no entender el heavy metal, dejando de dar leche o que el bater\u00eda pille la hepatitis, sin ir m\u00e1s lejos) o en \u00e1ridos y abandonados descampados. M\u00fasicos vocacionales, militantes de sus instrumentos, que viven y se desviven por tocar, sin descanso.<\/p>\n<figure id=\"attachment_5552\" aria-describedby=\"caption-attachment-5552\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/04\/_43.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5552\" title=\"Teher\u00e1n\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/04\/_43.jpg\" alt=\"Teher\u00e1n, mon amour\" width=\"500\" height=\"375\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/04\/_43.jpg 600w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/04\/_43-300x225.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption id=\"caption-attachment-5552\" class=\"wp-caption-text\">Teher\u00e1n, mon amour<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">\u00abNadie sabe nada de gatos persas\u00bb es una pel\u00edcula necesaria, que pasar\u00e1 inadvertida entre las Furias de los Titanes y los Maravillosos Mundos de Alicia. Una buena pel\u00edcula que seguramente no ver\u00e1s pero de la que, al menos, est\u00e1 bien que sepas que existe, por si una noche la pasan de forma furtiva y subrepticia por alguna ignota cadena de televisi\u00f3n&#8230;<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens Espinosa de los Monteros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos sabemos lo que es la m\u00fasica underground, \u00bfverdad? Al menos, creemos saberlo. Consultemos esa fuente de sabidur\u00eda y conocimiento popular llamado Wikipedia: \u00abUnderground (subterr\u00e1neo en espa\u00f1ol) es un t\u00e9rmino ingl\u00e9s con el que se designa a los movimientos contraculturales que se consideran alternativos, paralelos, contrarios o ajenos a la cultura oficial (el mainstream). La [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[10,17,2805,2804,2803],"class_list":["post-5548","post","type-post","status-publish","format-standard","hentry","category-cine","tag-cine","tag-musica","tag-musica-underground","tag-nadie-sabe-nada-de-gatos-persas","tag-teheran"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/5548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=5548"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/5548\/revisions"}],"predecessor-version":[{"id":5553,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/5548\/revisions\/5553"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=5548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=5548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=5548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}