{"id":532,"date":"2008-11-13T20:01:00","date_gmt":"2008-11-13T19:01:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=532"},"modified":"2008-11-13T20:01:00","modified_gmt":"2008-11-13T19:01:00","slug":"paco-ignacio-taibo-i","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/paco-ignacio-taibo-i\/","title":{"rendered":"PACO IGNACIO TAIBO I"},"content":{"rendered":"<div align=\"justify\"><em>\u201cLa gran mayor\u00eda de mis viajes est\u00e1n estimulados por el im\u00e1n que significan los amigos, sin los cuales acaso yo hubiera sido un personaje sedentario, en vez de lo que en M\u00e9xico se llama Pata de Perro.<\/p>\n<p>Llegu\u00e9, por tanto, a Alburquerque, a la b\u00fasqueda del poeta \u00c1ngel Gonz\u00e1lez&#8230;\u201d <\/em><\/div>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5268219961752440354\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; WIDTH: 252px; CURSOR: hand; HEIGHT: 167px; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/3.bp.blogspot.com\/_r6VY1mvj3jk\/SRx6JJrgTiI\/AAAAAAAAFTQ\/kcExpWnPOgE\/s400\/_026.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">La primera vez que fui a Semana Negra, cenando en la estaci\u00f3n de Chamart\u00edn, coincid\u00ed junto un se\u00f1or cuya provecta edad era directamente proporcional a su vitalismo, entusiasmo y buen humor.<\/p>\n<p>Ten\u00eda un bigote m\u00e1s fino, pero se llamaba, tambi\u00e9n, Paco Ignacio. Y era Taibo. El I. El primero. El Number One. Yo, reconozco, me sent\u00e9 a aquella mesa queriendo haber estado junto a PIT II, mi \u00eddolo literario, mi escritor de cabecera, padre de Olga Lavanderos y del Jefe Fierro, autor de \u201cSombra de la sombra\u201d o \u201cLa bicicleta de Leonardo\u201d.<\/p>\n<p>Y, sin embargo, la suerte me cruz\u00f3 con otro Taibo, con el que pas\u00e9 una gloriosa velada, escuchando hablar de viajes, poes\u00eda, libros&#8230; y ciclismo. Porque el PIT I periodista hab\u00eda cubierto muchas el Tour de Francia: \u201c<em>Tourmalet. El Tour de Francia pasa por una cumbre que a m\u00ed, tan poco afecto a los sentimentalismos geogr\u00e1ficos, me produce un escalofr\u00edo entre helado y doloroso&#8230; el Tourmalet no es tanto una monta\u00f1a como una maldici\u00f3n.\u201d <\/em><\/p>\n<p align=\"justify\"> <\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5268219943557494562\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; WIDTH: 400px; CURSOR: hand; HEIGHT: 286px; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/2.bp.blogspot.com\/_r6VY1mvj3jk\/SRx6IF5fdyI\/AAAAAAAAFTA\/aDUaYCtt62w\/s400\/_001.JPG\" border=\"0\" \/><br \/>Es cierto. Primero vi a PIT II y justo despu\u00e9s abrac\u00e9 a Justo Vasco. Pero mi primera conversaci\u00f3n en Semana Negra, la primera de esas charlas que confieren al Festival Multicultural m\u00e1s importante de Europa su aut\u00e9ntica esencia y raz\u00f3n de ser, la sostuve con PIT I. O, mejor dicho, \u00e9l tuvo la deferencia y yo la inmensa suerte de poder escuchar la sabidur\u00eda y el inmenso caudal de experiencias vitales acumuladas por un hombre mayor, divertido, ingenioso y extraordinario contador de historias. <\/p>\n<p><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5268219960340969666\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; WIDTH: 320px; CURSOR: hand; HEIGHT: 308px; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/1.bp.blogspot.com\/_r6VY1mvj3jk\/SRx6JEa--MI\/AAAAAAAAFTc\/SsH-F4lCGJc\/s400\/_017.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Hoy, 13 de noviembre, d\u00eda de felicidades fraternas, se ha convertido, tambi\u00e9n, en d\u00eda de luto.<\/p>\n<p>Y por eso voy a mi biblioteca y rescato esas \u201cOcurrencias. Notas de viajes\u201d de Paco Ignacio Taibo I, que comienzan de una forma tan magistralmente sencilla:<\/p>\n<p>\u201cEsto que sigue son ocurrencias.<br \/>A mucha gente se le ocurren ocurrencias.<br \/>Algunos, por pudor, las ocultan.<br \/>Otros, por negligencia, las olvidan.<br \/>Algunos no tienen ocurrencias.<br \/>Para el Diccionario de la Lengua Castellana,<br \/>de la Real Academia Espa\u00f1ola, edici\u00f3n de<br \/>1780, ocurrencia es encuentro, suceso casual,<br \/>ocasi\u00f3n, coyuntura.<br \/>Todo esto bien pueden ser estas ocurrencias,<br \/>tambi\u00e9n.<br \/>Nacieron en la secci\u00f3n de Cultura de El Universal.<br \/>A pesar de ser solamente ocurrencias, me dio pena<br \/>dejarlas morir.\u201d <\/p>\n<p align=\"justify\"> <\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5268219950517944530\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; WIDTH: 250px; CURSOR: hand; HEIGHT: 166px; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/3.bp.blogspot.com\/_r6VY1mvj3jk\/SRx6If0_gNI\/AAAAAAAAFTI\/35rtwOuPROs\/s400\/_014.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Por ejemplo, \u00e9sta: <em>\u201cMadrid. No conozco otra ciudad tan dada a la vida sin sue\u00f1o, tan abierta a gozar hoy lo que los hombres de ayer no pod\u00edan ni so\u00f1ar con gozarlo. Yo dir\u00eda que el hombre y la mujer que viven en Madrid, viven tres o cuatro veces m\u00e1s que los que habitan en otros lugares del planeta.\u201d<br \/><\/em><br \/>Exactamente como t\u00fa, Maestro.<\/p>\n<p>Buen viaje, Pata de Perro.<\/p>\n<p>Jes\u00fas Lens.<\/p>\n<div align=\"justify\">\n<div>Etiquetas: <a href=\"http:\/\/bitacoras.com\/canales\/pit+i\" rel=\"tag\">PIT I<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/pit+ii\" rel=\"tag\">PIT II<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/pata+de+perro\" rel=\"tag\">pata de perro<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/paco+ignacio+taibo+i\" rel=\"tag\">paco ignacio taibo I<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/ocurrencias\" rel=\"tag\">ocurrencias<\/a><\/div>\n<p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLa gran mayor\u00eda de mis viajes est\u00e1n estimulados por el im\u00e1n que significan los amigos, sin los cuales acaso yo hubiera sido un personaje sedentario, en vez de lo que en M\u00e9xico se llama Pata de Perro. Llegu\u00e9, por tanto, a Alburquerque, a la b\u00fasqueda del poeta \u00c1ngel Gonz\u00e1lez&#8230;\u201d La primera vez que fui a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9,3,28],"tags":[],"class_list":["post-532","post","type-post","status-publish","format-standard","hentry","category-literarios","category-miscelanea","category-semana-negra"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=532"}],"version-history":[{"count":0,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/532\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}