{"id":53,"date":"2008-02-19T14:37:00","date_gmt":"2008-02-19T13:37:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=53"},"modified":"2008-02-19T14:37:00","modified_gmt":"2008-02-19T13:37:00","slug":"gadgetoblog","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/gadgetoblog\/","title":{"rendered":"GADGETOBLOG"},"content":{"rendered":"<div align=\"justify\">Lo mejor de esto de los Blogs o Bit\u00e1coras es, por supuesto, el contacto directo con un mont\u00f3n de amigos que comentan, discuten, debaten, animan y, en general, consiguen que las palabras de uno tengan sentido. Cada Comentario significa que una Entrada ha sido le\u00edda (o vista) y ha suscitado el suficiente inter\u00e9s como para que t\u00fa, a ese lado, dediques unos segundos de tu precioso tiempo a comentarla, sea para bien o sea para mal.<\/div>\n<p><\/p>\n<div><\/div>\n<p><\/p>\n<div><\/div>\n<p><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5168686756678915218\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp0.blogger.com\/_r6VY1mvj3jk\/R7rdOGcc1JI\/AAAAAAAAAeY\/RRYqBNJnSgY\/s400\/_8.jpg\" border=\"0\" \/><\/p>\n<p><\/p>\n<p align=\"justify\">\u00c9sa es la grandeza de la Blogosfera y su sentido \u00faltimo: relacionar a un mont\u00f3n de personas en torno a un sitio virtual que, de esta manera, adquiere un sentido real y cierto, tangible y palpable.<\/p>\n<p>Pero, adem\u00e1s, la Blogosfera ofrece un mont\u00f3n m\u00e1s de posibilidades, al venir repleta de herramientas que permiten enriquecer las Bit\u00e1coras. Y uno, que tiene tendencias ansioso-compulsivas, las va probando todas. De ah\u00ed el empe\u00f1o en que ech\u00e9is un ojo a la parte derecha de la pantalla. <\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5168686752383947890\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp3.blogger.com\/_r6VY1mvj3jk\/R7rdN2cc1HI\/AAAAAAAAAeI\/CSPeqRXkYHE\/s400\/_2.jpg\" border=\"0\" \/><br \/>Lo primero y m\u00e1s interesante es, posiblemente, el tema de las encuestas. Una de las \u00faltimas que hemos tenido en marcha nos demuestra que, la mayor\u00eda, prefer\u00eds los art\u00edculos de opini\u00f3n, seguido de la literatura, el cine y los viajes. El deporte y la m\u00fasica os interesan menos.<\/p>\n<p>Adem\u00e1s, para el 80%, Obama ser\u00e1 el candidato dem\u00f3crata en las elecciones americanas (27 votos) y ZP ser\u00e1 el pr\u00f3ximo presidente del gobierno espa\u00f1ol (el 63% de los 68 votos emitidos) Y acabamos de poner una nueva consulta popular, estilo CIS, sobre las preocupaciones de la pe\u00f1a. S\u00f3lo van 16 votos, pero el resultado es abrumador ya que al 56% les preocupa, sobre todo, el tema de la educaci\u00f3n.<\/p>\n<p>\u00bfQu\u00e9 os parece esto de las encuestas? \u00bfCu\u00e1les otras pod\u00edamos poner en marcha?<\/p>\n<p>Adem\u00e1s, de <a href=\"http:\/\/fondista1996.blogspot.com\/\"><span style=\"color:#ff0000;\"><strong>Paco Montoro<\/strong><\/span> <\/a>he copiado su idea de poner las diez \u00faltimas pel\u00edculas que ha visto. Las que he rese\u00f1ado, las vinculo. Las que no&#8230; pues eso. Que no. Est\u00e1 bien saber qu\u00e9 vamos viendo, qu\u00e9 nos interesa y de qu\u00e9 pecamos, por exceso o por defecto. <\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5168686760973882546\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp1.blogger.com\/_r6VY1mvj3jk\/R7rdOWcc1LI\/AAAAAAAAAeo\/6rRN0FWYhIM\/s400\/1.bmp\" border=\"0\" \/><br \/>Por supuesto, metemos im\u00e1genes que puedan resultar ilustrativas, divertidas o interesantes, para darle m\u00e1s colorido a esa margen derecha. Seguimos con las \u201cConvocatorias de la semana\u201d, en que rese\u00f1amos los eventos que captan nuestro inter\u00e9s y en los que tenemos previsto participar. En este caso, el domingo toca correr en Albolote, Carrera de la Amistad, creo que se llama, la prueba del Circuito de Fondo de la Diputaci\u00f3n granadina.<\/p>\n<p>En \u201cLibros que se acumulan\u201d vamos reflejando los libros que vamos adquiriendo, todos ellos vinculados con link hacia alguna informaci\u00f3n relevante sobre los mismos, sea una ficha t\u00e9cnica, una rese\u00f1a, una entrevista&#8230; pero todo ello ajeno a este Blog, para que sea m\u00e1s plural y abierto al mundo.<\/p>\n<p>Un apartado en que ten\u00eda puestas muchas esperanzas era \u201c\u00c1frica habla\u201d, en que quer\u00eda poner las ense\u00f1anzas de los maestros africanos que nos transmite un libro del que pronto hablaremos. Deber\u00eda cambiarlo una vez al d\u00eda, pero como tiene tan poco \u00e9xito&#8230; snif, snif.  <\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5168688027989234882\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp0.blogger.com\/_r6VY1mvj3jk\/R7reYGcc1MI\/AAAAAAAAAew\/Xnnzm757ZLk\/s400\/_8.jpg\" border=\"0\" \/><br \/>Tenemos los enlaces con otros compinches y amigos internautas y blogueros y hemos metido otro apartado de Convocatorias: citas imprescindibles del a\u00f1o, por toda Espa\u00f1a, en las que esperamos estar y participar activamente, muy recomendables para todos. <\/p>\n<p><\/p>\n<p><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5168686756678915202\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp0.blogger.com\/_r6VY1mvj3jk\/R7rdOGcc1II\/AAAAAAAAAeQ\/k44Id1A4Vws\/s400\/_4.jpg\" border=\"0\" \/><br \/>Tenemos las Etiquetas de esta Bit\u00e1cora, donde se archivan las diferentes entradas, por categor\u00edas. Un \u201cDi\u00e1logo\u201d que espero ir cambiando a medida que vayamos leyendo conversaciones interesantes o entrevistas jugosas. El ya tradicional \u201cQu\u00e9 estamos leyendo\u201d y una relaci\u00f3n, con v\u00ednculo, de las editoriales que nos parecen m\u00e1s jugosas e interesantes, para que podamos acceder a su cat\u00e1logo de novedades, fondo editorial, noticias, autores, etc\u00e9tera.<\/p>\n<p>Y, finalmente, siempre dejaremos la referencia a los libros en que un servidor tenga \u201cintereses\u201d directos. El de los microcr\u00e9ditos, del que somos coautores, y la \u201cConstantinopla\u201d de De Amicis, del que escribimos un largo y completo pr\u00f3logo y estudio preliminar. \u00bfAutobombo? \u00a1Claro que s\u00ed! Pero es que tenemos que querernos a nosotros mismos para que nos quieran los dem\u00e1s, \u00bfo no?<\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5168688027989234898\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp0.blogger.com\/_r6VY1mvj3jk\/R7reYGcc1NI\/AAAAAAAAAe4\/SX0VJvPNmqw\/s400\/_11.jpg\" border=\"0\" \/><br \/>Pero esta Bit\u00e1cora, adem\u00e1s de margen derecha, tiene un fondo, una base, un suelo. No s\u00e9 si se han fijado pero en el Fondo tenemos un contador de visitas (esperamos alcanzar las 10.000 visitas antes de que pase el primer mes de vida de esta Neo-Pateando el Mundo) y, si pinchan, un espectacular sistema de contabilidad que lo cuenta todo, pero todo, sobre los accesos al Blog.<\/p>\n<p>Adem\u00e1s, tenemos un servicio de informaci\u00f3n on line con noticias sobre cultura, literatura, m\u00fasica y cine, que va leyendo los titulares de las ediciones digitales de los m\u00e1s importantes peri\u00f3dicos y agencias de noticias de todo el mundo latino, para saber lo que se publica a ambos lados del oc\u00e9ano. Acabamos de poner un servicio de Suscripci\u00f3n al Blog, por si alguien quiere usarlo y, lo que todav\u00eda no hemos hecho, es meterle publicidad a la Bit\u00e1cora, a trav\u00e9s de los Google Ads (de Advertitsments).<br \/><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5168686760973882530\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp1.blogger.com\/_r6VY1mvj3jk\/R7rdOWcc1KI\/AAAAAAAAAeg\/A0KD3POkD3E\/s400\/000.gif\" border=\"0\" \/><br \/>As\u00ed las cosas, \u00bfqu\u00e9 os parece este dise\u00f1o? \u00bfQu\u00e9 os parece prescindible? \u00bfE imprescindible? \u00bfQu\u00e9 ech\u00e1is en falta que os gustar\u00eda que figurase en la parte est\u00e1tica del Blog? \u00bfNos vendemos al capitalismo y le metemos anuncios a esta vuestra bit\u00e1cora?<\/p>\n<p>Fdo.- Pat\u00f3n, que quiere saber.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo mejor de esto de los Blogs o Bit\u00e1coras es, por supuesto, el contacto directo con un mont\u00f3n de amigos que comentan, discuten, debaten, animan y, en general, consiguen que las palabras de uno tengan sentido. Cada Comentario significa que una Entrada ha sido le\u00edda (o vista) y ha suscitado el suficiente inter\u00e9s como para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-53","post","type-post","status-publish","format-standard","hentry","category-miscelanea"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=53"}],"version-history":[{"count":0,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/53\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=53"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=53"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}