{"id":4917,"date":"2010-02-04T23:55:33","date_gmt":"2010-02-04T22:55:33","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=4917"},"modified":"2010-02-04T22:08:33","modified_gmt":"2010-02-04T21:08:33","slug":"ingles-en-granada","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/ingles-en-granada\/","title":{"rendered":"INGLES EN GRANADA"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>No. La columna de hoy viernes de IDEAL no es (s\u00f3lo) sobre baloncesto&#8230; <\/em><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Desde el partido de presentaci\u00f3n del CeB\u00e9 Granada, mi hermano y yo le llamamos Bob, el Ingl\u00e9s, recordando al personaje que Richard Harris interpretara en la memorable \u00abSin perd\u00f3n\u00bb, un famoso pistolero que recalaba en Big Whisky para cumplir un encargo que terminar\u00eda por demostrarse harto complicado&#8230;<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<figure id=\"attachment_4918\" aria-describedby=\"caption-attachment-4918\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/02\/_027.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4918\" title=\"Bob el Ingl\u00e9s\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/02\/_027.jpg\" alt=\"Bob, el Ingl\u00e9s.\" width=\"500\" height=\"214\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/02\/_027.jpg 698w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/02\/_027-300x128.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption id=\"caption-attachment-4918\" class=\"wp-caption-text\">Bob, el Ingl\u00e9s.<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Rubio y letal, Ingles es un tirador excepcional y su mu\u00f1eca prodigiosa le vali\u00f3, la pasada semana, alzarse con el MVP de la jornada de la ACB de baloncesto. Pero si hacemos referencia al bueno de Joe en esta columna, m\u00e1s all\u00e1 de por su indudable calidad baloncest\u00edstica -entonces tendr\u00edamos que hablar de \u00abPata Negra\u00bb Aguilar, de las carreras de Gianella \u00abGacela de la Pampa\u00bb o de los solos de Hendrix dentro de la zona- es por su actitud en la cancha.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/02\/_05.bmp\"><img decoding=\"async\" class=\"size-full wp-image-4919 aligncenter\" title=\"Joe Ingles\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/02\/_05.bmp\" alt=\"Joe Ingles\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Nada m\u00e1s empezar el partido, el pasado domingo, Ingles le clav\u00f3 un triple a su defensor. En la cara. Lo que los norteamericanos, tan dados a los eufemismos sonoros, llaman \u00abin your face\u00bb. Unos instantes despu\u00e9s, le meti\u00f3 otro. Limpio. Y en ambas ocasiones, mientras volv\u00eda para defender, Ingles le miraba con todo descaro, ret\u00e1ndole, busc\u00e1ndole la boca.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Precisamente, esa agresiva actitud le ha costado a Ingles alguna cr\u00edtica y censura en otros partidos. Y es que el australiano no se achanta ni se deja avasallar por nadie, sean rivales, \u00e1rbitros o el p\u00fablico contrario, encar\u00e1ndose con cualquiera, aunque le saque una cabeza y pese treinta kilos m\u00e1s que \u00e9l.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/02\/_026.jpg\"><img decoding=\"async\" class=\"size-full wp-image-4920 aligncenter\" title=\"Joe Ingles\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/02\/_026.jpg\" alt=\"Si hay que sacar los codos, se sacan\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y a m\u00ed, personalmente, me encanta esa actitud. Acostumbrados como estamos los granadinos a que nos ninguneen en todos los foros y a que nuestros dirigentes sean mayormente unos pintamonas, siempre achant\u00e1ndose ante los poderes sevillanos y madrile\u00f1os, da gusto ver al <em>aussie<\/em>, vestido con los colores nazar\u00edes, sacando pecho y peleando por lo que cree justo y necesario.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Porque, adem\u00e1s de pele\u00f3n, Joe se parte el pecho en cada partido, dej\u00e1ndose la piel en todos y cada uno de los minutos que est\u00e1 en cancha, aunando calidad, voluntad y disposici\u00f3n. Lo que siempre se ha dicho que deben tener las personas grandes: aptitud y actitud, algo a lo que, por desgracia, estamos muy poco acostumbrados por estos lares.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<figure id=\"attachment_4921\" aria-describedby=\"caption-attachment-4921\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/02\/_025.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4921\" title=\"Joe Ingles\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/02\/_025.jpg\" alt=\"\u00bfDr. Ingles y Mr. Hyde?\" width=\"500\" height=\"698\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/02\/_025.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/02\/_025-214x300.jpg 214w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption id=\"caption-attachment-4921\" class=\"wp-caption-text\">\u00bfDr. Ingles y Mr. Hyde?<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">\u00a1Ojal\u00e1 hubiera m\u00e1s Ingleses en otros \u00e1mbitos de la vida granadina! Porque su actitud rocosa y peleona no significa que no sea un exquisito deportista, sin maldad alguna en sus acciones. Un tipo que va de cara y al que se le ve venir&#8230; aunque despu\u00e9s resulte letal en sus acciones. Es lo que caracteriza a la gente valiosa: no necesitan utilizar tretas falsarias ni arteras artima\u00f1as para ser los mejores. A base de entrenamiento, trabajo duro, compromiso, actitud e ilusi\u00f3n, son capaces de cargarse todo un equipo a las espaldas. Por eso, en los momentos en que las cosas no les salen bien, que siempre llegan, siguen contando con el cari\u00f1o y el benepl\u00e1cito de un p\u00fablico que admira su arrojo, descaro y valent\u00eda.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens Espinosa de los Monteros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No. La columna de hoy viernes de IDEAL no es (s\u00f3lo) sobre baloncesto&#8230; \u00a0 Desde el partido de presentaci\u00f3n del CeB\u00e9 Granada, mi hermano y yo le llamamos Bob, el Ingl\u00e9s, recordando al personaje que Richard Harris interpretara en la memorable \u00abSin perd\u00f3n\u00bb, un famoso pistolero que recalaba en Big Whisky para cumplir un encargo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[13,8,6],"tags":[2507,2506,2508,42,1473,2510,50,2505,6,2509,1002],"class_list":["post-4917","post","type-post","status-publish","format-standard","hentry","category-deporte-vida-empresa","category-deportes","category-opinion","tag-actitud","tag-actitud-y-aptitud","tag-aptitud","tag-baloncesto","tag-cb-granada","tag-cebe-granada","tag-deporte","tag-joe-ingles","tag-opinion","tag-pintamonas","tag-talento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/4917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=4917"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/4917\/revisions"}],"predecessor-version":[{"id":4922,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/4917\/revisions\/4922"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=4917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=4917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=4917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}