{"id":476,"date":"2008-10-14T11:35:00","date_gmt":"2008-10-14T10:35:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=476"},"modified":"2008-10-14T11:35:00","modified_gmt":"2008-10-14T10:35:00","slug":"el-secreto-de-los-flamencos","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-secreto-de-los-flamencos\/","title":{"rendered":"EL SECRETO DE LOS FLAMENCOS"},"content":{"rendered":"<div align=\"justify\">Cuando le he dado a \u201cArchivo. Guardar como&#8230;\u201d a esta rese\u00f1a, he dudado si incluirla en la carpeta de \u201cRese\u00f1as negras\u201d o en la m\u00e1s gen\u00e9rica de \u201cRese\u00f1as\u201d, a secas. Aunque \u201cEl secreto de los flamencos\u201d, de la que es autor Federico Andahazi, parte de la investigaci\u00f3n de un asesinato, su esencia tiene m\u00e1s que ver con el mundo del arte, la pintura, la luz y el color que con el de una trama criminal propiamente dicha. <\/div>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5256957024828441554\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/2.bp.blogspot.com\/_r6VY1mvj3jk\/SPR2j8Bkw9I\/AAAAAAAADqw\/10_X71BwAVg\/s400\/_7.jpg\" border=\"0\" \/><br \/>Me gustan, y mucho, las novelas y las pel\u00edculas que arrancan con el cad\u00e1ver de un personaje atractivo. Hay que ser muy valiente para empezar matando al protagonista, por mucho que luego recuperemos su vida a trav\u00e9s de narraciones o flash backs.<\/p>\n<p>Saber que el protagonista est\u00e1 muerto, desde el principio, hace que el autor tenga que redoblar esfuerzos por hacer que nos enamoremos de \u00e9l. Porque no es f\u00e1cil tenerle aprecio a un fiambre. Hay algo que, inconscientemente, nos repele y nos aleja de \u00e9l. Ponemos barreras y distancias. No queremos cogerle excesivo aprecio ya que, al final, sabemos que terminar\u00e1 desangrado y desmembrado, ex\u00e1nime, en la mesa de un m\u00e9dico forense. <\/p>\n<p><\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5256957033270673970\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/3.bp.blogspot.com\/_r6VY1mvj3jk\/SPR2kbeXAjI\/AAAAAAAADrQ\/txqiWOldcic\/s400\/_27.jpg\" border=\"0\" \/><br \/>Y, sin embargo, nos enamoramos del difunto Pietro de la Chiesa, el aventajado alumno de Francesco Monterga, que nos permitir\u00e1 disfrutar de un singular viaje de ida y vuelta entre Florencia y Brujas, dos de las grandes capitales del arte y la creatividad del Renacimiento que, sin embargo, son radicalmente distintas entre s\u00ed. <\/p>\n<p><\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5256957027445321106\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/2.bp.blogspot.com\/_r6VY1mvj3jk\/SPR2kFxfLZI\/AAAAAAAADq4\/fHv25tT_PTg\/s400\/_26.jpg\" border=\"0\" \/><br \/>Ustedes saben que los artistas, por geniales que puedan llegar a ser en su trabajo, tambi\u00e9n son personas. Y su naturaleza humana les hace ser envidiosos, vanidosos, competitivos, crueles y celosos. Sobre todo, de otros artistas que est\u00e1n a su altura o amenazan su reinado.<\/p>\n<p>Es llamativo que, ahora, en este siglo XXI, podemos ir a un museo y extasiarnos con la belleza de un cuadro. Un especialista nos podr\u00e1 explicar las cualidades del mismo y, por tanto, podremos disfrutar de una extraordinaria experiencia est\u00e9tica. Pero, en la mayor\u00eda de los casos, nunca sabremos lo que realmente bull\u00eda en la cabeza del artista, cuando daba sus pinceladas en el lienzo.<\/p>\n<p align=\"justify\"> <img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5256957028537852002\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/4.bp.blogspot.com\/_r6VY1mvj3jk\/SPR2kJ194GI\/AAAAAAAADrI\/eSs_H_vS3-Y\/s400\/_037.jpg\" border=\"0\" \/><\/p>\n<p>Y ah\u00ed radica la grandeza de \u201cEl secreto de los flamencos\u201d. Nos permite entrar en el estudio de los pintores y contemplar el proceso creativo desde dentro, asistiendo a las grandezas, miserias y ruindades que pueden concitarse en torno a la elaboraci\u00f3n de un cuadro, en la consecuci\u00f3n de un escorzo imposible, del color m\u00e1s luminoso y perdurable.<\/p>\n<p>Y, personalmente, me impact\u00f3 la descripci\u00f3n de Brujas, la ciudad de la muerte, cerrada a cal y canto, abandonada durante decenas y decenas de a\u00f1os, fantasmal, triste y luctuosa. <\/p>\n<p><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5256957025989477602\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/3.bp.blogspot.com\/_r6VY1mvj3jk\/SPR2kAWYxOI\/AAAAAAAADrA\/5Gteamd4Dnw\/s400\/_034.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">\u201cEl secreto de los flamencos\u201d es una interesant\u00edsima novela en que la pulsi\u00f3n creativa, el genio y las ansias de pasar a la posteridad se dan la mano de una investigaci\u00f3n criminal en un Europa del Renacimiento en que el lujo y el oropel de las clases nobles se dan la mano con la miseria m\u00e1s mis\u00e9rrima de los siervos y vasallos. Porque las cosas cambian&#8230; pero siempre m\u00e1s despacio de lo imaginarse pueda.<\/p>\n<p>Jes\u00fas Lens Espinosa de los Monteros. <\/p>\n<p align=\"justify\">Etiquetas: <a href=\"http:\/\/bitacoras.com\/canales\/el+secreto+de+los+flamencos\" rel=\"tag\">el secreto de los flamencos<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/brujas\" rel=\"tag\">brujas<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/florencia\" rel=\"tag\">florencia<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/federico+andahazi\" rel=\"tag\">Federico Andahazi<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/libros\" rel=\"tag\">libros<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/literatura\" rel=\"tag\">literatura<\/a><\/p>\n<p align=\"justify\">\n","protected":false},"excerpt":{"rendered":"<p>Cuando le he dado a \u201cArchivo. Guardar como&#8230;\u201d a esta rese\u00f1a, he dudado si incluirla en la carpeta de \u201cRese\u00f1as negras\u201d o en la m\u00e1s gen\u00e9rica de \u201cRese\u00f1as\u201d, a secas. Aunque \u201cEl secreto de los flamencos\u201d, de la que es autor Federico Andahazi, parte de la investigaci\u00f3n de un asesinato, su esencia tiene m\u00e1s que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-476","post","type-post","status-publish","format-standard","hentry","category-literarios"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=476"}],"version-history":[{"count":0,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/476\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}