{"id":469,"date":"2008-10-10T09:10:00","date_gmt":"2008-10-10T08:10:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=469"},"modified":"2008-10-10T09:10:00","modified_gmt":"2008-10-10T08:10:00","slug":"elogio-del-diez","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/elogio-del-diez\/","title":{"rendered":"ELOGIO DEL DIEZ"},"content":{"rendered":"<table id=\"HB_Mail_Container\" height=\"100%\" cellspacing=\"0\" cellpadding=\"0\" width=\"100%\" border=\"0\" unselectable=\"on\">\n<tbody>\n<tr height=\"100%\" width=\"100%\" unselectable=\"on\">\n<td id=\"HB_Focus_Element\" valign=\"top\" width=\"100%\" background=\"\" height=\"250\" unselectable=\"off\">\n<div align=\"justify\"><em><span style=\"font-family:times new roman;\">La columna de IDEAL, cambiando de tercio sobre Crisis y dem\u00e1s. Hoy, en clave casi esot\u00e9rica.<\/span><\/em> <\/div>\n<div align=\"justify\"> <\/div>\n<div align=\"justify\">Hoy es diez del diez. Un d\u00eda, pues, importante y significativo. Porque, siendo s\u00f3lo un n\u00famero, el diez no es un n\u00famero cualquiera, cargado como est\u00e1 de simbolismo y de resonancias a caballo entre lo puramente matem\u00e1tico, lo m\u00edstico y lo astrol\u00f3gico. <\/div>\n<div align=\"justify\"> <\/div>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5255245784518540674\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/3.bp.blogspot.com\/_r6VY1mvj3jk\/SO5iMpGYvYI\/AAAAAAAADn8\/Y_3VidNS1pg\/s400\/000.gif\" border=\"0\" \/> <\/p>\n<p align=\"justify\">El diez, por supuesto, est\u00e1 en la base del sistema decimal, utilizado hist\u00f3ricamente por multitud de pueblos como forma b\u00e1sica de contar, dado que tenemos cinco dedos en cada mano. Si los egipcios construyeron un complejo sistema tomando como base el diez, los griegos pitag\u00f3ricos lo elevaron a la categor\u00eda de paradigma filos\u00f3fico.<\/p>\n<p>Efectivamente, para los pitag\u00f3ricos el diez era la perfecci\u00f3n, relacion\u00e1ndolo directamente con Dios, el Ser Supremo. De hecho, su juramento m\u00e1s apreciado era \u201cpor tetractis\u201d, lo m\u00e1s sagrado. En la C\u00e1bala, el diez es el Sefirot, s\u00edmbolo de la Totalidad y a partir de esta herencia, los cristianos asumen sus diez mandamientos y distintos pueblos adoptan el diezmo como f\u00f3rmula impositiva o de financiaci\u00f3n, incluyendo a nuestra Iglesia, aunque se abus\u00f3 tanto del concepto que, ahora, cuando hablamos de diezmar una poblaci\u00f3n, nada bueno podemos esperar.<\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5255245781812502258\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/3.bp.blogspot.com\/_r6VY1mvj3jk\/SO5iMfBN3vI\/AAAAAAAADns\/xJwcLJzcglc\/s400\/_020.jpg\" border=\"0\" \/><br \/>A partir de todo ello, el hombre ha tendido a glorificar el diez. Desde la mejor puntuaci\u00f3n en un examen a la excelencia en cualquier actividad o faceta humana. As\u00ed lo entendi\u00f3 Blake Edwards, por ejemplo, en su famosa \u201c10. La mujer perfecta\u201d. <\/p>\n<p><\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5255245776379507202\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/1.bp.blogspot.com\/_r6VY1mvj3jk\/SO5iMKx48gI\/AAAAAAAADnc\/1vg2Yh34g5o\/s400\/_01.jpg\" border=\"0\" \/><br \/>Procuramos sentar doctrina a trav\u00e9s de Dec\u00e1logos que nos sirvan para condensar toda una filosof\u00eda o pensamiento y, aunque no lo queramos reconocer, siempre estamos atentos al Top Ten de las disciplinas que nos interesan. Tendemos a hacer listas con nuestras diez pel\u00edculas, discos o libros favoritos y, aunque sea inconscientemente, apreciamos a \u201cLos diez negritos\u201d de Agatha Christie o los \u201cDiez d\u00edas que conmovieron el mundo\u201d por lo absoluto de una cifra redonda.<\/p>\n<p>El n\u00famero diez, en un equipo de f\u00fatbol, ha de ser un jugador que marque diferencias, imprima car\u00e1cter y se eche el equipo a las espaldas. Como Cesc F\u00e1bregas, en la pasada Eurocopa ganada por Espa\u00f1a. Como el m\u00edtico Maradona, la Mano de Dios. Como el mejor Zidane de la selecci\u00f3n francesa o el inolvidable Zico del combinado carioca. <\/p>\n<p><\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5255245775747838274\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/3.bp.blogspot.com\/_r6VY1mvj3jk\/SO5iMIbScUI\/AAAAAAAADnk\/lUkAwSnfaPI\/s400\/_019.jpg\" border=\"0\" \/><br \/>Los cambios de d\u00e9cada siempre resultan especiales. Cuando cumplimos los veinte, los treinta o los cuarenta, tendemos a analizarnos y a hacer balance. Lo mismo ocurre cuando cambian las d\u00e9cadas del calendario, que todo son valoraciones, an\u00e1lisis y proyectos de futuro. Poetas de todos los tiempos han puesto su ingenio y sensibilidad en la composici\u00f3n de d\u00e9cimas, estrofa predilecta de algunos poetas de la Generaci\u00f3n del 27 y el decathlon es la disciplina atl\u00e9tica que consagra a los atletas m\u00e1s completos. <\/p>\n<p><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5255245781210872690\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/3.bp.blogspot.com\/_r6VY1mvj3jk\/SO5iMcxxu3I\/AAAAAAAADn0\/5WeX860Q5Go\/s400\/_023.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">El diez, por tanto, preside nuestra vida. El n\u00famero perfecto, el n\u00famero compendio de todos los n\u00fameros. \u00bfEl n\u00famero de la suerte? Desde luego, si hoy me cruzo con alg\u00fan lotero que lleve el diez, no dudar\u00e9 ni un segundo en comprarle un d\u00e9cimo. \u00a1Viva el 10!<\/p>\n<p>Jes\u00fas Lens Espinosa de los Monteros.<\/p>\n<p align=\"justify\">Etiquetas: <a href=\"http:\/\/bitacoras.com\/canales\/10\" rel=\"tag\">10<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/diez\" rel=\"tag\">diez<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/mujer+perfecta\" rel=\"tag\">mujer perfecta<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/maradona\" rel=\"tag\">maradona<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/zico\" rel=\"tag\">zico<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/sefirot\" rel=\"tag\">sefirot<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/tetractis\" rel=\"tag\">tetractis<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/pit\u00e1goras\" rel=\"tag\">pit\u00e1goras<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/perfecci\u00f3n\" rel=\"tag\">perfecci\u00f3n<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/dios\" rel=\"tag\">Dios<\/a><\/p>\n<\/td>\n<\/tr>\n<tr unselectable=\"on\" hb_tag=\"1\">\n<td style=\"FONT-SIZE: 1pt\" height=\"1\" unselectable=\"on\"><\/p>\n<div id=\"hotbar_promo\"><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>La columna de IDEAL, cambiando de tercio sobre Crisis y dem\u00e1s. Hoy, en clave casi esot\u00e9rica. Hoy es diez del diez. Un d\u00eda, pues, importante y significativo. Porque, siendo s\u00f3lo un n\u00famero, el diez no es un n\u00famero cualquiera, cargado como est\u00e1 de simbolismo y de resonancias a caballo entre lo puramente matem\u00e1tico, lo m\u00edstico [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-469","post","type-post","status-publish","format-standard","hentry","category-opinion"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=469"}],"version-history":[{"count":0,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/469\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}