{"id":4683,"date":"2010-01-13T20:28:49","date_gmt":"2010-01-13T19:28:49","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=4683"},"modified":"2010-01-13T20:28:49","modified_gmt":"2010-01-13T19:28:49","slug":"estrellas","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/estrellas\/","title":{"rendered":"ESTRELLAS"},"content":{"rendered":"<p style=\"text-align: justify;\">Querido Jorge Alberto, cuando vi esta primera foto, yo tampoco entend\u00eda nada.<\/p>\n<figure id=\"attachment_4684\" aria-describedby=\"caption-attachment-4684\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/01\/000001.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4684\" title=\"Sembrador de estrellas\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/01\/000001.jpg\" alt=\"\u00a1Malditos grafiteros!\" width=\"500\" height=\"281\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/01\/000001.jpg 790w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/01\/000001-300x168.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption id=\"caption-attachment-4684\" class=\"wp-caption-text\">\u00a1Malditos grafiteros!<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Despu\u00e9s, por fortuna, cuando cay\u00f3 la oscuridad, lo vi claro. \u00a1Qu\u00e9 gran lecci\u00f3n acerca de la necesidad de no juzgar las cosas a simple vista y de un primer vistazo!<\/p>\n<figure id=\"attachment_4685\" aria-describedby=\"caption-attachment-4685\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/01\/_0711.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4685\" title=\"Sembrador de estrellas\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/01\/_0711.jpg\" alt=\"\u00a1No era un cutre-graffiti!\" width=\"500\" height=\"302\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/01\/_0711.jpg 790w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2010\/01\/_0711-300x181.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption id=\"caption-attachment-4685\" class=\"wp-caption-text\">\u00a1No era un cutre-graffiti!<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">\u00abEl sembrador de estrellas\u00bb es una escultura situada en Kaunas, Lituania, herencia de la Uni\u00f3n Sovi\u00e9tica. Un buen consejo: aunque no se aprecien a simple vista, nunca dejemos de sembrar estrellas&#8230;<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00bfC\u00f3mo va ese 2010? Por aqu\u00ed, intentando ser concientes de que, seg\u00fan lo que sembremos, as\u00ed recogeremos, sean semillas, vientos o, como en este caso, hermosas estrellas.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Querido Jorge Alberto, cuando vi esta primera foto, yo tampoco entend\u00eda nada. Despu\u00e9s, por fortuna, cuando cay\u00f3 la oscuridad, lo vi claro. \u00a1Qu\u00e9 gran lecci\u00f3n acerca de la necesidad de no juzgar las cosas a simple vista y de un primer vistazo! \u00abEl sembrador de estrellas\u00bb es una escultura situada en Kaunas, Lituania, herencia de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[22,7],"tags":[2359,2363,7,2360,2361,2362],"class_list":["post-4683","post","type-post","status-publish","format-standard","hentry","category-aforismos","category-imagenes","tag-el-sembrador-de-estrellas","tag-escultura","tag-imagenes","tag-kaunas","tag-lituania","tag-union-sovietica"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/4683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=4683"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/4683\/revisions"}],"predecessor-version":[{"id":4686,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/4683\/revisions\/4686"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=4683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=4683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=4683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}