{"id":462,"date":"2008-10-07T08:57:00","date_gmt":"2008-10-07T07:57:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=462"},"modified":"2008-10-07T08:57:00","modified_gmt":"2008-10-07T07:57:00","slug":"a-la-salida","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/a-la-salida\/","title":{"rendered":"A LA SALIDA"},"content":{"rendered":"<div align=\"justify\">Una vez, inspir\u00e1ndome en el gran profesor, excelente literato, ameno conversador y gran humanista, Andr\u00e9s Sope\u00f1a, inici\u00e9 la presentaci\u00f3n de un libro de Antonio Lozano, otro enorme y comprometido escritor, diciendo que le odiaba. Que le odiaba cruel y sa\u00f1udamente. Y no ment\u00eda. Odiaba a Antonio porque, con su \u201cDonde mueren los r\u00edos\u201d, hab\u00eda escrito la novela que me habr\u00eda gustado escribir a m\u00ed. <\/div>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5254318474710382210\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/4.bp.blogspot.com\/_r6VY1mvj3jk\/SOsW0G3idoI\/AAAAAAAADlE\/RJEFoFP4U24\/s400\/_7.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Hoy, se une a esta n\u00f3mina de escritores cordialmente odiados Dominique Manotti, cuyo \u201cEl cuerpo negro\u201d, tanto nos gustara hace unos meses. Efectivamente, odio a Dominique porque ha escrito otra novela que me hubiera encantado escribir a m\u00ed. Si la de Antonio versaba sobre la tragedia de la emigraci\u00f3n africana y las mafias que la controlan, \u201c\u00a1A la salida!\u201d, publicada por la editorial <a href=\"http:\/\/www.tropismos.com\/\"><span style=\"color:#ff0000;\"><strong>Tropismos<\/strong><\/span><\/a>, es un brutal an\u00e1lisis de la salvaje sociedad capitalista neoliberal que impuso la socialdemocracia surgida de los partidos m\u00e1s radicalmente situados en la extrema izquierda.<\/p>\n<p>Estamos a finales de los a\u00f1os ochenta y mientras las noticias que llegan de la Europa del Este hacen presagiar que algo est\u00e1 cambiando al otro lado del Tel\u00f3n de Acero, los socialistas franceses han ocupado el poder y se aprestan a revolucionar la econom\u00eda del pa\u00eds. En su propio beneficio, por supuesto. <\/p>\n<p align=\"justify\"><\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5254318479664663618\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/1.bp.blogspot.com\/_r6VY1mvj3jk\/SOsW0ZUuzEI\/AAAAAAAADlU\/Z_d39nzRBtw\/s400\/_034.jpg\" border=\"0\" \/><br \/>A lo largo de 250 vibrantes y esclarecedoras p\u00e1ginas, Manotti hablar\u00e1 de tr\u00e1fico de drogas y prostituci\u00f3n, pero de forma tangencial. Porque la esencia de \u201c\u00a1A la salida!\u201d es el fino, completo y riguroso an\u00e1lisis del modelo de corrupci\u00f3n impuesto por los magnates de los grandes conglomerados empresariales y los pol\u00edticos que les ampararon. Con la complicidad y la connivencia, por supuesto, de bur\u00f3cratas, matones, funcionarios de medio pelo, putas, traficantes y arribistas de todo pelaje.<\/p>\n<p>A trav\u00e9s de una prosa cortante como el acero, \u00e1cida, escueta y directa, Manotti nos presenta al memorable comisario Daquin y a su grupo de inspectores. Unos polis de carne y hueso, ni \u00e1ngeles ni demonios, cuyo jefe es un vocacional jugador de rugby, homosexual, dotado de un corrosivo sentido del humor hacia el que sus colaboradores mantienen una lealtad a prueba de bomba. <\/p>\n<p><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5254318479567621986\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/1.bp.blogspot.com\/_r6VY1mvj3jk\/SOsW0Y9mD2I\/AAAAAAAADlM\/ndBpc-T3ltg\/s400\/_27.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Modelo de jefe que toma decisiones, organiza equipos y sabe escuchar, Daquin monta una investigaci\u00f3n mod\u00e9lica que le conducir\u00e1 de mozos de cuadra de hip\u00f3dromos y jockeis drogadictos a adinerados poseedores de caballos y fincas que terminar\u00e1n por llevarle a la c\u00fapula de algunas de las empresas m\u00e1s importantes del pa\u00eds.<\/p>\n<p>Y, como meollo de todo ello, la especulaci\u00f3n urban\u00edstica que, en Par\u00eds, hace y deshace fortunas a una velocidad vertiginosa. Informaci\u00f3n privilegiada, maletines que cambian de manos, OPAS burs\u00e1tiles, regalos institucionales, cenas en restaurantes de post\u00edn&#8230; todo ello tiene cabida en una narraci\u00f3n que, con el contrapunto de la Ca\u00edda del Muro de Berl\u00edn, nos cuenta el origen de la sociedad del siglo XXI en que vivimos, con su especulaci\u00f3n, redes sociales y tr\u00e1fico de influencias.<\/p>\n<p align=\"justify\"><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5254318480609225026\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/2.bp.blogspot.com\/_r6VY1mvj3jk\/SOsW0c17qUI\/AAAAAAAADlc\/jhsDSCoCMMU\/s400\/_037.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Una novela cuya publicaci\u00f3n tenemos que agradecer a la editorial Tropismos, que tiene en Dominique Manotti a uno de sus puntales literarios m\u00e1s s\u00f3lidos y contundentes. Una novela para disfrutar aprendiendo c\u00f3mo se genera la corrupci\u00f3n y c\u00f3mo se lucha contra ella: con paciencia, con calma, con integridad, con arrojo y decisi\u00f3n, sin titubeos. Y, cuando llega el momento de enfrentarse a los realmente poderosos, con un buen par de pelotas.<\/p>\n<p>Una novela imprescindible.<\/p>\n<p><strong>La frase:<\/strong> <em>\u201cJefe, perm\u00edtame decirle que no est\u00e1 usted en la onda. Actualmente, ya no es delito hacerse rico ilegalmente. Es una demostraci\u00f3n de inteligencia y buen gusto. S\u00f3lo los mediocres siguen siendo pobres en los ochenta.\u201d<br \/><\/em><br \/>Jes\u00fas Lens Espinosa de los Monteros. <\/p>\n<p align=\"justify\">Etiquetas: <a href=\"http:\/\/bitacoras.com\/canales\/a+la+salida\" rel=\"tag\">A la salida<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/tropismos\" rel=\"tag\">tropismos<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/manotti\" rel=\"tag\">manotti<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/negra+y+criminal\" rel=\"tag\">negra y criminal<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/rese\u00f1as\" rel=\"tag\">rese\u00f1as<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/libros\" rel=\"tag\">libros<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/literatura\" rel=\"tag\">literatura<\/a><\/p>\n<p align=\"justify\">\n","protected":false},"excerpt":{"rendered":"<p>Una vez, inspir\u00e1ndome en el gran profesor, excelente literato, ameno conversador y gran humanista, Andr\u00e9s Sope\u00f1a, inici\u00e9 la presentaci\u00f3n de un libro de Antonio Lozano, otro enorme y comprometido escritor, diciendo que le odiaba. Que le odiaba cruel y sa\u00f1udamente. Y no ment\u00eda. Odiaba a Antonio porque, con su \u201cDonde mueren los r\u00edos\u201d, hab\u00eda escrito [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-462","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=462"}],"version-history":[{"count":0,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/462\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}