{"id":4468,"date":"2009-12-21T09:00:01","date_gmt":"2009-12-21T08:00:01","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=4468"},"modified":"2009-12-20T19:00:49","modified_gmt":"2009-12-20T18:00:49","slug":"felicidades-es-el-tiempo-de-los-peques","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/felicidades-es-el-tiempo-de-los-peques\/","title":{"rendered":"FELICIDADES. ES EL TIEMPO DE LOS PEQUES"},"content":{"rendered":"<p style=\"text-align: right;\"><strong><em>\u00abLos cuentos no est\u00e1n hechos para dormir a los ni\u00f1os, <\/em><\/strong><\/p>\n<p style=\"text-align: right;\"><strong><em>sino para despertar a los adultos&#8230;\u00bb<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Con esta ilustrativa frase se presenta la web de la <a href=\"http:\/\/www.fresolinaeditorial.com\/\">editorial granadina Fresolina<\/a>, especializada en literatura infantil y juvenil.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/12\/___0.bmp\"><img decoding=\"async\" class=\"size-full wp-image-4469 aligncenter\" title=\"Fresolina editorial\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/12\/___0.bmp\" alt=\"\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Ahora que llegan las vacaciones de Navidad hay que tener especial dedicaci\u00f3n a los peque\u00f1uelos, a los que les quedan un mont\u00f3n de horas libres y, con el fr\u00edo que hace, poca calle y actividades al aire libre pueden desarrollar.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Por eso, hoy lunes d\u00eda 21 de diciembre (qu\u00e9 importante ser\u00e1 este d\u00eda dentro de tres a\u00f1os) la gente de Fresolina presenta una nueva revista, \u00abCosquillas\u00bb, que reunir\u00e1 toda la informaci\u00f3n sobre actividades, convocatorias, fiestas y cualquier cosa que tenga que ver con los m\u00e1s peque\u00f1os de la casa. Una revista&#8230; gratuita. Que conste.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Imprescindible.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Y, si quer\u00e9is aprovechar para regalar un libro infantil, una recomendaci\u00f3n: \u00abEl bosque del tiempo\u00bb, de Bianca Estela S\u00e1nchez, publicado por la editorial granadina Cuadernos del Vig\u00eda, protagonizada por un ratoncito llamado Valent\u00edn que, de tanta prisa que ten\u00eda, no pod\u00eda disfrutar de la vida, llegando a angustiarse cada vez que llegaba su cumplea\u00f1os, cuando todos sabemos que no deber\u00eda haber un d\u00eda m\u00e1s alegre y feliz en la vida de un ni\u00f1o que el d\u00eda de su cumplea\u00f1os, \u00bfverdad?<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/12\/0000.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4470 aligncenter\" title=\"El bosque sin tiempo\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/12\/0000.png\" alt=\"\" width=\"194\" height=\"194\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/12\/0000.png 194w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/12\/0000-150x150.png 150w\" sizes=\"auto, (max-width: 194px) 100vw, 194px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Menos mal que sus amigos le ayudar\u00e1n a saber disfrutar y aprovechar el tiempo, que no hay otro regalo mejor \u00bfverdad?<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">El libro, una delicia, est\u00e1 primorosamente ilustrado por Pablo del Pino y prologado por uno de los grandes de las letras espa\u00f1olas: Benjam\u00edn Prado, en un texto que tiene un t\u00edtulo aparentemente contradictorio: <strong><em>\u00abSi todo est\u00e1 al rev\u00e9s, est\u00e1 en su sitio\u00bb<\/em><\/strong>. Y, ojo, como los mejores libros para la gente menuda, \u00abEl bosque del tiempo\u00bb tambi\u00e9n es de lo m\u00e1s ilustrativo y recomendable para los trastos mayores de la casa, que conste. Y no dejen de visitar <a href=\"http:\/\/www.biancaestelasanchez.com\/index.html\">la web personal de la autora<\/a>, una interesant\u00edsima escritora a la que seguir la pista. Muy de cerca.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/12\/00.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4471 aligncenter\" title=\"El bosque sin tiempo\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/12\/00.png\" alt=\"\" width=\"241\" height=\"212\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Navidad. Tiempo de y para los m\u00e1s peque\u00f1os. Tiempo de magia. \u00bfTiempo de leer?\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">As\u00ed que&#8230; \u00a1Muchas Felicidades!<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Que ha costado llegar hasta aqu\u00ed, sanos y salvos, de una pieza. \u00bfVerdad?<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens, celebrativo. \u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLos cuentos no est\u00e1n hechos para dormir a los ni\u00f1os, sino para despertar a los adultos&#8230;\u00bb \u00a0 \u00a0 Con esta ilustrativa frase se presenta la web de la editorial granadina Fresolina, especializada en literatura infantil y juvenil. \u00a0 Ahora que llegan las vacaciones de Navidad hay que tener especial dedicaci\u00f3n a los peque\u00f1uelos, a los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[2252,2249,2251,2248,2254,49,2253,2250],"class_list":["post-4468","post","type-post","status-publish","format-standard","hentry","category-literarios","tag-bianca-estela-sanchez","tag-cosquillas","tag-el-bosque-del-tiempo","tag-fresolina-editorial","tag-gente-menuda","tag-libros","tag-literatura-infantil","tag-revista-cosquillas"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/4468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=4468"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/4468\/revisions"}],"predecessor-version":[{"id":4472,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/4468\/revisions\/4472"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=4468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=4468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=4468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}