{"id":4363,"date":"2009-12-05T13:18:06","date_gmt":"2009-12-05T12:18:06","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=4363"},"modified":"2009-12-05T13:18:06","modified_gmt":"2009-12-05T12:18:06","slug":"%c2%bfque-es-negra-y-criminal","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/%c2%bfque-es-negra-y-criminal\/","title":{"rendered":"\u00bfQU\u00c9 ES NEGRA Y CRIMINAL?"},"content":{"rendered":"<p style=\"text-align: justify;\">Hace unas semanas aparec\u00eda yo en esta pantalla, posando con la camiseta de NyC&#8230; en la puerta de la librer\u00eda Negra y Criminal. Porque suelo llevar esa camiseta, cuando de hablar de libros se trata. Pero esa vez era especial. Muy especial. Porque me retrataba como autor, tal y como contamos en ESTA entrada.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/12\/_010.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4364 aligncenter\" title=\"Jes\u00fas Lens, negro y criminal\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/12\/_010.jpg\" alt=\"\" width=\"390\" height=\"356\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/12\/_010.jpg 390w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/12\/_010-300x273.jpg 300w\" sizes=\"auto, (max-width: 390px) 100vw, 390px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Uf.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Lo s\u00e9. Quiz\u00e1 era demasiado pronto. Posiblemente. Pero tambi\u00e9n es verdad que gestos, detalles como \u00e9se, hacen que me reafirme a\u00fan m\u00e1s en mis inquietudes y veleidades paraliterarias. Porque NyC, como <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=2998\">Semana Negra <\/a>o el <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=2984\">Festival de Ag\u00fcimes<\/a>, como el <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=4356\">Hocus Pocus <\/a>o el <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=4231\">Festival de Jazz<\/a>, son eventos, lugares, citas y acontecimientos que excitan la curiosidad, que fomentan la creatividad y que animan a dar el salto al otro lado para convertirte, adem\u00e1s de en rendido y entusiasta espectador, en actor, part\u00edcipe y creador.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Pero \u00bfqu\u00e9 es Negra y Criminal? Una vez lo explicamos, largamente, en palabras. Hoy, gracias a ese genio multimedia que es Ricardo Bosque, lo vemos en im\u00e1genes.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"425\" height=\"344\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/eLTGUSQX07Q&amp;hl=es_ES&amp;fs=1&amp;\" \/><\/object><\/p>\n<p style=\"text-align: justify;\">\u00bfMola o no mola Negra y Criminal?<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Gracias, Montse y Paco, por estar ah\u00ed.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Gracias, Ricardo, por retratarlos tan brillantemente.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens, hiperactivo y m\u00e1s que agradecido. \u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace unas semanas aparec\u00eda yo en esta pantalla, posando con la camiseta de NyC&#8230; en la puerta de la librer\u00eda Negra y Criminal. Porque suelo llevar esa camiseta, cuando de hablar de libros se trata. Pero esa vez era especial. Muy especial. Porque me retrataba como autor, tal y como contamos en ESTA entrada. \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[1253,49,21,144,240],"class_list":["post-4363","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","tag-hasta-donde-el-cine-nos-lleve","tag-libros","tag-negra-y-criminal","tag-paco-camarasa","tag-ricardo-bosque"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/4363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=4363"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/4363\/revisions"}],"predecessor-version":[{"id":4365,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/4363\/revisions\/4365"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=4363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=4363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=4363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}