{"id":4328,"date":"2009-11-29T13:35:15","date_gmt":"2009-11-29T12:35:15","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=4328"},"modified":"2009-11-29T13:35:15","modified_gmt":"2009-11-29T12:35:15","slug":"trago-amargo","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/trago-amargo\/","title":{"rendered":"TRAGO AMARGO"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">Horizontal. Transversal, que dicen los planes de estudios m\u00e1s vanguardistas y avanzados. As\u00ed me gusta pensar que soy, en base a la m\u00e1xima de que <em style=\"mso-bidi-font-style: normal;\">\u201cnada de lo humano me es ajeno\u201d<\/em>. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\">\u00a0<\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/11\/_0103.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4329 aligncenter\" title=\"Trago amargo\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/11\/_0103.jpg\" alt=\"\" width=\"264\" height=\"400\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/11\/_0103.jpg 264w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/11\/_0103-198x300.jpg 198w\" sizes=\"auto, (max-width: 264px) 100vw, 264px\" \/><\/a><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">Por eso me embarqu\u00e9 con mi amigo Fran en escribir un libro de cine sobre viajes. Porque me gustan las mezclas, los mestizajes y los follones. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">Y por eso (y porque es un libro cojonudo, claro) me ha encantado \u201cTrago amargo\u201d, de F. G. Haghenbeck, publicado por esa envidiable editorial Roca. Un libro que se abre con una cita del siempre genial Groucho Marx: <em style=\"mso-bidi-font-style: normal;\">\u201cTodo el mundo deber\u00eda creer en algo. Yo creo que voy a seguir bebiendo\u201d<\/em>.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">Un libro que cuenta, en clave negra y criminal, una historia de chantajes, robos y asesinatos, pero radicada en un escenario muy particular: el rodaje de una pel\u00edcula m\u00edtica de John Huston, como fue \u201cLa noche de la iguana\u201d, protagonizada por Richard Burton, Deborah Kerr, Sue Lyon y Ava Gardner&#8230; nada menos. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\">\u00a0<\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/11\/_0269.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4330 aligncenter\" title=\"La noche de la iguana\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/11\/_0269.jpg\" alt=\"\" width=\"325\" height=\"475\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/11\/_0269.jpg 325w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/11\/_0269-205x300.jpg 205w\" sizes=\"auto, (max-width: 325px) 100vw, 325px\" \/><\/a><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">Los rodajes de Huston son famosos por ser ca\u00f3ticos, complejos y por ejecutarse en lugares estramb\u00f3ticos, como atestigua el caso de \u201cLa reina de \u00c1frica\u201d que, y perdonen la autorreferencia, Fran y yo contamos con pelos y se\u00f1ales en nuestro querido \u201cHasta donde el cine nos lleve\u201d. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">En este caso, el rodaje de la peli se llev\u00f3 a cabo en una inaccesible playa de Puerto Vallarta, M\u00e9xico. Y fue tempestuoso, complicado y escandaloso. Por eso, los productores contrataron a Sunny Pascal, para que controlara que las cosas no se desmandaran excesivamente. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small;\"><span style=\"font-family: Times New Roman;\">Lo que pasa es que el alcohol corr\u00eda a raudales en el set de filmaci\u00f3n. Y que los intereses de los productores de la pel\u00edcula no estaban del todo claros. \u00bfQuer\u00edan un \u00e9xito de taquilla o, en realidad, buscaban otra cosa con esa filmaci\u00f3n, en un para\u00edso virginal de las costas mexicanas? Y, si no quer\u00edan problemas, \u00bfpor qu\u00e9 regal\u00f3 John Huston una pistola de oro con cinco balas de plata a cada uno de los protagonistas?<span style=\"mso-spacerun: yes;\">\u00a0 <\/span><\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small;\"><span style=\"font-family: Times New Roman;\"><\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: center;\"><span style=\"font-size: small;\"><span style=\"font-family: Times New Roman;\"><span style=\"mso-spacerun: yes;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/11\/_0249.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4331 aligncenter\" title=\"Trago amargo\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/11\/_0249.jpg\" alt=\"\" width=\"470\" height=\"336\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/11\/_0249.jpg 470w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/11\/_0249-300x214.jpg 300w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\" \/><\/a><\/span><\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">Con este cocktail, que mezcla cine cl\u00e1sico con literatura negra, con unas gotas de humor y unos toques de sarcasmo y acidez, Haghenbeck hace felices a los amantes del cine y a los amantes de la novela polic\u00edaca. Y, tambi\u00e9n, a los amantes de los bares. Porque cada cap\u00edtulo lleva el nombre de un combinado et\u00edlico, la receta para hacerlo y su historia, su origen y alguna particularidad que lo caracteriza. Como el <strong style=\"mso-bidi-font-weight: normal;\">Bloody Mary<\/strong>, la Mar\u00eda sangrienta, cuya maternidad se disputan la Reina Mar\u00eda I de Inglaterra y una corista del Club Bucket of Blood llamada Mary, obviamente. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">\u201cTrago amargo\u201d. Un libro para paladear despacio. Para divertirse y, a la vez, aprender de cine y de bares, de bebidas y de mujeres. De la vida, o sea, como dec\u00edamos en <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=4315\">ESTE<\/a> art\u00edculo. \u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: small; font-family: Times New Roman;\">Jes\u00fas Lens Espinosa de los Monteros. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Horizontal. Transversal, que dicen los planes de estudios m\u00e1s vanguardistas y avanzados. As\u00ed me gusta pensar que soy, en base a la m\u00e1xima de que \u201cnada de lo humano me es ajeno\u201d. \u00a0 \u00a0 Por eso me embarqu\u00e9 con mi amigo Fran en escribir un libro de cine sobre viajes. Porque me gustan las mezclas, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[2157,2156,49,21,581,2155],"class_list":["post-4328","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","tag-f-g-haghenbeck","tag-la-noche-de-la-iguana","tag-libros","tag-negra-y-criminal","tag-roca-editorial","tag-trago-amargo"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/4328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=4328"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/4328\/revisions"}],"predecessor-version":[{"id":4332,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/4328\/revisions\/4332"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=4328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=4328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=4328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}