{"id":416,"date":"2008-09-11T10:15:00","date_gmt":"2008-09-11T09:15:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=416"},"modified":"2008-09-11T10:15:00","modified_gmt":"2008-09-11T09:15:00","slug":"el-tren-de-las-310-a-yuma","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-tren-de-las-310-a-yuma\/","title":{"rendered":"EL TREN DE LAS 3.10 A YUMA"},"content":{"rendered":"<div align=\"justify\">Deber\u00eda comenzar esta rese\u00f1a advirtiendo al lector que, para m\u00ed, un tipo montando a caballo y disparando un Colt mientras su frente suda bajo un sombrero de ala ancha, quemado por el inclemente sol del desierto; es la mejor imagen que se puede ver en una sala de cine. Esto es, que el cine del Oeste, los westerns, me flipan. <\/div>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5244690864289014802\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/2.bp.blogspot.com\/_r6VY1mvj3jk\/SMjijbKu5BI\/AAAAAAAADK8\/2kMxyFbD9pM\/s400\/_042.jpg\" border=\"0\" \/><br \/>Y, como por desgracia el g\u00e9nero est\u00e1 en horas bajas y apenas nadie filma ya pelis del Oeste, poder ir a un cine de estreno y, en pantalla grande, tener la posibilidad de ver un filme protagonizado por pistoleros, indios, vaqueros y dem\u00e1s paisanaje; es un lujo. Un privilegio.<\/p>\n<p>As\u00ed que, por supuesto, entr\u00e9 a \u201cEl tren de las 3.10 a Yuma\u201d con la ilusi\u00f3n de un cr\u00edo chico al que llevan a ver la \u00faltima pel\u00edcula de Pixar. Receptivo, abierto y optimista, firmemente dispuesto a disfrutar de las haza\u00f1as de Christian Bale y Russell Crowe, pistola en mano. <\/p>\n<p><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5244690856838670514\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/1.bp.blogspot.com\/_r6VY1mvj3jk\/SMjii_abqLI\/AAAAAAAADKs\/dZPJ4W3Otvc\/s400\/_034.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Y me gust\u00f3. Bastante. Mucho. Excepto el episodio final, que me pareci\u00f3 excesivamente forzado y tontorr\u00f3n, toda la pel\u00edcula tiene un desarrollo muy coherente, bebiendo de esa hist\u00f3rica tradici\u00f3n, literaria y cinematogr\u00e1fica, que analiza la figura del h\u00e9roe, el arquetipo del mito y su influencia en la realidad.<\/p>\n<p>La pel\u00edcula arranca con un ni\u00f1o que se despierta, por la noche, asustado. Enciende la l\u00e1mpara y coge un librito que reposa encima de su mesa. Una novela del Oeste sobre un pistolero m\u00edtico. Y, sobre la marcha, el caos. Unos villanos entran a galope tendido en el rancho y queman el establo, sin que el padre del chaval -un ajustado Christian Bale- haga nada por evitarlo. <\/p>\n<p align=\"justify\"><\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5244690861237142770\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/2.bp.blogspot.com\/_r6VY1mvj3jk\/SMjijPzHBPI\/AAAAAAAADK0\/0pxAIczIOw4\/s400\/_041.jpg\" border=\"0\" \/><br \/>Al d\u00eda siguiente, el chaval tendr\u00e1 ocasi\u00f3n de contemplar otra actuaci\u00f3n, mucho m\u00e1s excitante, protagonizada por un tipo carism\u00e1tico, un pistolero r\u00e1pido como el demonio, letal, que parece rodeado por un aura en lugar de por la tristeza que apesadumbra a su padre, un labriego con un inequ\u00edvoco sombrero de campesino que jam\u00e1s podr\u00eda hacer frente a alguien como el personaje interpretado por Crowe.<\/p>\n<p><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5244690852447680674\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/3.bp.blogspot.com\/_r6VY1mvj3jk\/SMjiivDieKI\/AAAAAAAADKk\/ZFPt6qabQus\/s400\/_033.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">A partir de ah\u00ed se entreteje una muy bien contada historia de amor\/odio y atracci\u00f3n\/repulsi\u00f3n entre dos modelos paternos tan diferentes como complementarios que, como dec\u00edamos, solo flojea al final.<\/p>\n<p>Entre medias, por supuesto, asaltos a diligencias, duelos, tugurios, chicas f\u00e1ciles, whiskey, charlas nocturnas en torno a un fuego, venganzas, maldades y asesinatos. El western, o sea.<\/p>\n<p>Despu\u00e9s est\u00e1n los secundarios, con Peter Fonda a la cabeza. Muy bien trazados. La acci\u00f3n, muy bien resuelta. La fotograf\u00eda, excelentemente conseguida. Un ritmo tranquilo en el devenir de la historia. Pausado. Introspectivo. <\/p>\n<p align=\"justify\"><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5244690864712230882\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/4.bp.blogspot.com\/_r6VY1mvj3jk\/SMjijcvop-I\/AAAAAAAADLE\/mLnlFPOYT4c\/s400\/_043.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Un estupendo western del siglo XXI que bucea en las ra\u00edces y la esencia del g\u00e9nero, cuestionando algunos de sus postulados hist\u00f3ricos. Por supuesto, no vamos a pensar que, a ra\u00edz de \u201cEl tren de las 3.10 a Yuma\u201d asistiremos a un revival del g\u00e9nero, pero s\u00ed que nos animaremos a ver la segunda parte de \u201cDeadwood\u201d y, posiblemente, aprovechemos la coyuntura para ver pel\u00edculas como \u201cCentauros del desierto\u201d o \u201cEl hombre que mat\u00f3 a Liverty Valance\u201d, tem\u00e1ticamente m\u00e1s emparejadas con este Yuma que la propia \u201cSolo ante el peligro\u201d con la que tanto se la compara.<\/p>\n<p>Valoraci\u00f3n: 7<\/p>\n<p>Lo mejor: la modernidad del planteamiento sobre la figura del h\u00e9roe, a trav\u00e9s de una narraci\u00f3n de corte cl\u00e1sico.<\/p>\n<p>Lo peor: el tiroteo final. Por lo que significa, mayormente.<\/p>\n<p>Jes\u00fas Lens Espinosa de los Monteros.<\/p>\n<div align=\"justify\"><\/div>\n<p align=\"justify\"><\/p>\n<div align=\"justify\">Etiquetas: <a href=\"http:\/\/bitacoras.com\/canales\/el+tren+de+las+3.10+a+yuma\" rel=\"tag\">el tren de las 3.10 a yuma<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/cine\" rel=\"tag\">cine<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/pel\u00edculas\" rel=\"tag\">pel\u00edculas<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/western\" rel=\"tag\">western<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/crowe\" rel=\"tag\">crowe<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/bale\" rel=\"tag\">bale<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Deber\u00eda comenzar esta rese\u00f1a advirtiendo al lector que, para m\u00ed, un tipo montando a caballo y disparando un Colt mientras su frente suda bajo un sombrero de ala ancha, quemado por el inclemente sol del desierto; es la mejor imagen que se puede ver en una sala de cine. Esto es, que el cine del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-416","post","type-post","status-publish","format-standard","hentry","category-cine"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=416"}],"version-history":[{"count":0,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/416\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}