{"id":39,"date":"2008-02-13T10:03:00","date_gmt":"2008-02-13T09:03:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=39"},"modified":"2008-02-13T10:03:00","modified_gmt":"2008-02-13T09:03:00","slug":"trenzas","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/trenzas\/","title":{"rendered":"TRENZAS"},"content":{"rendered":"<div align=\"justify\"><\/div>\n<div align=\"right\"><em><span style=\"font-family:times new roman;\"><strong>Dedicado a Silvia, Pilar, Chusi, Pamela y Mariluz, extraordinarios compa\u00f1eros de viaje.<\/strong><\/span><\/em><\/div>\n<div align=\"right\"><em><span style=\"font-family:times new roman;\"><strong>Y a Ibrahim, Yaya, Mohammed y Mulay, los mejores gu\u00edas.<\/strong><\/span><\/em><\/div>\n<div align=\"right\"><em><span style=\"font-family:Times New Roman;\"><strong>Y al enigm\u00e1tico Prosper, claro.<\/strong><\/span><\/em><\/div>\n<div align=\"right\"><\/div>\n<div align=\"right\"><\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Sacai quer\u00eda hacerse las trenzas, pero le daba un poquito de miedo el pensar c\u00f3mo quedar\u00edan. Se lo coment\u00f3 a Ibrahim, nuestro hombre en Bamako, un gu\u00eda para el que la palabra \u201cNo\u201d no figura en los diccionarios; y despu\u00e9s de comer en un restaurante senegal\u00e9s de cuarta categor\u00eda, en un arrabal de la capital del Mal\u00ed, nos plantamos en la peluquer\u00eda, donde dos jovencitas daban buena cuenta de unos bocatas estilo shawarma.<\/p>\n<p>Tras una buena discusi\u00f3n sobre el precio final del peinado m\u00e1s el pelo postizo a a\u00f1adir, Sacai se qued\u00f3 sentada en el sill\u00f3n de la peluquer\u00eda mientras Silvia, Mari Luz y un servidor se iban con Ibrahim y Mohammed al mercado, a buscar m\u00e1scaras y dem\u00e1s elementos artesanales decorativos que, cuando llegas a casa, te cuestan un disgusto a la hora de elegir d\u00f3nde ponerlos. <\/p><\/div>\n<div align=\"justify\"><\/div>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5166391891228151586\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp1.blogger.com\/_r6VY1mvj3jk\/R7K2DWcczyI\/AAAAAAAAATc\/w9IOcTUnB5g\/s400\/Mali5.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Pero \u00e9sa es otra historia. El caso es que dejamos a Sacai, cerca de las cuatro, en la pelu. Y quedamos en recogerla a eso de las ocho, que trenzar toda una cabeza no es moco de pavo.<\/p>\n<p>Regresamos al local ya entrada la noche, pero nos hab\u00edamos adelantado un poco a la hora convenida. Mi Sacai ten\u00eda buena parte de la cabeza bien anudada. Tres mujeres se afanaban sobre su pelo, cogiendo peque\u00f1os mechones, a\u00f1adiendo el postizo y retorciendo el resultado en largu\u00edsimos tirabuzones que terminaban descansando, elegantemente, sobre los hombros.<\/p>\n<p>Y nos quedamos. La peluquer\u00eda, que medir\u00eda diez o quince metros cuadrados, albergaba a cuatro chicas y un beb\u00e9. En cuanto Ibrahim se hizo cargo del infante y empez\u00f3 a hacerle moner\u00edas, la cuarta chica se abalanz\u00f3 sobre Sacai y se uni\u00f3 a la fiesta de la trenza. El caso era que las chicas, cuando ve\u00edan a alguna amiga o conocida por la calle, le gritaban. Entraba y anudaba dos, tres o las trencitas que pudiera, antes de de seguir con sus quehaceres. <\/p>\n<p align=\"justify\"><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5166391895523118898\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp2.blogger.com\/_r6VY1mvj3jk\/R7K2DmcczzI\/AAAAAAAAATk\/W_sVUDevX8M\/s400\/Mali4.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Sacai nos dijo c\u00f3mo se hab\u00edan pasado la tarde cascando, bailando, riendo, viendo telenovelas y escuchando m\u00fasica. Pero trabajando. Sin parar. Entonces apareci\u00f3 una voluminosa se\u00f1ora. Una se\u00f1ora que, ella sola, abarcaba un cuarto de la peluquer\u00eda con su gran humanidad. Arrebat\u00f3 al mocoso de los brazos de Ibrahim y se puso a mecerlo con convencimiento. Era (deb\u00eda ser) la abuela de la criatura.<\/p>\n<p>Entonces, la chica m\u00e1s alta dej\u00f3 el trabajo y se fue al fondo de la sala. Se puso un manto negro sobre su traje marr\u00f3n y un pa\u00f1uelo en la cabeza, estir\u00f3 una manta y se puso a rezar, levant\u00e1ndose y tendi\u00e9ndose discretamente, pero a la vista de todos y mientras la tele atronaba con los videoclips. <\/p>\n<p align=\"justify\"><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5166391899818086210\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp3.blogger.com\/_r6VY1mvj3jk\/R7K2D2ccz0I\/AAAAAAAAATs\/K5jmmy4bWBY\/s400\/Mali6.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Lleg\u00f3 la hora de la merienda del churumbel, que todav\u00eda tomaba el pecho. Sin problema. Un rinc\u00f3n del sof\u00e1 de eskai era suficiente. Entraron dos mujeres, saludaron, se rieron y se fueron. Segu\u00edan las voces y el cachondeo. Y el trabajo. Y volvi\u00f3 a ser hora de rezar para la chica alta. Y, para calentar agua, una de las peluqueras se sali\u00f3 a la calle y encendi\u00f3 un hornillo.<\/p>\n<p>Al haber entrado hombres en la pelu, las mujeres ya se hab\u00edan quedado m\u00e1s serias, m\u00e1s compuestas, m\u00e1s en su papel. Como dice mi amigo peluquero del Zaid\u00edn, es dif\u00edcil que triunfen las peluquer\u00edas unisex. A ellas les gusta la intimidad de la compa\u00f1\u00eda femenina, pudiendo hablar de sus cosas, libremente, sin que la presencia de clientes hombres haga que se corten, sin tener necesidad de mantener una compostura formal y gestual que el ejercicio de la peluquer\u00eda no contribuye a fomentar, precisamente. <\/p>\n<p align=\"justify\"><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5166391899818086226\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp3.blogger.com\/_r6VY1mvj3jk\/R7K2D2ccz1I\/AAAAAAAAAT0\/utlyGJJ2n9U\/s400\/Mali7.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">As\u00ed, no es de extra\u00f1ar que el Bagdad de los peores momentos de la Guerra de Irak, las peluquer\u00edas fueran objetivo primordial de los integristas. Las peluquer\u00edas son reductos de libertad para unas personas que gustan de hablar, re\u00edr, comentar y discutir en unos locales que fomentan la relaci\u00f3n social y comunitaria de las personas. <\/p>\n<p align=\"justify\"><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5166391904113053538\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp0.blogger.com\/_r6VY1mvj3jk\/R7K2EGccz2I\/AAAAAAAAAT8\/yAsrgYbKItY\/s400\/Mali8.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Para Sacai, trenzas aparte, la velada en la peluquer\u00eda de Bamako fue una muestra del natural amable, cari\u00f1oso y gentil de unos malienses que son, sin duda, los mejores embajadores y relaciones p\u00fablicas de un pa\u00eds que, como tantas veces hemos dicho, tiene una magia especial.<\/p>\n<p>Jes\u00fas Lens Espinosa de los Monteros. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dedicado a Silvia, Pilar, Chusi, Pamela y Mariluz, extraordinarios compa\u00f1eros de viaje. Y a Ibrahim, Yaya, Mohammed y Mulay, los mejores gu\u00edas. Y al enigm\u00e1tico Prosper, claro. Sacai quer\u00eda hacerse las trenzas, pero le daba un poquito de miedo el pensar c\u00f3mo quedar\u00edan. Se lo coment\u00f3 a Ibrahim, nuestro hombre en Bamako, un gu\u00eda para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-39","post","type-post","status-publish","format-standard","hentry","category-viajes-africa"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=39"}],"version-history":[{"count":0,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/39\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=39"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=39"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}