{"id":3656,"date":"2009-09-24T20:30:03","date_gmt":"2009-09-24T19:30:03","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=3656"},"modified":"2009-09-24T21:04:59","modified_gmt":"2009-09-24T20:04:59","slug":"la-habana-y-alejandria","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-habana-y-alejandria\/","title":{"rendered":"LA HABANA Y ALEJANDR\u00cdA"},"content":{"rendered":"<p style=\"text-align: justify;\">La editorial ALMED presenta dos aut\u00e9nticas perlas bibliogr\u00e1ficas.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Por un lado, el cl\u00e1sico de E.M. Foster sobre <a href=\"http:\/\/www.almed.net\/home_pr.php?pag=libro_det.php?id_libro=046\">Alejandr\u00eda<\/a>.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/09\/155.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3657 aligncenter\" title=\"Alejandr\u00eda\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/09\/155.jpg\" alt=\"\" width=\"160\" height=\"252\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y, por otro, un libro muy especial: <a href=\"http:\/\/www.almed.net\/home_pr.php?pag=libro_det.php?id_libro=046\">\u00abLa Habana. Puerta de las Am\u00e9ricas\u00bb<\/a>, del cubano Amir Valle.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00bfEs posible que les suene el nombre de Amir?<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/09\/_0615.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3663 aligncenter\" title=\"La Habana. Puerta de Las Am\u00e9ricas\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/09\/_0615.jpg\" alt=\"\" width=\"161\" height=\"252\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">S\u00ed.\u00a0Cuando habl\u00e1bamos de \u00e9l y de <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=324\">La Otra Cuba<\/a>. O cuando <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=311\">estuvimos en Carmona<\/a>, celebrando con \u00e9l la consecuci\u00f3n del premio de Novela Negra Ciudad de Carmona,\u00a0de Almuzara, con <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=307\">\u00abLargas noches con Flavia\u00bb<\/a>. Vinculado, por lo general, a ese g\u00e9nero negro y criminal que tanto nos subyuga. Sin embargo, hace un par de a\u00f1os, en Semana Negra, le pregunt\u00e9 a Amir si le gustar\u00eda escribir la historia de su ciudad. De esa La Habana que es parte de su existencia.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/09\/164.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3658 aligncenter\" title=\"Amir Valle\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/09\/164.jpg\" alt=\"\" width=\"380\" height=\"249\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/09\/164.jpg 380w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/09\/164-300x196.jpg 300w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">No se lo pens\u00f3. Y dijo que, por supuesto, ser\u00eda un honor. \u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Y tras meses de documentarse, leer y estudiar, se lanz\u00f3 a escribir un libro prodigioso que, en cada una de sus p\u00e1ginas, consigue captar la magia, la esencia, la dureza y el goce de vivir de una de esas ciudades que, m\u00e1s all\u00e1 de ser la capital de un pa\u00eds tan arrebatadoramente hermoso como controvertido, atesora buena parte de la historia de Latinoam\u00e9rica.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Como dec\u00eda, es un libro muy especial para m\u00ed. Porque Amir es un buen amigo. Porque <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=2644\">La Habana nos arrebat\u00f3<\/a>, cuando la visitamos, hace unos meses. Porque es uno de mis escritores favoritos. Porque la idea surgi\u00f3 en Gij\u00f3n, en ese m\u00e1gico festival que es Semana Negra. Porque, dejando aparte \u00abHasta donde el cine nos lleve\u00bb, es el libro del que m\u00e1s cerca he estado. Desde su g\u00e9nesis, siguiendo la redacci\u00f3n, correcci\u00f3n, dise\u00f1o, b\u00fasqueda de la foto de la portada&#8230;<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<figure id=\"attachment_3659\" aria-describedby=\"caption-attachment-3659\" style=\"width: 356px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/09\/madozcactus2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3659\" title=\"Amir Valle, Paco Camarasa y Eduardo Monteverde\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/09\/madozcactus2.jpg\" alt=\"Amir y Eduardo Monteverde, en Negra y Criminal versi\u00f3n Gij\u00f3n\" width=\"356\" height=\"280\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/09\/madozcactus2.jpg 356w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/09\/madozcactus2-300x235.jpg 300w\" sizes=\"auto, (max-width: 356px) 100vw, 356px\" \/><\/a><figcaption id=\"caption-attachment-3659\" class=\"wp-caption-text\">Amir y Eduardo Monteverde, en Negra y Criminal versi\u00f3n Gij\u00f3n<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Escribir es fant\u00e1stico. Pero asistir al proceso de creaci\u00f3n literaria va m\u00e1s all\u00e1. Ha sido un placer y un honor compartir conversaciones, e mails, manuscritos y maquetaciones tanto con Amir Valle, el autor, como con Jer\u00f3nimo, Jos\u00e9 Manuel y Juana, art\u00edfices de que esta aventura haya llegado a buen puerto.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Ahora sois los lectores a qui\u00e9nes os toca juzgar.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">En unos d\u00edas volveremos a hablar de \u00abLa Habana. Puerta de las Am\u00e9ricas\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens, contento como un ni\u00f1o con zapatillas nuevas.\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La editorial ALMED presenta dos aut\u00e9nticas perlas bibliogr\u00e1ficas. \u00a0 Por un lado, el cl\u00e1sico de E.M. Foster sobre Alejandr\u00eda. \u00a0 Y, por otro, un libro muy especial: \u00abLa Habana. Puerta de las Am\u00e9ricas\u00bb, del cubano Amir Valle. \u00a0 \u00bfEs posible que les suene el nombre de Amir? \u00a0 S\u00ed.\u00a0Cuando habl\u00e1bamos de \u00e9l y de La [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[1873,1871,900,937,1872,21,28,24],"class_list":["post-3656","post","type-post","status-publish","format-standard","hentry","category-libros-bellos","tag-alejandria","tag-amir-valle","tag-cuba","tag-la-habana","tag-la-habana-puerta-de-las-americas","tag-negra-y-criminal","tag-semana-negra","tag-viajes"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/3656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=3656"}],"version-history":[{"count":5,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/3656\/revisions"}],"predecessor-version":[{"id":3665,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/3656\/revisions\/3665"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=3656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=3656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=3656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}