{"id":346,"date":"2008-07-08T11:43:00","date_gmt":"2008-07-08T10:43:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=346"},"modified":"2008-07-08T11:43:00","modified_gmt":"2008-07-08T10:43:00","slug":"el-bulevar-del-miedo","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-bulevar-del-miedo\/","title":{"rendered":"EL BULEVAR DEL MIEDO"},"content":{"rendered":"<div align=\"justify\"><\/div>\n<div align=\"justify\">\u201cEl bulevar del miedo\u201d es una apreciable novela de la escritora Juana Salabert, publicada por Alianza Editorial que, por lo primero que destaca es por la extraordinaria foto de su portada, titulada \u201cEmbajador nazi en Espa\u00f1a\u201d, presidida por una enorme cruz gamada, un grupo de los temidos moros de Franco a caballo y, al fondo, uno de los m\u00e1s emblem\u00e1ticos edificios de Madrid. Una fotograf\u00eda en blanco y negro cargada de simbolog\u00eda y fuerza. Una ilustraci\u00f3n que te ayuda a meterte en la historia cada vez que coges el libro y contin\u00faan la lectura. <\/div>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5220593025612110690\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp0.blogger.com\/_r6VY1mvj3jk\/SHNFsmh922I\/AAAAAAAACnE\/1AhWymsTuJ0\/s400\/_7.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Una lectura que nos lleva a dos ciudades muy diferentes, casi contradictorias, en dos \u00e9pocas muy diferentes, pero a las que la autora ha sabido encontrar un hilo conductor muy especial: el de los sue\u00f1os frustrados, las promesas incumplidas y las esperanzas rotas.<\/p>\n<p>Por un lado, el Madrid de los primeros a\u00f1os cuarenta en que Europa se desangraba en una Guerra Mundial cuyo salvaje pr\u00f3logo ya se hab\u00eda cerrado en Espa\u00f1a, en la Guerra Civil. Una Espa\u00f1a en la que los nazis campaban a su antojo, no obstante la te\u00f3rica neutralidad dispuesta por Franco. Una neutralidad que se demostr\u00f3 partidista, interesada y, sobre todo, muy inteligente, para desgracia de los espa\u00f1oles. <\/p>\n<p align=\"justify\"><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5220593034428276610\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp2.blogger.com\/_r6VY1mvj3jk\/SHNFtHX534I\/AAAAAAAACnk\/-6C43U3kqfA\/s400\/1.bmp\" border=\"0\" \/> <\/p>\n<p align=\"justify\">La segunda ciudad protagonista de \u201cEl bulevar del miedo\u201d es el Par\u00eds que, en mayo del 68, hac\u00eda pensar que otro mundo podr\u00eda ser posible. Ese Par\u00eds que, como escribiera Vila Matas, no se muere nunca. Una ciudad que ser\u00eda la capital oficiosa de un mundo enamorado del arte, la creatividad, la belleza y la hermosura. <\/p>\n<p align=\"justify\"><\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5220593030348640178\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp3.blogger.com\/_r6VY1mvj3jk\/SHNFs4LPj7I\/AAAAAAAACnc\/Ds7EJt_MAdo\/s400\/_26.jpg\" border=\"0\" \/><br \/>Y por esas dos ciudades transita, en momentos muy diferentes de su vida, Federico Fernet, hijo de un pintor republicano al que las circunstancias sit\u00faan en unas situaciones y compa\u00f1\u00edas muy parad\u00f3jicas. Desde la hermosa, intrigante y fascinante Frieda al enga\u00f1oso y sibilino Mosieur Maurice, qui\u00e9nes tienen montado en Madrid un jugoso tinglado de tr\u00e1fico de obras de arte provenientes del expolio que los nazis estaban haciendo en Francia. <\/p>\n<p><\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5220593025943408306\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp0.blogger.com\/_r6VY1mvj3jk\/SHNFsnw9DrI\/AAAAAAAACnM\/qc7w8pGgB2E\/s400\/_11.jpg\" border=\"0\" \/><br \/>Las relaciones vamp\u00edricas que se establecen entre ellos y esa mezcla de atracci\u00f3n\/repulsi\u00f3n con que el mal siempre trata de seducir a los esp\u00edritus j\u00f3venes, idealistas, sensibles y con amplitud de miras.<\/p>\n<p>En \u201cEl bulevar del miedo\u201d, Juana Salabert sube al joven Fernet a un alambre, muy alto, en mitad de la Gran V\u00eda madrile\u00f1a, y le obliga a bailar sobre \u00e9l, ante la miranda atenta de unos lectores que ven sus heroicos esfuerzos y sus apurados escorzos, intentando no perder el equilibrio. Una narraci\u00f3n tensa, con unas descripciones muy poderosas y que denota la exquisita sensibilidad de su autora. Una novela de lectura continua en la que su autora es muy exigente con el lector, no d\u00e1ndole tregua en ning\u00fan momento, por lo que quedado entre las <a href=\"http:\/\/pateando-el-mundo.blogspot.com\/2008\/05\/los-finalistas-de-los-premios.html\"><span style=\"color:#ff0000;\"><strong>finalistas del Premio Hammett de Semana Negra<\/strong><\/span><\/a> junto a <a href=\"http:\/\/pateando-el-mundo.blogspot.com\/2008\/07\/chamam.html\"><span style=\"color:#ff0000;\"><strong>\u00abChamam\u00e9\u00bb<\/strong><\/span><\/a>, <a href=\"http:\/\/pateando-el-mundo.blogspot.com\/2008\/07\/pjaro.html\"><span style=\"color:#ff0000;\"><strong>\u00abP\u00e1jaro en mano\u00bb<\/strong><\/span><\/a>, <a href=\"http:\/\/pateando-el-mundo.blogspot.com\/2008\/06\/imn.html\"><span style=\"color:#ff0000;\"><strong>\u00abEl im\u00e1n y la br\u00fajula\u00bb<\/strong><\/span><\/a> y \u00abDelincuente argentino\u00bb.<\/p>\n<p><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5220593028308581074\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp2.blogger.com\/_r6VY1mvj3jk\/SHNFswk2utI\/AAAAAAAACnU\/wTGs7imCVEg\/s400\/_12.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Una novela compleja en que la tormentosa situaci\u00f3n internacional contribuye a generar unas apasionadas relaciones entre los personajes, para qui\u00e9nes parece cumplirse una de las m\u00e1s c\u00e9lebres maldiciones de la milenaria cultura china: \u201cte deseo que vivas tiempos interesantes\u201d.<\/p>\n<p>Jes\u00fas Lens Espinosa de los Monteros.<\/p>\n<p>Etiquetas: <a href=\"http:\/\/bitacoras.com\/canales\/el+bulevar+del+miedo\" rel=\"tag\">el bulevar del miedo<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/salabert\" rel=\"tag\">salabert<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/libros\" rel=\"tag\">libros<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/novela\" rel=\"tag\">novela<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/negra+y+criminal\" rel=\"tag\">negra y criminal<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/semana+negra\" rel=\"tag\">semana negra<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/nazis\" rel=\"tag\">nazis<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEl bulevar del miedo\u201d es una apreciable novela de la escritora Juana Salabert, publicada por Alianza Editorial que, por lo primero que destaca es por la extraordinaria foto de su portada, titulada \u201cEmbajador nazi en Espa\u00f1a\u201d, presidida por una enorme cruz gamada, un grupo de los temidos moros de Franco a caballo y, al fondo, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,28],"tags":[],"class_list":["post-346","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","category-semana-negra"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=346"}],"version-history":[{"count":0,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/346\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}