{"id":3412,"date":"2009-09-02T19:34:52","date_gmt":"2009-09-02T18:34:52","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=3412"},"modified":"2009-09-06T13:14:24","modified_gmt":"2009-09-06T12:14:24","slug":"asesinato-creativo","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/asesinato-creativo\/","title":{"rendered":"ASESINATO CREATIVO"},"content":{"rendered":"<ul>\n<li style=\"text-align: justify;\">\u00a0\u00bfUsted sabe lo que es el crowdfunding?<\/li>\n<li style=\"text-align: justify;\">\u00a0\u00bfPerd\u00f3n?<\/li>\n<li style=\"text-align: justify;\">\u00a0Pues mal empezamos.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>El inspector L\u00f3pez sali\u00f3 del calabozo dando uno de esos portazos susceptibles de provocar, por s\u00ed mismos, un terremoto devastador.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<ul>\n<li>\u00a0\u00bfHa llegado ya el maldito abogado de oficio?- bram\u00f3 L\u00f3pez, mientras se iba para su despacho, mascullando entre dientes.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>Pero, sin llegar a sentarse en su sill\u00f3n, enfil\u00f3 para el bar.<\/p>\n<p>\u00a0<\/p>\n<ul>\n<li>\u00a0A ver, Jorge. \u00bfT\u00fa sabes lo que es el crowdfunding?<\/li>\n<li>\u00a0\u00bfUn nuevo deporte de riesgo en los que cualquier gilipollas\u00a0paga una pasta gansa para que le suba la adrenalina, supuestamente jug\u00e1ndose el tipo, pero en realidad m\u00e1s seguro que el Air Force One?<\/li>\n<li>\u00a0Pues ser\u00e1. Anda. Ponme un Pampero con Coca-cola Zero, que no estamos m\u00e1s que a dos de septiembre y ya estoy hasta los cojones.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>Volvi\u00f3 a la comisar\u00eda. El abogado segu\u00eda sin aparecer y el fiscal quer\u00eda irse a casa a ver el resumen del partido del Real Madrid, que, aunque quisiera ocultarlo, el CR9 le pon\u00eda cantidad.<\/p>\n<p>\u00a0<\/p>\n<ul>\n<li>\u00a0A ver, L\u00f3pez. \u00bfQu\u00e9 pasa con el detenido del siete?<\/li>\n<li>\u00a0Que dice que la culpa fue del crowdfunding. Y de un cu\u00f1ado suyo adicto a Internet. Que lo hizo en estado de necesidad y en leg\u00edtima defensa creativa.<\/li>\n<li>\u00a0En serio, L\u00f3pez, \u00bfhas superado realmente lo de Paulina?<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>Y cuando L\u00f3pez iba a contestarle al fiscal que lo de Paulina lo hab\u00eda superado a trav\u00e9s de las bondades de la boca de su hermana, y no por lo bien que hablaba precisamente, apareci\u00f3 el abogado. Un pipiolo. Para variar. Traje de chaqueta, gomina a espuertas y una de esas carteras, seguramente regalada por sus orgullosos suegros, que costaba lo mismo que \u00e9l cobraba en un mes&#8230; guardias, mordidas y coimas incluidas.<\/p>\n<p>\u00a0<\/p>\n<ul>\n<li>\u00a0Se\u00f1or abogado, que es verdad que yo le mat\u00e9.<\/li>\n<li>\u00a0\u00a1Calle, hombre, calle! \u00bfNo ve que ya le han le\u00eddo sus derechos y que todo lo que diga puede ser usado en su contra?<\/li>\n<li>\u00a0Pero si es que no lo puedo negar. \u00bfPara qu\u00e9? El portero de su casa me trinc\u00f3 con las tijeras en la mano y todo cubierto con su sangre. Hay testigos, tienen el arma del crimen con mis huellas en ella, todas las pruebas de ADN que quieran y, adem\u00e1s, hab\u00eda motivo. Y ah\u00ed es donde radica el quid de la cuesti\u00f3n y la \u00fanica defensa posible, se\u00f1or abogado.<\/li>\n<li>\u00a0Y el motivo es&#8230;<\/li>\n<li>\u00a0El crowdfunding.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>L\u00f3pez pudo sonre\u00edr. Por fin. El pipiolo interrogaba con la mirada al veterano polic\u00eda, angustiado, intentando buscar su complicidad para encontrar algo de luz en las palabras de su defendido. Como toda respuesta, L\u00f3pez dedic\u00f3 al abogado un leve arqueo de cejas que, traducido, ven\u00eda a significar algo as\u00ed como \u00ab\u00a1ch\u00fapate esa, mete el crowdfunding en tu carterita, la enrollas y te la embutes por el culo, pijo de mierda!\u00bb<\/p>\n<p>\u00a0<\/p>\n<ul>\n<li>\u00a0\u00a1Ah! El crowdfunding&#8230; ya. Eso es algo parecido a la estafa piramidal de Madoff, pero en versi\u00f3n m\u00e1s sofisticada, \u00bfverdad? Creo que le\u00ed algo sobre ello en las p\u00e1ginas sepia del peri\u00f3dico del domingo&#8230;<\/li>\n<li>\u00a0Pero \u00bfde qu\u00e9 co\u00f1o est\u00e1 hablando? \u00bfY usted es mi abogado? Creo que lo mejor ser\u00e1 que me defienda yo mismo.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>Y, efectivamente, renunci\u00f3 a que el abogado le representara en la comparecencia ante el Juez de guardia, en la que el fiscal solicit\u00f3 el ingreso en prisi\u00f3n sin fianza de Andr\u00e9s Berbell\u00f3n, acusado del asesinato de Mat\u00edas Angulo, al que degoll\u00f3, acuchill\u00f3 y medio desmembr\u00f3 con unas afiladas tijeras, tras sostener con \u00e9l una acalorada discusi\u00f3n.<\/p>\n<p>\u00a0<\/p>\n<ul>\n<li>\u00a0Y la culpa dice usted que fue&#8230;<\/li>\n<li>\u00a0\u00a1De mi cu\u00f1ado!<\/li>\n<li>\u00a0Ahhhh. Vale. Su cu\u00f1ado. \u00bfY eso?<\/li>\n<li>\u00a0Porque mi hermana y yo hab\u00edamos heredado un dinerito. Y no sab\u00edamos qu\u00e9 hacer con \u00e9l. Con esto de la crisis, \u00a1como para embarcarse en alg\u00fan piso! Y ni pensar en la Cuenta Naranja de un banco que no existe y que cualquier d\u00eda, en vez de Naranja, se pone rojo como un tomate. Y entonces lleg\u00f3 \u00e9l. El espabilado. El listo. El E-cu\u00f1ado, como a \u00e9l le gusta definirse.<\/li>\n<li>\u00a0\u00bfE-cu\u00f1ado?<\/li>\n<li>\u00a0S\u00ed. \u00bfUsted no tiene en su familia a un cu\u00f1ado que hace paellas los domingos o que lo sabe todo acerca de los \u00faltimos modelos de coches?<\/li>\n<li>\u00a0Hombre, la verdad&#8230; pues s\u00ed. A m\u00ed me ha tocado el paellero.<\/li>\n<li>\u00a0A m\u00ed, sin embargo, me ha tocado el cu\u00f1ado del siglo XXI. El c\u00edbercu\u00f1ado. El que est\u00e1 todo el d\u00eda enganchado a Internet. Y el que descubri\u00f3 el crowdfunding&#8230;<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>El Juez ten\u00eda que reconocer que aquel tipo le ca\u00eda bien. Sinceramente, \u00e9l mismo hab\u00eda barajado, m\u00e1s de un s\u00e1bado, la posibilidad de contratar a un sicario que matara a su cu\u00f1ado el paellero, por la v\u00eda de hacerle tragar kilos y kilos de arroz pasado, requemado y pastoso&#8230; Eximente completa, quiz\u00e1 no, pero todo el mundo sabe que cargarse a un cu\u00f1ado, por lo general, lleva impl\u00edcita una cierta carga atenuante&#8230;<\/p>\n<p>\u00a0<\/p>\n<ul>\n<li>\u00a0Pero usted no ha matado a su cu\u00f1ado&#8230;<\/li>\n<li>\u00a0Ya. Pero en cuanto decrete usted mi libertad, cr\u00e9ame que pienso estrangularlo con mis propias manos.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>Decididamente, aqu\u00e9l tipo le ca\u00eda mejor que bien&#8230; de hecho, empez\u00f3 a fantasear con la posibilidad de soltarlo a cambio de que aplicara una oferta \u00abdos por uno\u00bb en eso de llevarse por delante al cu\u00f1ado.<\/p>\n<p>\u00a0<\/p>\n<ul>\n<li>\u00a0\u00bfEst\u00e1 usted loco? Olvide sus desbarros y explique de una vez qu\u00e9 tiene que ver su cu\u00f1ado con Mat\u00edas Angulo y con el crownfulling \u00e9se&#8230;<\/li>\n<li>\u00a0\u00bfCrownfulling? Se\u00f1or\u00eda, por favor. Aunque nuestra monarqu\u00eda empiece a dar risa, no estamos a\u00fan en la Inglaterra del pr\u00edncipe Charles&#8230; \u00a1CROWDFUNDING!<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>El juez dio un respingo que casi le tir\u00f3 de la silla, ante la exclamaci\u00f3n del detenido.<\/p>\n<p>\u00a0<\/p>\n<ul>\n<li>\u00a0Lo mismo me pas\u00f3 a m\u00ed, Se\u00f1or\u00eda. Casi me incrusto en el techo cuando el capullo de mi cu\u00f1ado grit\u00f3 la palabrita de marras, como si hubiera encontrado la piedra filosofal o el arca de alianza, a trav\u00e9s de Internet.<\/li>\n<li>\u00a0\u00bfY podr\u00eda usted explicarnos, someramente, qu\u00e9 es eso?<\/li>\n<li>\u00a0Crowdfunding. Uni\u00f3n y fuerza. T\u00e9cnicamente, se describe como \u00abla forma que tienen los nuevos creadores de sacar partido de la Red, gracias a la obtenci\u00f3n instant\u00e1nea de datos, informaci\u00f3n, publicidad y dinero.\u00bb<\/li>\n<li>\u00a0O sea, que le timaron por Internet a trav\u00e9s de una nueva modalidad de pshishing con nombre de estilo cl\u00e1sico de nataci\u00f3n&#8230; a trav\u00e9s del que le limpiaron la cuenta bancaria hasta bien el fondo&#8230;<\/li>\n<li>\u00a0\u00a1Que no! Que no es tan sencillo.<\/li>\n<li>\u00a0Ya me parec\u00eda a m\u00ed&#8230;<\/li>\n<li>\u00a0En pocas palabras, de lo que se trata con el crowdfunding de los cojones es de captar socios capitalistas para que financien la producci\u00f3n de pel\u00edculas y, dependiendo de lo que aporten, adem\u00e1s de que su nombre aparezca en los t\u00edtulos de cr\u00e9dito y de participar en un hipot\u00e9tico reparto de beneficios, los inversores tienen derecho a participar en el proceso creativo de la misma.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>Y el Juez se qued\u00f3, l\u00f3gicamente, m\u00e1s estupefacto a\u00fan. Si cabe.<\/p>\n<p>\u00a0<\/p>\n<ul>\n<li>\u00a0Perdone, pero yo entiendo ni una palabra de lo que me est\u00e1 usted contando&#8230;<\/li>\n<li>\u00a0Pues m\u00e1s claro, el agua. Mat\u00edas Angulo es el director de la pel\u00edcula. O lo era. \u00a1Menudo cretino! \u00bfSe puede usted creer? Ten\u00edamos una historia fabulosa sobre la que trabajar. En eso, el memo de mi cu\u00f1ado ten\u00eda raz\u00f3n. \u00a1Pedazo de historia! Tan buena era, que no s\u00f3lo invert\u00ed en el proyecto el importe completo de la herencia, sino que, a medida que la preproducci\u00f3n necesitaba de m\u00e1s y m\u00e1s fondos, hipotequ\u00e9 mi piso de la ciudad y el apartamento de la playa y hasta ped\u00ed un pr\u00e9stamo personal a mi Caja de Ahorros de toda la vida.<\/li>\n<li>\u00a0\u00bfComo?<\/li>\n<li>\u00a0Claro. Al principio iba a ser una pel\u00edcula modesta, de \u00ednfimo presupuesto. Pero a medida que me met\u00ed a fondo en la escritura del gui\u00f3n, me di cuenta de que la historia era demasiado buena como para desperdiciarla en una cutreproducci\u00f3n de tres al cuarto.<\/li>\n<li>\u00a0\u00bfY qu\u00e9 pas\u00f3?<\/li>\n<li>\u00a0Pues que lleg\u00f3 Mat\u00edas a joderla. Que lleg\u00f3 el directorcillo \u00e9se de las narices, un mindundi, un don nadie reci\u00e9n salido de la Escuela de Cine de Barcelona, al que no conoc\u00eda ni Dios, y empez\u00f3 a hacer cambios en mi gui\u00f3n. Que la productora hab\u00eda firmado con \u00e9l un contrato en el que le permit\u00eda hacer y deshacer a su antojo. A ese miserable.<\/li>\n<li>\u00a0Pero \u00bfpor qu\u00e9 habla usted de su gui\u00f3n con tanta insistencia? \u00bfNo era un trabajo creativo comunitario?<\/li>\n<li>\u00a0\u00a1Comunitario y unos cojones! \u00a1M\u00edo, m\u00edo! \u00a1Era m\u00edo! \u00a1Yo lo pagu\u00e9! \u00a1Era m\u00edo! \u00a1Yo hab\u00eda escrito! Eran m\u00edos tanto el gui\u00f3n como la pel\u00edcula. \u00bfNo lo entiende? Yo hab\u00eda puesto la pasta y aquel indeseable quer\u00eda robar mi proyecto, destrozarlo, poseerlo, hacerlo suyo&#8230;<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p style=\"text-align: justify;\">Es un relato de Jes\u00fas Lens Espinosa de los Monteros y&#8230;\u00a0 <span style=\"color: #ff0000;\">CONTINUAR\u00c1&#8230;\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">&#8230;por culpa de <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=3418\">ESTO. <\/a><\/span>\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Para seguir leyendo el Cuento, pinchar <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=3452\">AQU\u00cd<\/a>. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00bfUsted sabe lo que es el crowdfunding? \u00a0\u00bfPerd\u00f3n? \u00a0Pues mal empezamos. \u00a0 El inspector L\u00f3pez sali\u00f3 del calabozo dando uno de esos portazos susceptibles de provocar, por s\u00ed mismos, un terremoto devastador.\u00a0\u00a0 \u00a0 \u00a0\u00bfHa llegado ya el maldito abogado de oficio?- bram\u00f3 L\u00f3pez, mientras se iba para su despacho, mascullando entre dientes. \u00a0 Pero, sin [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[31],"tags":[1775,1774,272,21,1643],"class_list":["post-3412","post","type-post","status-publish","format-standard","hentry","category-relatos","tag-asesinato-creativo","tag-crowdfunding","tag-cuento","tag-negra-y-criminal","tag-relato"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/3412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=3412"}],"version-history":[{"count":7,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/3412\/revisions"}],"predecessor-version":[{"id":3415,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/3412\/revisions\/3415"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=3412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=3412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=3412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}