{"id":3361,"date":"2009-08-29T20:33:42","date_gmt":"2009-08-29T19:33:42","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=3361"},"modified":"2009-08-29T21:08:23","modified_gmt":"2009-08-29T20:08:23","slug":"la-compania-del-nadador-de-fondo","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-compania-del-nadador-de-fondo\/","title":{"rendered":"LA COMPA\u00d1\u00cdA DEL NADADOR DE FONDO"},"content":{"rendered":"<p style=\"text-align: justify;\">De las cosas que m\u00e1s me gustan, cuando estamos en la Chucha, es hacerme a las aguas del Mediterr\u00e1neo, a nadar, con mi hermano. Hace unos a\u00f1os casi le provocamos una apoplej\u00eda a nuestra madre cuando entramos en el mar a nadar un rato por la tarde y, tras doblar el Cabo Sacratif y descansar un rato en la playa de La Joya, no volvimos a casa hasta bien entrada la noche. La pobre se llev\u00f3 un berrinche del quince, pero, desde entonces, echarnos a las aguas en uno de esos ritos fraternales que nos gusta repetir de cuando en vez.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Hoy, por primera y seguramente \u00faltima vez este verano, lo volvimos a hacer. Un par de horas de nataci\u00f3n en aguas abiertas, sometidos a los vaivanes de las corrientes en ese Cabo, bajo el farall\u00f3n de rocas sobre el que reina el Faro.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Yo no nado. Yo floto y me desplazo miserablemente por el agua. Mi hermano desespera, teniendo que esperarme, pero mola eso de pasarse un par de horas metiendo y sacando la cabeza del agua, viendo los fondos marinos y los peces y disfrutando de un agua limpia, cristalina, fresquita, pero agradable. Y como pasa cuando vas corriendo, la cabeza da vueltas. Muchas vueltas, puesta en remojo. Casi como si centrifugase.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Aunque, por razones obvias, cuando nadas no puedes hablar, me gusta\u00a0echarme\u00a0a las aguas con mi hermano y ver su cabeza ah\u00ed delante, subiendo y bajando al comp\u00e1s de las olas, pasando junto a las rocas infestadas de afilados mejillones y disfrutando de las espuma del agua del mar, chocando contra la piedra. Mirando hacia arriba y viendo unas veces el farall\u00f3n monta\u00f1oso y, otras, el horizonte y las aguas sin fin, las olas que vienen y van.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Correr es algo inherente al ser humano. Nadar no. Pero ambos deportes, de fondo y soledad, son muy parecidos. Como la bicicleta. Deportes de resistencia en los que lo importante es la cabeza, que te permiten disfrutar de una actividad f\u00edsica que conlleva una buena actividad cerebral. Y sensual. Dentro del agua, sintiendo que el sol acaricia la piel, con el cuerpo sumergido en unas aguas c\u00e1lidas y generosas&#8230; es un estado muy cercano al de la felicidad.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Y, despu\u00e9s, un buen arroz compartido con un pu\u00f1ado de amigos y nuevamente la playa, leyendo en la orilla y disfrutando de una buena lectura o del jaleo de los cr\u00edos&#8230; ahora que el verano se termina, siempre te preguntas que por qu\u00e9 no has disfrutado m\u00e1s de esa Chucha\u00a0en\u00a0la que no est\u00e1s como en casa, no. Es que est\u00e1s en esa casa a\u00a0la que viniste con 11 d\u00edas de edad y\u00a0en la que, cuando vienes, no entiendes por qu\u00e9 \u00a0no vienes m\u00e1s.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Uno y sus contradicciones.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens, acu\u00e1tico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De las cosas que m\u00e1s me gustan, cuando estamos en la Chucha, es hacerme a las aguas del Mediterr\u00e1neo, a nadar, con mi hermano. Hace unos a\u00f1os casi le provocamos una apoplej\u00eda a nuestra madre cuando entramos en el mar a nadar un rato por la tarde y, tras doblar el Cabo Sacratif y descansar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[1750,1751,1748,1749],"class_list":["post-3361","post","type-post","status-publish","format-standard","hentry","category-miscelanea","tag-cabo-sacratif","tag-carchuna","tag-chucha","tag-nadar"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/3361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=3361"}],"version-history":[{"count":10,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/3361\/revisions"}],"predecessor-version":[{"id":3363,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/3361\/revisions\/3363"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=3361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=3361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=3361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}