{"id":3307,"date":"2009-08-21T07:00:14","date_gmt":"2009-08-21T06:00:14","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=3307"},"modified":"2009-08-20T09:12:33","modified_gmt":"2009-08-20T08:12:33","slug":"sonria-por-favor","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/sonria-por-favor\/","title":{"rendered":"SONR\u00cdA, POR FAVOR"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>La columna de hoy viernes, en plan luminoso, positivo y alegre. \u00a1Qu\u00e9 ya se va terminando agosto! \ud83d\ude42 \u00a0<\/em><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Hay d\u00edas, cuando vuelvo de correr, en que al final del camino me encuentro con una amiga que, a\u00fan sudando por todos y cada uno de los poros de mi piel, no duda en plantarme dos besazos y, a trav\u00e9s de una enorme y luminosa sonrisa, me desea una feliz tarde. Una sonrisa, abierta, generosa y natural que consigue hacer que me olvide del cansancio, del calor y de la sed, alegr\u00e1ndome el resto del d\u00eda.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<figure id=\"attachment_3308\" aria-describedby=\"caption-attachment-3308\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/08\/081.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3308\" title=\"Joker\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/08\/081.jpg\" alt=\"Sonr\u00eda, please\" width=\"400\" height=\"613\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/08\/081.jpg 400w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/08\/081-195x300.jpg 195w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><figcaption id=\"caption-attachment-3308\" class=\"wp-caption-text\">Sonr\u00eda, please<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Seguramente ya conocen ustedes esa frase que, al estilo Autoayuda-New age, reza as\u00ed: <em>\u00abUna sonrisa significa mucho. Enriquece a quien la recibe, sin empobrecer a quien la ofrece. Dura un segundo y su recuerdo nunca se borra.\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Aunque un tanto engolada, reconozcamos que la frase es de libro. Para enmarcar. Para escribir con may\u00fasculas en el espejo en que nos miramos cada ma\u00f1ana, al levantarnos, mientras nos lavamos la cara y hacemos planes para el resto de la jornada. Uno de esos consejos que todos deber\u00edamos aplicarnos y seguir a rajatabla.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong><em>\u00abWhy so serious?\u00bb<\/em><\/strong>, se preguntaba el Joker en los carteles publicitarios de la \u00faltima y fant\u00e1stica pel\u00edcula de Batman. Un Joker que, a trav\u00e9s de su mal\u00e9fica y tr\u00e1gica sonrisa, se erigi\u00f3 en el verdadero protagonista del filme y cuya imagen de portada en el tebeo \u00abLa broma asesina\u00bb, armado con una c\u00e1mara de fotos y diciendo <strong><em>\u00abSonr\u00eda\u00bb<\/em><\/strong>, he usado muchas veces en mails dirigidos a personas que andaban tristes, alica\u00eddas o en baja forma.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<figure id=\"attachment_3309\" aria-describedby=\"caption-attachment-3309\" style=\"width: 450px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/08\/073.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3309\" title=\"Joker\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/08\/073.jpg\" alt=\"\u00bfPor qu\u00e9 tan serios?\" width=\"450\" height=\"666\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/08\/073.jpg 450w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/08\/073-202x300.jpg 202w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><figcaption id=\"caption-attachment-3309\" class=\"wp-caption-text\">\u00bfPor qu\u00e9 tan serios?<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Como Marta Dom\u00ednguez. La atleta palentina, una de las mejores deportistas espa\u00f1olas de todos los tiempos, gane o pierda, siempre tiene una inmensa y festiva sonrisa en su rostro. \u00bfLa recuerdan en Pek\u00edn, despu\u00e9s de caerse en el final de su maravillosa carrera de 3.000 obst\u00e1culos, al tropezar con una de las vallas, cuando cabalgaba directamente hacia el medallero ol\u00edmpico? A m\u00ed se me saltaron las l\u00e1grimas, vi\u00e9ndola sonre\u00edr frente a las c\u00e1maras de televisi\u00f3n, con el coraz\u00f3n todav\u00eda a mil pulsaciones, quit\u00e1ndole hierro al accidente. Y quiz\u00e1 por eso, el pasado lunes me emocion\u00e9 como un ni\u00f1o peque\u00f1o cuando gan\u00f3 <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=3269\">la medalla de oro en los Mundiales de Berl\u00edn<\/a>, viendo su enorme cara de felicidad al entrar en meta.<\/p>\n<figure id=\"attachment_3310\" aria-describedby=\"caption-attachment-3310\" style=\"width: 499px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/08\/129.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3310\" title=\"Marta Dom\u00ednguez\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/08\/129.jpg\" alt=\"\u00a1Sonrisa de oro!\" width=\"499\" height=\"367\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/08\/129.jpg 620w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/08\/129-300x220.jpg 300w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><\/a><figcaption id=\"caption-attachment-3310\" class=\"wp-caption-text\">\u00a1Sonrisa de oro!<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">O Usain Bolt. Un tipo feliz que, antes, durante y despu\u00e9s de sus carreras, majestuosas e imperiales, siempre sonr\u00ede y bromea con desenfado y alegr\u00eda, incluso antes de batir su sideral r\u00e9cord del mundo, en uno de los <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=3252\">Instantes Decisivos atl\u00e9ticos <\/a>m\u00e1s impresionantes de la historia.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<figure id=\"attachment_3311\" aria-describedby=\"caption-attachment-3311\" style=\"width: 490px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/08\/159.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3311\" title=\"Usain Bolt\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/08\/159.jpg\" alt=\"Bolt, un tipo feliz\" width=\"490\" height=\"333\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/08\/159.jpg 490w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/08\/159-300x203.jpg 300w\" sizes=\"auto, (max-width: 490px) 100vw, 490px\" \/><\/a><figcaption id=\"caption-attachment-3311\" class=\"wp-caption-text\">Bolt, un tipo feliz<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Hay profesiones, como la de la hosteler\u00eda, en que las sonrisas deber\u00edan ir con el puesto. Por ejemplo, las que acompa\u00f1an a la ca\u00f1as que nos pone Isa, las noches de concierto en la Plaza de las Culturas. \u00a1Impagables! \u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">As\u00ed que, ahora que las autoridades sanitarias nos proh\u00edben los besos, abrazos, apretones de mano y dem\u00e1s muestras de afectuoso cari\u00f1o, hagamos caso al Maestro Tuitero Antonio Domingo y <em>\u00abregalemos sonrisas, que son gratis, no se nos gasta el semillero y dan una cosecha buen\u00edsima de momentos felices\u00bb<\/em>.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens Espinosa de los Monteros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La columna de hoy viernes, en plan luminoso, positivo y alegre. \u00a1Qu\u00e9 ya se va terminando agosto! \ud83d\ude42 \u00a0 \u00a0 Hay d\u00edas, cuando vuelvo de correr, en que al final del camino me encuentro con una amiga que, a\u00fan sudando por todos y cada uno de los poros de mi piel, no duda en plantarme [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[1700,877,1697,1646,1698,1659,1699,1695,1696,1648],"class_list":["post-3307","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-antonio-domingo","tag-batman","tag-gripe-a","tag-instante-decisivo","tag-joker","tag-marta-dominguez","tag-sonreir","tag-sonria","tag-sonrisa","tag-usain-bolt"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/3307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=3307"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/3307\/revisions"}],"predecessor-version":[{"id":3312,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/3307\/revisions\/3312"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=3307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=3307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=3307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}