{"id":33042,"date":"2023-05-29T13:18:10","date_gmt":"2023-05-29T12:18:10","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=33042"},"modified":"2023-05-29T13:18:10","modified_gmt":"2023-05-29T12:18:10","slug":"la-unidad-es-el-noir-televisivo-mas-vibrante","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-unidad-es-el-noir-televisivo-mas-vibrante\/","title":{"rendered":"&#8216;La unidad&#8217; es el noir televisivo m\u00e1s vibrante"},"content":{"rendered":"<p>Les confieso que, sobre todo cuando se termina la temporada de baloncesto, hay meses en que me planteo darme de baja de Movistar +. Es muy cara. Entonces me acuerdo de series de producci\u00f3n propia tan estupendas como \u2018La peste\u2019, la muy reciente \u2018El hijo zurdo\u2019 o \u2018La unidad\u2019 y se me pasan las ganas de entonar el adi\u00f3s con el coraz\u00f3n. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-unidad-es-el-noir-televisivo-mas-vibrante\/la-unidad-kabul-poster\/\" rel=\"attachment wp-att-33043\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-33043\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-unidad-kabul-poster-212x300.jpeg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-unidad-kabul-poster-212x300.jpeg 212w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-unidad-kabul-poster-644x911.jpeg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-unidad-kabul-poster-768x1087.jpeg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-unidad-kabul-poster.jpeg 848w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n<p>Hace ahora tres a\u00f1os salud\u00e1bamos con alegr\u00eda y alborozo la llegada a la parrilla de la primera temporada de \u2018La unidad\u2019. As\u00ed arrancaba aquella rese\u00f1a: \u201cUna sola temporada de seis episodios ha bastado para que la miniserie \u2018La unidad\u2019, reci\u00e9n estrenada en la plataforma de Movistar +, se haya convertido en obra referencial del noir televisivo espa\u00f1ol. Hablamos de una serie polic\u00edaca sobre una unidad especializada en la lucha contra el terrorismo yihadista, radicada en la Comisar\u00eda General de Informaci\u00f3n. Una serie que transmite verismo y autenticidad: desde el primer momento te crees lo que pasa en pantalla. Realismo. Es la piedra angular sobre la que se proyecta \u2018La unidad\u2019. Realismo en las tramas, en los personajes y en la ambientaci\u00f3n\u201d. (Leer el resto <a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-unidad-television-de-alto-voltaje\/\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a>).<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-unidad-es-el-noir-televisivo-mas-vibrante\/la-unidad-kabul\/\" rel=\"attachment wp-att-33044\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-33044\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-Kabul-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-Kabul-300x200.jpeg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-Kabul-644x429.jpeg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-Kabul-768x512.jpeg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-Kabul-1536x1024.jpeg 1536w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-Kabul-2048x1366.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Y pon\u00edamos otros dos t\u00edtulos como referencia: \u2018Oficina de infiltrados\u2019 y \u2018Homeland\u2019. \u00a1Casi nada al aparato! En 2022 lleg\u00f3 la segunda temporada de la serie creada por Dani de la Torre y Alberto Marini, igualmente espectacular y, para m\u00e1s inri, con una inquietante rama de la trama rodada y radicada en Granada. (Leer <a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/rapa-y-la-unidad-t2-gran-cine-negro\/\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a> aquella rese\u00f1a).<\/p>\n<p>Y lleg\u00f3 la tercera temporada. Y nos sorprendi\u00f3 a todos ya que la acci\u00f3n transcurre \u00edntegramente en Afganist\u00e1n, durante los cuatro d\u00edas que precedieron la ca\u00edda de Kabul en manos de los talibanes y el puente a\u00e9reo que sac\u00f3 a miles de personas del pa\u00eds\u2026 dejando a muchos millones de afganos, y sobre todo de afganas, abandonadas a su suerte.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-unidad-es-el-noir-televisivo-mas-vibrante\/la-unidad-actrices\/\" rel=\"attachment wp-att-33045\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-33045\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-unidad-actrices-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-unidad-actrices-300x200.jpeg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-unidad-actrices-644x429.jpeg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-unidad-actrices-768x512.jpeg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-unidad-actrices-1536x1024.jpeg 1536w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-unidad-actrices-2048x1366.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>La apuesta es valiente y los resultados, rotundos. Una maravilla. En estos d\u00edas de tanto ajetreo, cada vez que pod\u00eda sacar una hora de tiempo, me enchufaba uno de los seis episodios de la temporada. Y no les digo nada del shock, de la conmoci\u00f3n, del segundo cap\u00edtulo. Porque si algo nos ense\u00f1aron series como la m\u00edtica \u201824\u2019 o las anteriormente citadas es que cualquier personaje puede morir en cualquier momento. Menos Bauer. Jack Bauer no. Pero los dem\u00e1s\u2026 Da lo mismo lo mejor o peor que nos caigan y su peso en la historia: si apareces en \u2018La unidad\u2019 puedes morir. Eso es as\u00ed. Argumentalmente hablando, enti\u00e9ndase.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Perm\u00edtanme que destaque el excepcional trabajo de la actriz Shabnam Rahimi, cuya historia personal es alucinante: campeona de boxeo en su Afganist\u00e1n natal, donde aprendi\u00f3 a boxear para defenderse del acoso sistem\u00e1tico de los hombres, sali\u00f3 del pa\u00eds con 21 a\u00f1os. Vino a Espa\u00f1a para el estreno de un documental, \u2018Boxing for Freedom\u2019 \u2014ya ardo por verlo en Filmin\u2014 y se qued\u00f3 con su hermana, con el apoyo de Juan Antonio Moreno Amador y Silvia Venegas, autores de la cinta.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-unidad-es-el-noir-televisivo-mas-vibrante\/la-unidad-actriz\/\" rel=\"attachment wp-att-33046\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-33046\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-actriz-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-actriz-300x200.jpeg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-actriz-644x429.jpeg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-actriz-768x512.jpeg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-actriz-1536x1024.jpeg 1536w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-actriz-2048x1366.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Como es marca de la casa, en esta tercera temporada de \u2018La unidad\u2019, la ficci\u00f3n cabalga a lomos de la realidad. Y el ritmo. Atenci\u00f3n al ritmo que le imprimen De la Torre y Marini a todo lo que pasa en pantalla. Si quieren saber lo que es un comienzo \u2018in medias res\u2019 de manual, vean el primer cap\u00edtulo de la temporada. No hay tiempos muertos. No hay pausas innecesarias. Hay tensi\u00f3n, nervio y\u2026 \u00bfhemos dicho ya lo del ritmo?<\/p>\n<figure id=\"attachment_33047\" aria-describedby=\"caption-attachment-33047\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-unidad-es-el-noir-televisivo-mas-vibrante\/la-unidad-western\/\" rel=\"attachment wp-att-33047\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-33047\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-western-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-western-300x200.jpeg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-western-644x429.jpeg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-western-768x512.jpeg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-western-1536x1024.jpeg 1536w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/05\/La-Unidad-western-2048x1366.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-33047\" class=\"wp-caption-text\">A ritmo de western, que para algo se ha filmado en Almer\u00eda&#8230;<\/figcaption><\/figure>\n<p>He o\u00eddo que con esta temporada se termina \u2018La unidad\u2019. Seguramente habr\u00e9 o\u00eddo mal. No tendr\u00eda sentido. Por cierto que el papel del ej\u00e9rcito espa\u00f1ol es igualmente relevante en la trama de una de esas series que llevan el marchamo de IMPRESCINDIBLE. \u00a1No se la pierdan!<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32647 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/11\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les confieso que, sobre todo cuando se termina la temporada de baloncesto, hay meses en que me planteo darme de baja de Movistar +. Es muy cara. Entonces me acuerdo de series de producci\u00f3n propia tan estupendas como \u2018La peste\u2019, la muy reciente \u2018El hijo zurdo\u2019 o \u2018La unidad\u2019 y se me pasan las ganas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11144,21,12],"tags":[21506,21509,19070,21507,21510,19069,21504,2900,21505,21503,21508,21511],"class_list":["post-33042","post","type-post","status-publish","format-standard","hentry","category-granada-noir","category-negra-y-criminal","category-television","tag-alberto-marina","tag-boxing-for-freedom","tag-dani-de-la-torre","tag-el-hijo-zurdo","tag-juan-antonio-moreno-amador","tag-la-unidad","tag-la-unidad-kabul","tag-movistar","tag-movistar-series","tag-serie-la-unidad","tag-shabnam-rahimi","tag-silvia-venegas"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/33042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=33042"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/33042\/revisions"}],"predecessor-version":[{"id":33049,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/33042\/revisions\/33049"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=33042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=33042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=33042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}