{"id":32918,"date":"2023-04-04T09:59:53","date_gmt":"2023-04-04T08:59:53","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=32918"},"modified":"2023-04-04T10:00:42","modified_gmt":"2023-04-04T09:00:42","slug":"cementerio-de-secretos-el-linguista-que-sabia-demasiado","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/cementerio-de-secretos-el-linguista-que-sabia-demasiado\/","title":{"rendered":"&#8216;Cementerio de secretos&#8217;: el ling\u00fcista que sab\u00eda demasiado"},"content":{"rendered":"<p>D\u00e9jenme que les cuente un secreto: se acaba de publicar una de Hitchcock en Espa\u00f1a. Una novela, quiero decir. La ha escrito esa bestia parda que responde al nombre de Jos\u00e9 Antonio P\u00e9rez Ledo, se titula \u2018Cementerio de secretos\u2019 y ya tardan en ir a su librer\u00eda de cabecera para hacerse con ella. Si la empiezan uno de estos santos d\u00edas, al domingo de Resurrecci\u00f3n no llega: sus cerca de 450 p\u00e1ginas se beben con la misma delectaci\u00f3n que el primer trago de cerveza despu\u00e9s de una larga caminata bajo el sol de verano.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/cementerio-de-secretos-el-linguista-que-sabia-demasiado\/cementerio-de-secretos-portada\/\" rel=\"attachment wp-att-32919\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32919\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/Cementerio-de-Secretos-portada-197x300.jpeg\" alt=\"\" width=\"197\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/Cementerio-de-Secretos-portada-197x300.jpeg 197w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/Cementerio-de-Secretos-portada.jpeg 329w\" sizes=\"auto, (max-width: 197px) 100vw, 197px\" \/><\/a><\/p>\n<p>Y ahora, perm\u00edtanme que me explique. \u2018Cementerio de secretos\u2019 cuenta una historia apasionante que habr\u00eda hecho las delicias del mism\u00edsimo Alfred Hitchcock. Todo comienza con un ling\u00fcista llamado Tirso que asesora a la Polic\u00eda en casos puntuales. Por ejemplo, cuando una mujer aparece en mitad del desierto del Sahara y resulta ser una ni\u00f1a madrile\u00f1a desaparecida tres d\u00e9cadas atr\u00e1s. \u00bfQu\u00e9 hac\u00eda all\u00ed? \u00bfD\u00f3nde pas\u00f3 esos a\u00f1os? \u00bfQu\u00e9 le pas\u00f3 en su momento? Alba apenas puede mascullar un pu\u00f1ado de palabras, lo que complica el trabajo de un Tirso que, perseverante, no cejar\u00e1 en su empe\u00f1o de querer saber. Saber, por ejemplo, por qu\u00e9 el padre de Alba, un cient\u00edfico adscrito a la JEN, la Junta de Energ\u00eda Nuclear, se suicid\u00f3 apenas diez d\u00edas despu\u00e9s de la desaparici\u00f3n de su hija.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/cementerio-de-secretos-el-linguista-que-sabia-demasiado\/cementerio-de-secretos-esto-que-es\/\" rel=\"attachment wp-att-32920\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32920\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/Cementerio-de-secretos-esto-que-es-300x186.png\" alt=\"\" width=\"300\" height=\"186\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/Cementerio-de-secretos-esto-que-es-300x186.png 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/Cementerio-de-secretos-esto-que-es-644x398.png 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/Cementerio-de-secretos-esto-que-es-768x475.png 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/Cementerio-de-secretos-esto-que-es.png 970w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>\u00bfQu\u00e9 hay de Hitchcock en esa relaci\u00f3n de hechos? As\u00ed contado, poco. Pero cr\u00e9anme: \u2018Cementerio de secretos\u2019, publicada por Plaza &amp; Jan\u00e9s, tiene mucho de \u2018El hombre que sab\u00eda demasiado\u2019 y \u2018Con la muerte en los talones\u2019. Para empezar, un ciudadano normal y corriente enfrentado a un enigma que tampoco parece para tanto. Al principio. Un tipo curioso e inquisitivo que empieza a hacer preguntas, a hablar con gente y a sacar conclusiones, algo que pondr\u00e1 nerviosos a seg\u00fan qu\u00e9 elementos del Gobierno, que no tardar\u00e1n en mover ficha.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/cementerio-de-secretos-el-linguista-que-sabia-demasiado\/los-enciclopedistas-en-granada\/\" rel=\"attachment wp-att-32921\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32921\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/Los-enciclopedistas-en-Granada-300x185.jpeg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/Los-enciclopedistas-en-Granada-300x185.jpeg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/Los-enciclopedistas-en-Granada.jpeg 623w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>\u00bfSobre qu\u00e9 pregunta Tirso? Les respondo con otra pregunta: \u00bfse acuerdan ustedes de Fraga ba\u00f1\u00e1ndose en la playa de Palomares? Pues aten cabos. Y no les cuento m\u00e1s. Solo les dir\u00e9 que hay MacGuffin, secretos ocultos a punto (o no) de ser desvelados, varios secundarios de lo m\u00e1s atractivo, un gran villano, persecuciones y acci\u00f3n. Mucha acci\u00f3n.<\/p>\n<p>El autor de la fascinante y adictiva \u2018Cementerio de secretos\u2019 es Jos\u00e9 Antonio P\u00e9rez Ledo, un tipo proteico que lo mismo escribe novelas estupendas que guiones para series de televisi\u00f3n como \u2018Caminantes\u2019 o para c\u00f3mics como \u2018Los enciclopedistas\u2019. <a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/tag\/jesus-lens-rincon-oscuro\/\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a> hice un amplio recorrido por su trayectoria. Es creador del programa de divulgaci\u00f3n cient\u00edfica \u2018\u00d3rbita Laika\u2019, en RTVE. Y sus p\u00f3dcats. Ojo a ese prodigio. Si salen ustedes a caminar, escuch\u00e1ndolos, batir\u00e1n su r\u00e9cord de kil\u00f3metros enlazando un cap\u00edtulo tras otro de \u2018El gran apag\u00f3n\u2019 y \u2018Guerra 3\u2019. Lo tuvimos hace unos a\u00f1os en Granada Noir y nos cont\u00f3 <a href=\"https:\/\/www.ideal.es\/culturas\/jose-perez-ledo-guerra-razon-programas-la2-20191005164920-nt.html\" target=\"_blank\" rel=\"noopener\">ESTO<\/a>. <span class=\"Apple-converted-space\">\u00a0\u00a1Grande Jos\u00e9 Enrique Cabrero!<\/span><\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/cementerio-de-secretos-el-linguista-que-sabia-demasiado\/los-enciclopedistas-2\/\" rel=\"attachment wp-att-32922\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32922\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/Los-enciclopedistas-300x180.jpeg\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/Los-enciclopedistas-300x180.jpeg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/Los-enciclopedistas-644x386.jpeg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/Los-enciclopedistas-768x461.jpeg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/Los-enciclopedistas.jpeg 850w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>De \u2018La firma de Dios\u2019 a\u00fan no les puedo decir nada, que lo guardo como oro en pa\u00f1o, como antidepresivo para un hipot\u00e9tico momento de baj\u00f3n, como un gran reserva para descorchar en un momento especial.<span class=\"Apple-converted-space\">\u00a0 \u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/cementerio-de-secretos-el-linguista-que-sabia-demasiado\/la-firma-de-dios\/\" rel=\"attachment wp-att-32923\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32923\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/La-firma-de-Dios--300x300.jpeg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/La-firma-de-Dios--300x300.jpeg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/La-firma-de-Dios--150x150.jpeg 150w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/04\/La-firma-de-Dios-.jpeg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Terminamos con el arranque de la novela. Dice as\u00ed. \u201cBajo cierta calle de Madrid existe un lugar donde yace nuestro pasado oculto. Kil\u00f3metros de galer\u00edas subterr\u00e1neas cuyo acceso es custodiado todos los minutos del d\u00eda, todos los d\u00edas del a\u00f1o\u2026 En esos misteriosos corredores se amontonan cajas de cart\u00f3n repletas de legajos. Toneladas de informes, memorias y dosieres. Papeles amarilleados por el tiempo y tinta enmudecida por la ley. D\u00e9cadas de documentos confidenciales a los que pocos ojos tienen acceso. Es el cementerio de secretos oficiales de nuestro pa\u00eds. Esta es la historia de uno de esos secretos\u201d. No dejen pasar la ocasi\u00f3n de desvelarlo. No se arrepentir\u00e1n.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32647 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/11\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9jenme que les cuente un secreto: se acaba de publicar una de Hitchcock en Espa\u00f1a. Una novela, quiero decir. La ha escrito esa bestia parda que responde al nombre de Jos\u00e9 Antonio P\u00e9rez Ledo, se titula \u2018Cementerio de secretos\u2019 y ya tardan en ir a su librer\u00eda de cabecera para hacerse con ella. Si la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,11774],"tags":[21415,21412,21411,18172,11145,16586,17479,21416,21413,18176,21414],"class_list":["post-32918","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","category-rincon-oscuro","tag-bomba-nuclear-espana","tag-caminantes","tag-cementerio-de-secretos","tag-el-gran-apagon","tag-granada-noir-2","tag-jose-antonio-perez-ledo","tag-los-enciclopedistas","tag-novela-hitchcock","tag-perez-ledo","tag-podium-podcast","tag-proyecto-islero"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=32918"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32918\/revisions"}],"predecessor-version":[{"id":32925,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32918\/revisions\/32925"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=32918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=32918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=32918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}