{"id":32704,"date":"2022-12-14T00:02:32","date_gmt":"2022-12-13T23:02:32","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=32704"},"modified":"2022-12-13T14:38:20","modified_gmt":"2022-12-13T13:38:20","slug":"para-espolear-la-curiosidad","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/para-espolear-la-curiosidad\/","title":{"rendered":"Para espolear la curiosidad"},"content":{"rendered":"<p>Ayer por la ma\u00f1ana estuve en el Caixa F\u00f3rum. Vestido con un ch\u00e1ndal viejo y calzado con pantuflas, \u2018desarreglao\u2019 a la par que informal, me asom\u00e9 a <a href=\"http:\/\/www.caixaforumplus.org\">www.caixaforumplus.org<\/a> y me pas\u00e9 el resto de la ma\u00f1ana bicheando y curioseando entre su ingente cantidad de contenidos.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=32705\" rel=\"attachment wp-att-32705\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32705\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/12\/Caixa-Forum-Plus-218x300.jpg\" alt=\"\" width=\"218\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/12\/Caixa-Forum-Plus-218x300.jpg 218w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/12\/Caixa-Forum-Plus-644x887.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/12\/Caixa-Forum-Plus-768x1057.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/12\/Caixa-Forum-Plus-1116x1536.jpg 1116w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/12\/Caixa-Forum-Plus.jpg 1170w\" sizes=\"auto, (max-width: 218px) 100vw, 218px\" \/><\/a><\/p>\n<p>Tras cuatro a\u00f1os de desarrollo t\u00e9cnico, la plataforma de divulgaci\u00f3n cultural y cient\u00edfica de Fundaci\u00f3n La Caixa ha nacido con 1000 piezas de contenido que conforman 600 horas de visualizaci\u00f3n y escucha. Hay piezas que te llevan dos minutos nada m\u00e1s y entrevistas en profundidad de hasta diez horas. Ojocuidao ah\u00ed.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Les confieso que llevaba meses esperando este momento. En concreto, desde que Clara Pe\u00f1alver me citara una fr\u00eda ma\u00f1ana de enero para hacerme una de esas propuestas que no se pueden rechazar: la creaci\u00f3n de un podcast sobre sobre el g\u00e9nero negro para una plataforma de contenidos audiovisuales que estaba impulsando Fundaci\u00f3n La Caixa.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=32706\" rel=\"attachment wp-att-32706\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32706\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/12\/Caixa-Forum-Plus-Alhambra-271x300.jpg\" alt=\"\" width=\"271\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/12\/Caixa-Forum-Plus-Alhambra-271x300.jpg 271w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/12\/Caixa-Forum-Plus-Alhambra-644x713.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/12\/Caixa-Forum-Plus-Alhambra-768x850.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/12\/Caixa-Forum-Plus-Alhambra.jpg 1170w\" sizes=\"auto, (max-width: 271px) 100vw, 271px\" \/><\/a><\/p>\n<p>Ella estaba ya trabajando ya en uno sobre m\u00fasica y pensamos que una producci\u00f3n transversal sobre iconos del noir que tocara diferentes aspectos del g\u00e9nero, combinando literatura, cine, m\u00fasica, c\u00f3mic, ciencia y gastronom\u00eda; pod\u00eda encajar en la filosof\u00eda de Caixa Forum Plus. Con su toque de intriga, claro. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Estuvimos trabajando toda la primavera y el verano en ello. A\u00fan no est\u00e1 disponible en la plataforma, que ir\u00e1 estrenando contenido nuevo cada semana, pero les confieso que tengo las pulsaciones disparadas a la vista de la salvajada de programaci\u00f3n y la impresionante n\u00f3mina de nombres que hay ah\u00ed dentro.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Me di de alta mientras escuchaba a Elisa Dur\u00e1n explicar la filosof\u00eda con que nace Caixa F\u00f3rum Plus y empec\u00e9 a navegar mientras escuchaba el sugerente Canto de la Sibilia de Mar\u00eda Arnal, acompa\u00f1ada de un coro de voces creado por una inteligencia artificial, fusionando una m\u00fasica ancestral, m\u00edtica y tel\u00farica con las tecnolog\u00edas m\u00e1s vanguardistas.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Hablamos de una ventana abierta a la difusi\u00f3n cultural y cient\u00edfica que busca espolear la curiosidad, como dijo uno de los invitados a la presentaci\u00f3n. Por ejemplo, lo que se oculta tras algunas de las fotos m\u00e1s ic\u00f3nicas de la historia de la ciencia, del famoso rostro de Albert Einstein a la huella del hombre sobre la superficie de la luna.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=32707\" rel=\"attachment wp-att-32707\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32707\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/12\/Caixa-Forum-Plus-Ecos-168x300.jpg\" alt=\"\" width=\"168\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/12\/Caixa-Forum-Plus-Ecos-168x300.jpg 168w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/12\/Caixa-Forum-Plus-Ecos.jpg 628w\" sizes=\"auto, (max-width: 168px) 100vw, 168px\" \/><\/a><\/p>\n<p>Lo primero que voy a escuchar son los \u2018Ecos\u2019 de Jorge Carri\u00f3n y, por supuesto, me ir\u00e9 con la m\u00fasica a otra parte para visitar \u2018La Alhambra sonora\u2019 que, efectivamente, los viajes son fuente de inspiraci\u00f3n. Les dejo, que 600 horas de contenido son mucha tela y se me est\u00e1 haciendo tarde.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32647 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/11\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer por la ma\u00f1ana estuve en el Caixa F\u00f3rum. Vestido con un ch\u00e1ndal viejo y calzado con pantuflas, \u2018desarreglao\u2019 a la par que informal, me asom\u00e9 a www.caixaforumplus.org y me pas\u00e9 el resto de la ma\u00f1ana bicheando y curioseando entre su ingente cantidad de contenidos.\u00a0 Tras cuatro a\u00f1os de desarrollo t\u00e9cnico, la plataforma de divulgaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,6],"tags":[19929,21282,9253,21281,21284,20049,21283],"class_list":["post-32704","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","category-opinion","tag-caixa-forum","tag-caixa-forum-plus","tag-clara-penalver","tag-ecos-jorge-carrion","tag-elisa-duran","tag-jorge-carrion","tag-maria-arnal"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=32704"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32704\/revisions"}],"predecessor-version":[{"id":32708,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32704\/revisions\/32708"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=32704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=32704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=32704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}