{"id":32428,"date":"2022-08-24T00:07:18","date_gmt":"2022-08-23T23:07:18","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=32428"},"modified":"2022-08-23T13:01:19","modified_gmt":"2022-08-23T12:01:19","slug":"menudos-banos-arabes-en-jaen","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/menudos-banos-arabes-en-jaen\/","title":{"rendered":"\u00a1Menudos ba\u00f1os \u00e1rabes, en Ja\u00e9n!"},"content":{"rendered":"<p>Volvamos a Ja\u00e9n en este paseo veraniego por Andaluc\u00eda Oriental. Tras caminar por Almer\u00eda, esa ciudad tan deliciosamente paseable, nos damos otro garbeo por las calles jienenses en busca de sus sobresalientes ba\u00f1os \u00e1rabes. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=32430\" rel=\"attachment wp-att-32430\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32430\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-1-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-1-644x483.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-1-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-1-1536x1152.jpg 1536w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-1.jpg 2016w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Hace unos a\u00f1os, El Legado Andalus\u00ed organiz\u00f3 una interesante exposici\u00f3n dedicada a \u2018Los Ba\u00f1os en al-Andalus\u2019. Tuve la suerte de hacer una visita guiada con las comisarias de la muestra, Carmen Pozuelo e Inmaculada Cort\u00e9s. Me dec\u00edan que Granada es la provincia espa\u00f1ola que conserva m\u00e1s hammam, m\u00e1s ba\u00f1os p\u00fablicos de origen andalus\u00ed.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Los ba\u00f1os eran los edificios m\u00e1s populares y comunes en la vida cotidiana de las ciudades de al-Andalus. As\u00ed lo explica la web del Legado: \u201cAll\u00ed donde se establec\u00eda un nuevo asentamiento o n\u00facleo urbano, lo primero que se constru\u00eda era un\u00a0<i>hamman<\/i>. Tal era su papel en la vida cotidiana, que la importancia de las ciudades se med\u00eda por el n\u00famero de ba\u00f1os que ten\u00eda. Es el ejemplo de la C\u00f3rdoba califal, que en el siglo X contaba, seg\u00fan las cr\u00f3nicas, con alrededor de 300. Eran construidos con frecuencia junto a las arterias principales, puertas y mezquitas. Su uso era tan extendido que se mantuvieron hasta el siglo XVI, y fueron incluidos en conjuntos arquitect\u00f3nicos en \u00e9poca cristiana\u201d.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=32431\" rel=\"attachment wp-att-32431\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32431\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-2-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-2-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-2-644x859.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-2-768x1024.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-2-1152x1536.jpg 1152w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-2-rotated.jpg 1512w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>Y es que, como Inmaculada y Carmen me contaban, \u201cpocos lugares de nuestro pasado son tan evocadores como los hammam: la luz, el ambiente, el murmullo que en ellos se respira han atra\u00eddo y a\u00fan atraen nuestra mirada\u201d. Y tambi\u00e9n recuerdo su consejo: no dejes de ir a ver los de Ja\u00e9n, que son soberbios.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>\u00a1Qu\u00e9 raz\u00f3n ten\u00edan! Miren que a m\u00ed me gusta el Ba\u00f1uelo, uno de los monumentos granadinos que no me canso de recomendar a quienes viajan a Granada, junto al Corral del Carb\u00f3n y la Madraza. Pero los ba\u00f1os \u00e1rabes de Ja\u00e9n est\u00e1n en otra dimensi\u00f3n. Tanto por su amplitud como por su excepcional nivel de conservaci\u00f3n.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Se hace extra\u00f1o su emplazamiento, ubicados bajo el Palacio de Villadompardo. Con una extensi\u00f3n de 450 metros cuadrados, son de los m\u00e1s grandes de los conservados en Espa\u00f1a y, aunque detalles decorativos almohades hacen pensar que pudieron ser restaurados all\u00e1 por el siglo XII, su origen m\u00e1s lejano data de los tiempos de los romanos, que debieron ser unas importantes termas en la antigua Auringis.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=32432\" rel=\"attachment wp-att-32432\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32432\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-3-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-3-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-3-644x859.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-3-768x1024.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-3-1152x1536.jpg 1152w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Banos-Arabes-Jaen-3-rotated.jpg 1512w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>Es curiosa la historia de los ba\u00f1os. Tras la conquista de Ja\u00e9n por Fernando III El Santo, siguieron en uso, aunque en los siglos XIV y XV cambi\u00f3 su uso y pasaron a ser unas tener\u00edas. Y as\u00ed llegamos al siglo XVI, cuando don Fernando de Torres y Portugal, Conde de Villardompardo y Virrey del Per\u00fa, decidi\u00f3 construir su residencia justo sobre los ba\u00f1os, literalmente hablando. Los llen\u00f3 de cascotes y quedaron sepultados entre los cimientos y los s\u00f3tanos del palacio, por lo que se les perdi\u00f3 la pista hasta que, a comienzos del siglo XX, el edificio pas\u00f3 a engrosar el acervo inmobiliario de la Diputaci\u00f3n de Ja\u00e9n, volviendo a salir a la luz.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32139 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/07\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Volvamos a Ja\u00e9n en este paseo veraniego por Andaluc\u00eda Oriental. Tras caminar por Almer\u00eda, esa ciudad tan deliciosamente paseable, nos damos otro garbeo por las calles jienenses en busca de sus sobresalientes ba\u00f1os \u00e1rabes. \u00a0 Hace unos a\u00f1os, El Legado Andalus\u00ed organiz\u00f3 una interesante exposici\u00f3n dedicada a \u2018Los Ba\u00f1os en al-Andalus\u2019. Tuve la suerte de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[24,20944],"tags":[18640,21121],"class_list":["post-32428","post","type-post","status-publish","format-standard","hentry","category-viajes","category-vuelta-y-vuelta","tag-banos-arabes","tag-banos-arabes-jaen"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=32428"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32428\/revisions"}],"predecessor-version":[{"id":32434,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32428\/revisions\/32434"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=32428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=32428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=32428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}