{"id":32389,"date":"2022-08-20T16:16:48","date_gmt":"2022-08-20T15:16:48","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=32389"},"modified":"2022-08-20T16:16:48","modified_gmt":"2022-08-20T15:16:48","slug":"la-espada-y-la-cruz","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-espada-y-la-cruz\/","title":{"rendered":"La espada y la cruz"},"content":{"rendered":"<p>Habl\u00e1bamos ayer de la catedral de Ja\u00e9n. En realidad, la primera vez que sus torres gemelas te saltan a la vista es cuando llegas en coche desde Granada. Y por encima de ellas, el castillo de Santa Catalina y la enorme Cruz Blanca desde la que disfrutar de una perspectiva a\u00e9rea inconmensurable de la ciudad y sus alrededores. Una vista ic\u00f3nica que, como dice nuestro compa\u00f1ero Jorge Pastor, hay que contemplar al menos una vez en la vida.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/catedral-de-jaen-amor-a-primera-vista\/catedral-de-jaen-vista-aerea\/\" rel=\"attachment wp-att-32385\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32385\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Catedral-de-Jaen-vista-aerea-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Catedral-de-Jaen-vista-aerea-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Catedral-de-Jaen-vista-aerea-644x483.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Catedral-de-Jaen-vista-aerea-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Catedral-de-Jaen-vista-aerea-1536x1152.jpg 1536w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Catedral-de-Jaen-vista-aerea.jpg 2016w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Antes de entrar en la ciudad propiamente dicha, subimos al castillo, que tambi\u00e9n alberga al Parador jienense. A ese lugar le tengo un cari\u00f1o especial, que acogi\u00f3 durante muchos a\u00f1os el acto de entrega de los Premios Literarios Ja\u00e9n de CajaGranada. Y, sin embargo, nunca hab\u00eda visitado el castillo como tal. Las incongruencias de la vida acelerada.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Ya se lo he contado otras veces. Ja\u00e9n es tierra de castillos, fortalezas y torreones. La historia del enriscado castillo de Santa Catalina es buen ejemplo de lo azaroso de la Reconquista. Asentado sobre roca viva, el cerro estuvo habitado desde la Edad del Bronce y los \u00edberos elevaron uno de sus oppidum. De ah\u00ed que los musulmanes aprovecharan para hacerse fuertes all\u00ed arriba desde el siglo VIII hasta 1246, cuando Fernando III, apodado el Santo, consigui\u00f3 doblegar a Al-Ahmar.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-espada-y-la-cruz\/castillo-de-santa-catalina\/\" rel=\"attachment wp-att-32390\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32390\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina--300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina--300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina--644x483.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina--768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina--1536x1152.jpg 1536w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina-.jpg 2016w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>No les cuento m\u00e1s batallitas sobre el castillo de Santa Catalina. Solo recordar, eso s\u00ed, que las tropas de Napole\u00f3n se aposentaron y acomodaron en su interior, donde estuvieron tan a gustito. Lo visitamos el pasado martes, un d\u00eda de viento fresco, afortunadamente. La visita al castillo podr\u00edamos describirla como ruidosa. A la entrada, una m\u00e1quina se encarga de abrir y cerrar el torno, pero falla bastante, por lo que no deja de sonar un inc\u00f3modo pitido.<\/p>\n<p>Y luego, desde mitad del patio y al acercarte a una de las torres, se oye el runr\u00fan incesante de un documental que, en bucle y en alta voz, no s\u00e9 si con prisas pero desde luego sin pausas, cuenta una historieta de guerra, peleas y broncas. O\u00edrse, se oye. Escucharlo, no lo escuchaba nadie. Pero qu\u00e9 ruidazo. En la zona de la prisi\u00f3n, por lo visto, hay un maniqu\u00ed parlante que te cuenta sus desdichas, pero afortunadamente estaba bien calladito.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-espada-y-la-cruz\/castillo-de-santa-catalina-torre\/\" rel=\"attachment wp-att-32391\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32391\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina-Torre-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina-Torre-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina-Torre-644x483.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina-Torre-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina-Torre-1536x1152.jpg 1536w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina-Torre.jpg 2016w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Salimos huyendo de all\u00ed, como si un ej\u00e9rcito enemigo nos acechara el lontananza, y subimos a otro espacio elevado, m\u00e1s alejado, desde el que se divisaban tanto la ciudad como la campi\u00f1a de Ja\u00e9n y algunos de sus picos m\u00e1s conocidos, como Jabalcuz. En otras torres del castillo tambi\u00e9n hay multimedias, audiovisuales, cartelones, pantallas t\u00e1ctiles y otros \u2018adelantos\u2019 t\u00e9cnicos. \u00a1Menos mal que estaban apagados!<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-espada-y-la-cruz\/castillo-de-santa-catalina-exterior\/\" rel=\"attachment wp-att-32392\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32392\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina-Exterior-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina-Exterior-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina-Exterior-644x859.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina-Exterior-768x1024.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina-Exterior-1152x1536.jpg 1152w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Castillo-de-Santa-Catalina-Exterior-rotated.jpg 1512w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>Siempre es un gusto visitar un castillo. M\u00e1s, si tiene la historia y las vistas del de Santa Catalina. Ech\u00e9 de menos, eso s\u00ed, una sencilla audiogu\u00eda que ponga en situaci\u00f3n a quien est\u00e9 interesado, en vez de tanto barullo. Rematamos la visita tomando una Milnoh en el Parador, que es parte del propio castillo y donde se est\u00e1 en la gloria.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32139 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/07\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Habl\u00e1bamos ayer de la catedral de Ja\u00e9n. En realidad, la primera vez que sus torres gemelas te saltan a la vista es cuando llegas en coche desde Granada. Y por encima de ellas, el castillo de Santa Catalina y la enorme Cruz Blanca desde la que disfrutar de una perspectiva a\u00e9rea inconmensurable de la ciudad [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[24,20944],"tags":[21099,21097,21096,6748,2373,21098],"class_list":["post-32389","post","type-post","status-publish","format-standard","hentry","category-viajes","category-vuelta-y-vuelta","tag-al-ahmar","tag-castillo-de-jaen","tag-castillo-de-santa-catalina","tag-jaen","tag-milno","tag-parador-de-jaen"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=32389"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32389\/revisions"}],"predecessor-version":[{"id":32394,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32389\/revisions\/32394"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=32389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=32389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=32389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}