{"id":32328,"date":"2022-08-12T00:03:22","date_gmt":"2022-08-11T23:03:22","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=32328"},"modified":"2022-08-11T12:39:54","modified_gmt":"2022-08-11T11:39:54","slug":"ya-tenemos-futbol-de-verdad","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/ya-tenemos-futbol-de-verdad\/","title":{"rendered":"Ya tenemos f\u00fatbol de verdad"},"content":{"rendered":"<p>El mi\u00e9rcoles, como ya pod\u00eda salir y para evitar el riesgo de sucumbir al s\u00edndrome de la caba\u00f1a, nos fuimos al cine. Estuvimos viendo la pel\u00edcula de Brad Pitt y al terminar, la plaza central del centro comercial estaba de bote en bote, con decenas de personas mirando la gran pantalla de televisi\u00f3n que preside el espacio.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=32329\" rel=\"attachment wp-att-32329\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32329\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Bullet-Train-240x300.jpg\" alt=\"\" width=\"240\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Bullet-Train-240x300.jpg 240w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Bullet-Train-644x805.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Bullet-Train-768x960.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Bullet-Train.jpg 1080w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a><\/p>\n<p>Hab\u00eda f\u00fatbol, claro. Di por supuesto que ser\u00edan im\u00e1genes random, repetici\u00f3n de alg\u00fan partido de la temporada pasada o suma de jugadas espectaculares en bucle.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Nos sentamos lejos, que quer\u00edamos hincarle el diente a las espectaculares hamburguesas de Sancho Casual Food, mis favoritas de Granada. Me ped\u00ed mi primera cerveza en diez d\u00edas, brindamos y empezamos a comentar la pel\u00edcula: qu\u00e9 risas, qu\u00e9 descojono, qu\u00e9 barbaridad. Que si tu eres Diesel y que si a ti te falta un poco\/mucho de desarrollo personal, como persona y tambi\u00e9n como ser humano.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Y de repente: \u00a1GOOOOOOOOOOOL!<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Lo primero que hice fue levantar los brazos y sumarme al alborozo. Si tanta gente gritaba tan alto y con tanto entusiasmo es que algo bueno estaba pasando. Achin\u00e9 los ojos para tratar de ver la pantalla y entonces ca\u00ed en la cuenta: el Real Madrid se jugaba la Supercopa de Europa.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=32330\" rel=\"attachment wp-att-32330\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32330\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Supercopa-2022-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Supercopa-2022-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Supercopa-2022-644x362.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Supercopa-2022-768x432.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Supercopa-2022-1536x864.jpg 1536w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Supercopa-2022.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Y ahora, el viejunismo. \u00bfD\u00f3nde han quedado aquellas largas y achicharrantes pretemporadas? \u00bfY los torneos de verano? El deporte profesional, como El Corte Ingl\u00e9s, marcaba nuestro calendario natural. El verano, tiempo de fabulaci\u00f3n y fantas\u00eda, acog\u00eda aquellos m\u00edticos Ram\u00f3n de Carranza, Joan Gamper, Teresa Herrera o Santiago Bernab\u00e9u. Se viv\u00edan como si su resultado importara y serv\u00edan para hacer mil y una c\u00e1balas sobre los nuevos equipos.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Al final de temporada, a ning\u00fan entrenador o presidente se le ocurr\u00eda decir que el a\u00f1o hab\u00eda sido bueno porque hab\u00eda ganado alguno de esos torneos de verano, pero en la laxitud de agosto, tiempo suspendido entre serpientes de verano y atascos en los accesos a la playa, le pon\u00edan su punto de mordiente a las ardientes noches de verano. El comienzo de la Liga llegaba en septiembre, con la compra de los libros de texto y el pago de las matr\u00edculas. Todo ten\u00eda sentido, un orden l\u00f3gico y cabal.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=32331\" rel=\"attachment wp-att-32331\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-32331\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Teresa-Herrera-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Teresa-Herrera-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Teresa-Herrera-644x362.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Teresa-Herrera-768x432.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/08\/Teresa-Herrera.jpg 880w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Sigamos con el \u00f1a\u00f1a\u00f1\u00e1. Que hoy arranque la Liga, la de verdad, me parece un desprop\u00f3sito y un atentado contra el orden natural de las cosas. \u00a1Si a\u00fan no ha sido la Asunci\u00f3n! Quiero creer que ser\u00e1 cosa del Mundial del Desierto, esa otra aberraci\u00f3n sin pies ni cabeza, pero sigue siendo absurdo.<\/p>\n<p>Una cosa de bueno tiene la vuelta temprana del f\u00fatbol, eso s\u00ed: las redes sociales se llenan de comentarios sobre Benzema, Lewandowski y Callej\u00f3n y sepultan debates tan cansinos como el de la espada de Bol\u00edvar, la en\u00e9sima rega\u00f1ina de Pablo Iglesias, las incongruencias de Vox, las imposiciones de S\u00e1nchez, el s\u00ed-pero-no de Feij\u00f3o o las risas de los indepes en la piscina. Que el verano tambi\u00e9n es para descansar de ellos. Sus vacaciones son las nuestras. \u00a1D\u00e9jenles en paz! Por nuestra salud mental.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32139 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/07\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mi\u00e9rcoles, como ya pod\u00eda salir y para evitar el riesgo de sucumbir al s\u00edndrome de la caba\u00f1a, nos fuimos al cine. Estuvimos viendo la pel\u00edcula de Brad Pitt y al terminar, la plaza central del centro comercial estaba de bote en bote, con decenas de personas mirando la gran pantalla de televisi\u00f3n que preside [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8,20944],"tags":[21051,21053,21055,21054,21049,21050,21052],"class_list":["post-32328","post","type-post","status-publish","format-standard","hentry","category-deportes","category-vuelta-y-vuelta","tag-bullet-train","tag-empieza-liga","tag-joder-con-las-bullas","tag-que-prisas-cono","tag-teresa-herrera","tag-torneos-de-verano","tag-vuelve-la-liga"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=32328"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32328\/revisions"}],"predecessor-version":[{"id":32332,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32328\/revisions\/32332"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=32328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=32328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=32328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}