{"id":32043,"date":"2022-05-19T21:34:09","date_gmt":"2022-05-19T20:34:09","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=32043"},"modified":"2022-05-23T13:22:37","modified_gmt":"2022-05-23T12:22:37","slug":"el-im-pulso-de-la-ciencia","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-im-pulso-de-la-ciencia\/","title":{"rendered":"El im-pulso de la ciencia"},"content":{"rendered":"<p>El pasado domingo, en el seno de la Feria del Libro, se estren\u00f3 \u2018Territorio Gravedad\u2019, una serie cient\u00edfica creada por el Instituto de Astrof\u00edsica de Andaluc\u00eda de una calidad apabullante. Ni que decir tiene que no comprend\u00ed algunos conceptos sobre la Teor\u00eda de la Relatividad, pero la serie es tan potente que sal\u00ed enfervorecido, presto y dispuesto a ampliar mis conocimientos en la materia. Lo que tampoco tiene m\u00e9rito alguno, dado lo exiguos que son.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<figure id=\"attachment_32044\" aria-describedby=\"caption-attachment-32044\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-im-pulso-de-la-ciencia\/el-pulso-de-la-ciencia\/\" rel=\"attachment wp-att-32044\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-32044\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/El-pulso-de-la-ciencia-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/El-pulso-de-la-ciencia-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/El-pulso-de-la-ciencia-644x430.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/El-pulso-de-la-ciencia-768x512.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/El-pulso-de-la-ciencia-1536x1025.jpg 1536w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/El-pulso-de-la-ciencia.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-32044\" class=\"wp-caption-text\">Pulso entre letras y ciencias. Foto Javier Mart\u00edn.<\/figcaption><\/figure>\n<p>Lo he contado muchas veces. Entre los d\u00edas m\u00e1s felices de mi vida, aquel de segundo de BUP, cuando aprob\u00e9 Matem\u00e1ticas y F\u00edsica y Qu\u00edmica. Yo era de letras puras, como dec\u00edamos entonces, y hab\u00eda cruzado mi Rubic\u00f3n particular. \u00a1Au revoir, f\u00f3rmulas compuestas! \u00a1Bye bye, paralelas y derivadas! \u00a1Sayonara, bencenos! Renegu\u00e9 tanto de n\u00fameros y cifras que, para mi verg\u00fcenza, cuando hab\u00eda que pagar las ca\u00f1as, me escabull\u00eda con eso de \u201chaz t\u00fa las cuentas, que yo soy de letras\u201d.<\/p>\n<p>Lo hablaba con Antxon Alberdi, tras el memorable concierto de Roc\u00edo M\u00e1rquez y Bronquio frente a la Alhambra. El director del IAA sonri\u00f3 al escuchar un poema de Carmen Camacho convertido en letra de una canci\u00f3n: \u201cToda ciencia trascendiendo \/ que uno m\u00e1s uno es uno \/ desde que te estoy queriendo\u201d. Hay que trascender la vieja separaci\u00f3n entre Ciencias y Letras y poner fin al pulso entre la cultura human\u00edstica y la cient\u00edfica. Debemos abogar por esa tercera cultura que las a\u00fana, integra y fusiona. En ese sentido, la labor de la Unidad de Cultura Cient\u00edfica del IAA que capitanea Emilio Garc\u00eda es impagable.<\/p>\n<figure id=\"attachment_32045\" aria-describedby=\"caption-attachment-32045\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-im-pulso-de-la-ciencia\/el-impuslso-de-la-ciencia\/\" rel=\"attachment wp-att-32045\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-32045\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/El-impuslso-de-la-ciencia-300x195.jpg\" alt=\"\" width=\"300\" height=\"195\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/El-impuslso-de-la-ciencia-300x195.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/El-impuslso-de-la-ciencia-644x418.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/El-impuslso-de-la-ciencia-768x499.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/El-impuslso-de-la-ciencia-1536x998.jpg 1536w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/El-impuslso-de-la-ciencia.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-32045\" class=\"wp-caption-text\">El impulso de la ciencia. Foto Javier Mart\u00edn<\/figcaption><\/figure>\n<p><a href=\"https:\/\/gravitefestival.com\" target=\"_blank\" rel=\"noopener\">El festival Gravite<\/a> patrocinado por CaixaBank naci\u00f3 de esa filosof\u00eda. Nos anim\u00f3 mucho que la primera fotograf\u00eda de un agujero negro supermasivo, en cuya consecuci\u00f3n tuvo tanta importancia el trabajo de nuestro IAA, est\u00e9 colgada en una de las salas del MOMA. O aquella conversaci\u00f3n con Isabel M\u00e1rquez, la vicedirectora del IAA, en la presentaci\u00f3n de \u2018Hola Tierra\u2019, el disco gal\u00e1ctico de Antonio Arias.<\/p>\n<figure id=\"attachment_32046\" aria-describedby=\"caption-attachment-32046\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-im-pulso-de-la-ciencia\/antxon-alberdi-jesus-lens\/\" rel=\"attachment wp-att-32046\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-32046\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/Antxon-Alberdi-Jesus-Lens-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/Antxon-Alberdi-Jesus-Lens-300x192.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/Antxon-Alberdi-Jesus-Lens-644x412.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/Antxon-Alberdi-Jesus-Lens-768x491.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/Antxon-Alberdi-Jesus-Lens-1536x982.jpg 1536w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/05\/Antxon-Alberdi-Jesus-Lens.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-32046\" class=\"wp-caption-text\">La amistad entre ciencias y letras. Jes\u00fas Lens y Antxon Alberdi, director del Instituto de Astrof\u00edsica de Andaluc\u00eda. Foto: Javier Mart\u00edn.<\/figcaption><\/figure>\n<p>Este a\u00f1o, el Premio Viajero en el Tiempo de Gravite es para el IAA. Lo entregamos en pr\u00f3ximo lunes en el Teatro CajaGranada, a las 20 horas, y tendremos la suerte de que Antxon nos hable del \u00faltimo hallazgo en que ha participado la instituci\u00f3n: la fotograf\u00eda del centro de nuestra galaxia que abri\u00f3 las portadas de los peri\u00f3dicos hace unos d\u00edas. El aut\u00e9ntico impulso de la ciencia.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31741 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/11\/00000-Twitter-1.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado domingo, en el seno de la Feria del Libro, se estren\u00f3 \u2018Territorio Gravedad\u2019, una serie cient\u00edfica creada por el Instituto de Astrof\u00edsica de Andaluc\u00eda de una calidad apabullante. Ni que decir tiene que no comprend\u00ed algunos conceptos sobre la Teor\u00eda de la Relatividad, pero la serie es tan potente que sal\u00ed enfervorecido, presto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16444,6],"tags":[20281,20911,7391,20910],"class_list":["post-32043","post","type-post","status-publish","format-standard","hentry","category-gravite","category-opinion","tag-antxon-alberdi","tag-caixabank","tag-ciencias-y-letras","tag-instituto-de-astrofisico-de-andalucia"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=32043"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32043\/revisions"}],"predecessor-version":[{"id":32049,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32043\/revisions\/32049"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=32043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=32043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=32043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}