{"id":31964,"date":"2022-03-22T18:02:05","date_gmt":"2022-03-22T17:02:05","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=31964"},"modified":"2022-03-22T18:02:05","modified_gmt":"2022-03-22T17:02:05","slug":"atractiva-y-peligrosa-tierra-de-furtivos","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/atractiva-y-peligrosa-tierra-de-furtivos\/","title":{"rendered":"Atractiva y peligrosa &#8216;Tierra de furtivos&#8217;"},"content":{"rendered":"<p>He disfrutado de todas y cada una de sus adictivas 400 p\u00e1ginas. Me ha encantado y se la recomiendo a todo el que me pregunta qu\u00e9 leer. Hablamos de \u2018Tierra de furtivos\u2019, un novel\u00f3n de \u00d3scar Beltr\u00e1n de Ot\u00e1lora publicado por Destino y protagonizado por tres personajes diferentes y contradictorios, todos muy bien construidos.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/atractiva-y-peligrosa-tierra-de-furtivos\/tierra-de-furtivos-2\/\" rel=\"attachment wp-att-31965\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-31965\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/03\/Tierra-de-furtivos-1-176x300.jpg\" alt=\"\" width=\"176\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/03\/Tierra-de-furtivos-1-176x300.jpg 176w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/03\/Tierra-de-furtivos-1.jpg 250w\" sizes=\"auto, (max-width: 176px) 100vw, 176px\" \/><\/a><\/p>\n<p>Me pas\u00f3 una cosa curiosa cuando vi el nombre del autor en la igualmente atractiva y sugerente portada del libro, con un coche ardiendo y el humo anaranjado difumin\u00e1ndose sobre un fondo negro. \u00d3scar Beltr\u00e1n de Ot\u00e1lora. Me sonaba mucho, pero no lo ubicaba el universo patrio de la literatura negro-criminal.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Fue leyendo la secci\u00f3n de Opini\u00f3n de IDEAL que ca\u00ed en la cuenta. Ten\u00eda que ser el mismo \u00d3scar B. de Ot\u00e1lora que firma unas piezas imprescindibles del peri\u00f3dico, tan chiquitas como potentes, tituladas \u2018Sociedad de la desinformaci\u00f3n\u2019, en las que habla de fake news, redes sociales o, como la que tengo enfrente justo ahora, los \u2018influencers\u2019 rusos del terror que hac\u00edan apolog\u00eda de la violencia a trav\u00e9s de sus v\u00eddeos y allanaron el camino a la guerra, propiciando un caldo de cultivo favorable a la putinesca invasi\u00f3n.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/atractiva-y-peligrosa-tierra-de-furtivos\/oscar-beltran-de-otalora\/\" rel=\"attachment wp-att-31966\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-31966\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/03\/Oscar-Beltran-de-Otalora-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/03\/Oscar-Beltran-de-Otalora-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/03\/Oscar-Beltran-de-Otalora-644x362.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/03\/Oscar-Beltran-de-Otalora-768x432.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/03\/Oscar-Beltran-de-Otalora.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Nacido en Vitoria en 1967 y periodista de El Correo, \u201cen los a\u00f1os noventa empez\u00f3 a trabajar en la secci\u00f3n de pol\u00edtica del diario bilba\u00edno, en la que se dedic\u00f3 en exclusiva a informar sobre terrorismo, tanto el de ETA como el de los grupos yihadistas\u201d, se puede leer en la solapa del libro. Otro dato biogr\u00e1fico-profesional, relevante para el contenido de la novela: \u201cEn 2008 fue premiado por la Fundaci\u00f3n V\u00edctimas del Terrorismo por su informaci\u00f3n del atentado que ese a\u00f1o arras\u00f3 el cuartel de la Guardia Civil de Legutio (\u00c1lava), en el que falleci\u00f3 el agente Jos\u00e9 Manuel Pi\u00f1uel\u201d.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Volvamos a la portada de la novela, una de las mejores que me he echado a la cara estos meses. \u00bfQu\u00e9 le sugiere? Efectivamente. Podr\u00eda ser la explosi\u00f3n de un coche bomba. Pero no. Es un coche ardiendo. Y es que as\u00ed arranca \u2018Tierra de furtivos\u2019. Con la quema de un coche.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/atractiva-y-peligrosa-tierra-de-furtivos\/tierra-de-furtivos-detalle\/\" rel=\"attachment wp-att-31967\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-31967\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/03\/Tierra-de-furtivos-detalle-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/03\/Tierra-de-furtivos-detalle-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/03\/Tierra-de-furtivos-detalle-644x397.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/03\/Tierra-de-furtivos-detalle-768x474.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/03\/Tierra-de-furtivos-detalle.jpg 1248w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>No les voy a contar nada de la trama. Solo les dir\u00e9 que estamos en la Vitoria contempor\u00e1nea y que los protagonistas son Josu Aguirre, un oficial de la Ertzaintza de car\u00e1cter particular; Tatiana, una aguerrida peluquera cuya amiga ha desaparecido \u2014lo que pone en marcha la acci\u00f3n\u2014 y Mikel, un guarda forestal que fue escolta en los tiempos del terrorismo etarra y que ahora protege a nos animales de los cazadores furtivos.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>No les cuento el argumento, insisto, pero s\u00ed les aviso de que \u2018Tierra de furtivos\u2019 tiene un trasfondo tem\u00e1tico que conecta con la actualidad social y period\u00edstica granadina: el tr\u00e1fico de marihuana, con \u201cbloques de viviendas en los que se cultivaba droga desde el s\u00f3tano hasta la terraza. Los cuartos de ba\u00f1o, las cocinas y los dormitorios se hab\u00edan convertido en invernaderos improvisados\u201d. \u00bfLes suena?<\/p>\n<p>Con su prosa precisa y certera, sin irse por las ramas, la novela tiene varios hilos narrativos en los que se entrelaza el tr\u00e1fico de drogas con el terrorismo y la violencia callejera. Es de una contemporaneidad absoluta y, a la vez, el autor se asoma a un pasado tr\u00e1gico que no debemos, no podemos olvidar.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/atractiva-y-peligrosa-tierra-de-furtivos\/oscar-beltran-de-otalora-pantano\/\" rel=\"attachment wp-att-31968\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-31968\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2022\/03\/oscar-Beltran-de-Otalora-pantano.jpg\" alt=\"\" width=\"227\" height=\"222\" \/><\/a><\/p>\n<p>\u2018Tierra de furtivos\u2019 es una nueva muestra del idilio entre el periodismo de investigaci\u00f3n con la novela polic\u00edaca. Cuando la realidad negro-criminal desborda los l\u00edmites del reportaje, la ficci\u00f3n acoge a periodistas de tron\u00edo como \u00d3car Beltr\u00e1n de Ot\u00e1lora y les brinda la posibilidad de poner, negro sobre blanco, todo lo mucho que saben sobre lo que pasa por las calles.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31741 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/11\/00000-Twitter-1.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>He disfrutado de todas y cada una de sus adictivas 400 p\u00e1ginas. Me ha encantado y se la recomiendo a todo el que me pregunta qu\u00e9 leer. Hablamos de \u2018Tierra de furtivos\u2019, un novel\u00f3n de \u00d3scar Beltr\u00e1n de Ot\u00e1lora publicado por Destino y protagonizado por tres personajes diferentes y contradictorios, todos muy bien construidos.\u00a0 Me [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,11774],"tags":[146,14002,20868,20855,20854],"class_list":["post-31964","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","category-rincon-oscuro","tag-editorial-destino","tag-marihuana-granada","tag-novelas-marihuana","tag-oscar-beltran-de-otalora","tag-tierra-de-furtivos"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=31964"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31964\/revisions"}],"predecessor-version":[{"id":31970,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31964\/revisions\/31970"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=31964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=31964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=31964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}