{"id":31671,"date":"2021-10-24T07:08:28","date_gmt":"2021-10-24T06:08:28","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=31671"},"modified":"2021-10-23T18:13:07","modified_gmt":"2021-10-23T17:13:07","slug":"la-granada-mas-exigente","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-granada-mas-exigente\/","title":{"rendered":"La Granada m\u00e1s exigente"},"content":{"rendered":"<p>Ayer hubo una concentraci\u00f3n en reivindicaci\u00f3n de la sanidad p\u00fablica. Fue en la Fuente de las Batallas y daba gusto ver a aquella gente all\u00ed reunida. Antes de ayer, una manifestaci\u00f3n recorri\u00f3 el centro de la ciudad exigiendo m\u00e1s y mejores conexiones ferroviarias. Y para diciembre se est\u00e1 organizando otra concentraci\u00f3n masiva para pedir las canalizaciones de Rules.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=31672\" rel=\"attachment wp-att-31672\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-31672\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/10\/Granada-se-mueve-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/10\/Granada-se-mueve-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/10\/Granada-se-mueve-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/10\/Granada-se-mueve-644x483.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>La ciudadan\u00eda vuelve a las calles a exigir soluciones, fechas y compromisos tangibles para resolver algunas de las carencias hist\u00f3ricas de nuestra tierra. Y hay que mostrarse orgullosos por ello. Tras este complicado a\u00f1o y medio pand\u00e9mico, Granada sale de su par\u00e1lisis y empieza a moverse.<\/p>\n<p>Lo mismo ocurre en la plaza del Carmen. El pasado viernes el ministro de Exteriores se asom\u00f3 al TAT Granada y se hizo un Julio C\u00e9sar de libro, un \u2018veni, vidi, vici\u2019 a toda mecha. Se marc\u00f3 un speech monumental de apenas 15 minutos y se march\u00f3 a toda mecha en loor de multitudes. Pero antes de subirse al coche encontr\u00f3 tiempo para encerrarse con el alcalde en una sala habilitada al efecto en el Parque de las Ciencias y departir un rato.<\/p>\n<p>Algo se mueve en nuestra tierra, insisto. Paco Cuenca, adem\u00e1s de hablar de Granada como Ciudad de la Ciencia con Albares, le hizo una serie de peticiones cuyo contenido no ha trascendido. Pero algo trama.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=31673\" rel=\"attachment wp-att-31673\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-31673\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/10\/Francisco-Cuenca-y-Albares-300x171.jpg\" alt=\"\" width=\"300\" height=\"171\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/10\/Francisco-Cuenca-y-Albares-300x171.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/10\/Francisco-Cuenca-y-Albares-768x437.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/10\/Francisco-Cuenca-y-Albares-644x367.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/10\/Francisco-Cuenca-y-Albares.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Algo m\u00e1s transparente se mostr\u00f3 el alcalde en sus peticiones al superministro Bola\u00f1os, con los transportes como tema central de sus reivindicaciones al Consejo de Ministros. Mayor frecuencia de trenes y aviones, la variante de Loja y el Corredor Mediterr\u00e1neo. Con una advertencia clara: \u201cle he pedido que haya una pronta respuesta porque, si no, los granadinos vamos a elevar el tono de nuestras reivindicaciones y, al mismo tiempo, de nuestras demandas\u201d.<\/p>\n<p>Alguno pensar\u00e1 que estas declaraciones son poca cosa. Pecata minuta. No es as\u00ed. Acostumbrados al seguidismo y a la indolencia cuando de reivindicar a los del mismo partido se trata, escuchar cosas as\u00ed de Cuenca es un cambio sustancial en la pol\u00edtica municipal.<\/p>\n<p>Los dos a\u00f1os de verborreico y tumultuoso gobierno de Cs y PP estuvieron condicionados por la pandemia, pero Granada dio muchos pasos atr\u00e1s en diferentes \u00e1mbitos que nada ten\u00edan que ver de forma directa con la cuesti\u00f3n sanitaria.<\/p>\n<p>Es b\u00e1sico que la ciudadan\u00eda siga abundando en esta senda reivindicativa para forzar a nuestros representantes institucionales a ser igualmente exigentes en Sevilla y Madrid. Nos va el futuro en ello.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-31674\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31674 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/10\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer hubo una concentraci\u00f3n en reivindicaci\u00f3n de la sanidad p\u00fablica. Fue en la Fuente de las Batallas y daba gusto ver a aquella gente all\u00ed reunida. Antes de ayer, una manifestaci\u00f3n recorri\u00f3 el centro de la ciudad exigiendo m\u00e1s y mejores conexiones ferroviarias. Y para diciembre se est\u00e1 organizando otra concentraci\u00f3n masiva para pedir las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[20725,2793,20726],"class_list":["post-31671","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-algo-se-mueve-en-granada","tag-francisco-cuenca","tag-granada-reivindicativa"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=31671"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31671\/revisions"}],"predecessor-version":[{"id":31675,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31671\/revisions\/31675"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=31671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=31671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=31671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}