{"id":31485,"date":"2021-09-08T16:19:52","date_gmt":"2021-09-08T15:19:52","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=31485"},"modified":"2021-09-11T16:23:59","modified_gmt":"2021-09-11T15:23:59","slug":"la-costa-sin-agua-y-con-sed","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-costa-sin-agua-y-con-sed\/","title":{"rendered":"La Costa, sin agua y con sed"},"content":{"rendered":"<p>Aunque algunos me miren raro, sigo siendo un firme defensor de la prensa en papel. Porque el formato importa. Y mucho. Las p\u00e1ginas 16 y 17 del IDEAL de ayer, sin ir m\u00e1s lejos, firmadas por Pilar Garc\u00eda-Trevijano, que abr\u00edan con el siguiente e ilusionante titular: \u00abLa agroindustria despega en Motril con la instalaci\u00f3n de empresas millonarias\u00bb. (Leer <a href=\"https:\/\/www.ideal.es\/granada\/costa\/agroindustria-despega-motril-20210907195328-nt.html\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a>) Nuevas industrias y marcas comerciales, crecimiento, potencial de desarrollo, expansi\u00f3n, puestos de trabajo \u00a0y riqueza. En la parte de abajo, otro titular interesante: \u00abLa Costa Tropical prev\u00e9 producir 10.000 toneladas de mango esta campa\u00f1a\u00bb, con informaci\u00f3n relevante sobre los subtropicales.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_31486\" aria-describedby=\"caption-attachment-31486\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-costa-sin-agua-y-con-sed\/agroindustria-costa\/\" rel=\"attachment wp-att-31486\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-31486\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/09\/AGROINDUSTRIA-COSTA-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/09\/AGROINDUSTRIA-COSTA-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/09\/AGROINDUSTRIA-COSTA.jpg 624w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-31486\" class=\"wp-caption-text\">Foto: Javier Mart\u00edn<\/figcaption><\/figure>\n<p>Al final de la p\u00e1gina, sin embargo, resaltadas en negrita, dos palabras: \u00abSin agua\u00bb. Dos palabras que saltan a la vista del lector del peri\u00f3dico en papel. \u00abSin agua\u00bb. Dos palabras que se clavan en los ojos y sirven de necesario reclamo para contextualizar toda la informaci\u00f3n precedente: la Costa Tropical no aguanta m\u00e1s la falta de agua para regar y necesita una soluci\u00f3n de emergencia que ya no pasa por las conducciones de Rules, esa ignominia que deber\u00eda abochornar a los pol\u00edticos de nuestra tierra. A todos ellos sin excepci\u00f3n.<\/p>\n<p>\u00abEl 60% de los pozos que riegan las fincas de la vega sexitana est\u00e1n al borde de la sequ\u00eda\u00bb, denuncian los regantes y el acu\u00edfero de R\u00edo Verde necesita una inyecci\u00f3n de urgencia. Granada es una de las provincias m\u00e1s empobrecidas de Europa y soporta unas intolerables tasas de desempleo. La agroindustria es una de las m\u00e1s pujantes y con mayores posibilidades de desarrollo. \u00bfQu\u00e9 hay m\u00e1s importante en las agendas de los representantes institucionales de Granada en Andaluc\u00eda y Espa\u00f1a que esta cuesti\u00f3n? \u00bfY en los presupuestos de unas y otras administraciones? Se nos llena la boca hablando del futuro, \u00bfpero qu\u00e9 pasa con el presente? Porque el presente, ahora mismo, indica que la pujante agricultura de la Costa Tropical se queda sin agua y empieza a tener sed. Mucha sed.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-31436\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31436 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/09\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque algunos me miren raro, sigo siendo un firme defensor de la prensa en papel. Porque el formato importa. Y mucho. Las p\u00e1ginas 16 y 17 del IDEAL de ayer, sin ir m\u00e1s lejos, firmadas por Pilar Garc\u00eda-Trevijano, que abr\u00edan con el siguiente e ilusionante titular: \u00abLa agroindustria despega en Motril con la instalaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[20337,20614,20615,12102,20616],"class_list":["post-31485","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-canalizaciones-rules","tag-costa-granada","tag-costa-sin-agua-con-sed","tag-costa-tropical","tag-subtropicales-costa-tropical"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=31485"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31485\/revisions"}],"predecessor-version":[{"id":31488,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31485\/revisions\/31488"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=31485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=31485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=31485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}