{"id":31441,"date":"2021-09-03T07:09:52","date_gmt":"2021-09-03T06:09:52","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=31441"},"modified":"2021-09-02T18:15:49","modified_gmt":"2021-09-02T17:15:49","slug":"geopolitica-del-futbol","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/geopolitica-del-futbol\/","title":{"rendered":"Geopol\u00edtica del f\u00fatbol"},"content":{"rendered":"<p>A medida que deca\u00eda mi inter\u00e9s por el f\u00fatbol como deporte se ha incrementado como factor estrat\u00e9gico de la geopol\u00edtica internacional. Alguna vez he escrito sobre las reminiscencias fantasmag\u00f3ricas del nombre Grupo Hope, encargado de gestionar los designios del Granada C.F. durante la presidencia de John Jiang. Sonaba a corporaci\u00f3n maligna de pel\u00edcula de 007. Eso s\u00ed: que terminara defraudando a Hacienda, presuntamente, le resta ese h\u00e1lito a supervillano de la Marvel para emparentarlo con los Gil y Gil de andar por casa.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=31444\" rel=\"attachment wp-att-31444\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-31444\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/09\/john-feliz-kPg-U110500664218IdH-624x385@Ideal-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/09\/john-feliz-kPg-U110500664218IdH-624x385@Ideal-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/09\/john-feliz-kPg-U110500664218IdH-624x385@Ideal.jpg 624w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>El f\u00fatbol es un poderoso instrumento de colonizaci\u00f3n. Y no solo mental. Personas que no mueven un dedo aunque les roben en la jeta, no dudan en echarse a la calle envueltos en la bandera del club de sus amores en cuanto sienten algo parecido a un agravio p un insulto. As\u00ed, veo en redes a personas inteligentes y habitualmente moderadas d\u00e1ndose dentelladas dial\u00e9cticas por un qu\u00edtame esa amarilla.<\/p>\n<p>Lo de Messi y Mbapp\u00e9 lleva consumidas tantas portadas, tantos titulares y tantas horas de conversaci\u00f3n y discusi\u00f3n que no ser\u00eda de extra\u00f1ar que, en el futuro y ante situaciones parecidas, los aficionados exijan al Gobierno que dote de fondos extraordinarios al Bar\u00e7a y al Real Madrid para que puedan hablarle de t\u00fa a t\u00fa al PSG, al Manchester City y a otros clubes dopados por los petrod\u00f3lares de Oriente Medio. El f\u00fatbol es, m\u00e1s que nunca, una cuesti\u00f3n de estado. Y esp\u00e9rate t\u00fa que no lo acabe siendo de Estado Mayor.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=31442\" rel=\"attachment wp-att-31442\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-31442\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/09\/PSG-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/09\/PSG-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/09\/PSG-644x362.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/09\/PSG.jpg 660w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>De aqu\u00ed a nada, el Ministerio de Defensa incluir\u00e1 secciones espec\u00edficas para analizar c\u00f3mo proteger a los porteros de los equipos patrios m\u00e1s punteros. M\u00e1s importante acabar\u00e1 siendo la zaga del Atl\u00e9tico que la defensa del pa\u00eds. El CNI tendr\u00e1 analistas especializados en el espionaje de los vestuarios rivales y los audios filtrados de Florentino ser\u00e1n un juego de ni\u00f1os con los esc\u00e1ndalos por venir.<\/p>\n<p>Dicen que Einstein dijo: \u201cNo s\u00e9 con qu\u00e9 armas se combatir\u00e1 la tercera guerra mundial, pero la cuarta ser\u00e1 con palos y piedras\u201d. Para m\u00ed que la IIIGM ya ha comenzado y, junto a los ciberataques y los drones, se est\u00e1 combatiendo con balones de f\u00fatbol, faxes, zapatillas y espinilleras.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=31443\" rel=\"attachment wp-att-31443\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-31443\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/09\/Real-madrid-War-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/09\/Real-madrid-War-300x300.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/09\/Real-madrid-War-150x150.jpg 150w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/09\/Real-madrid-War.jpg 540w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Los presidentes de los clubes ejercen como estadistas, los entrenadores ser\u00edan los generales y los capitanes, los mariscales de campo. El f\u00fatbol en los tiempos de \u2018Mad Max\u2019. Qu\u00e9 gran serie har\u00eda la HBO con esas mimbres y qu\u00e9 buen juego de rol saldr\u00eda de ah\u00ed. Algo as\u00ed como &#8216;The Football Wars&#8217;.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-31436\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31436 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/09\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A medida que deca\u00eda mi inter\u00e9s por el f\u00fatbol como deporte se ha incrementado como factor estrat\u00e9gico de la geopol\u00edtica internacional. Alguna vez he escrito sobre las reminiscencias fantasmag\u00f3ricas del nombre Grupo Hope, encargado de gestionar los designios del Granada C.F. durante la presidencia de John Jiang. Sonaba a corporaci\u00f3n maligna de pel\u00edcula de 007. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8,6],"tags":[20577,12894,20578,20580,20579],"class_list":["post-31441","post","type-post","status-publish","format-standard","hentry","category-deportes","category-opinion","tag-grupo-hope","tag-iii-guerra-mundial","tag-john-jiang","tag-psg","tag-the-football-wars"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=31441"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31441\/revisions"}],"predecessor-version":[{"id":31445,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31441\/revisions\/31445"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=31441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=31441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=31441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}