{"id":31314,"date":"2021-08-04T06:24:14","date_gmt":"2021-08-04T05:24:14","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=31314"},"modified":"2021-08-03T18:28:49","modified_gmt":"2021-08-03T17:28:49","slug":"menuda-panza-millones","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/menuda-panza-millones\/","title":{"rendered":"Menuda &#8216;panz\u00e1&#8217; millones"},"content":{"rendered":"<p>El alcalde nos sorprend\u00eda hace un par de d\u00edas con la petici\u00f3n a la Junta de Andaluc\u00eda de una inversi\u00f3n de tres millones de euros para el Palacio de Congresos de Granada. Digo que nos sorprend\u00eda porque esa cantidad es manifiestamente insuficiente, de acuerdo a las cifras publicadas en meses anteriores. De hecho, el proyecto de remodelaci\u00f3n presentado para concurrir a los fondos europeos es de 28 millones. (Leer <a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/tag\/palacio-de-congresos-granada\/\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a>).<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/palacio-rima-con-despacio\/palacio-de-congresos-de-granada-2\/\" rel=\"attachment wp-att-30483\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-30483\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/02\/Palacio-de-congresos-de-granada-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/02\/Palacio-de-congresos-de-granada-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/02\/Palacio-de-congresos-de-granada-768x474.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/02\/Palacio-de-congresos-de-granada-644x397.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/02\/Palacio-de-congresos-de-granada.jpg 1248w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Vamos a redondear: 30 kilos para el Palacio de Congresos. El otro gran palacio de Granada, el de Deportes, necesitar\u00eda 10 o 12 millones para algo m\u00e1s que un lavado de cara. Pongamos 15.<\/p>\n<p>Rebuscando en la hemeroteca, he encontrado una noticia de 2016 en que se hablaba de una inversi\u00f3n para las canalizaciones de Rules de 50 millones de euros para ejecutar hasta 2021 por parte de la Junta de Andaluc\u00eda. Ejem, ejem. \u00bfY qu\u00e9 costar\u00eda la entrada soterrada del AVE en Granada? Pongamos 75 millones. En total, 170 millones en infraestructuras que podr\u00edamos definir como de primera necesidad, prometidas hasta la saciedad la mayor\u00eda de ellas.<\/p>\n<p>As\u00ed en bruto, hablar de 170 millones de euros puede parecer una barbaridad. \u00a1En estos tiempos! \u00a1Con la que est\u00e1 cayendo! \u00a1A qui\u00e9n se le ocurre! Sin embargo, cuando nos enteramos de que Pedro S\u00e1nchez va a inyectarle 1700 millones al aeropuerto del Prat y 1600 a Barajas, \u00bfqu\u00e9 podemos decir? Yo me he quedado mudo, la verdad.<\/p>\n<p>\u00bfNo hab\u00edamos quedado en que lo importante del turismo es la calidad y no la cantidad? \u00bfNo es el avi\u00f3n el medio de transporte m\u00e1s contaminante? \u00bfNo tenemos una agenda 2050 entre lo sostenible y lo saludable? Para m\u00ed que la ampliaci\u00f3n de los aeropuertos no casa con esa filosof\u00eda ni va en esa direcci\u00f3n. \u00bfY qu\u00e9 pasa con la Espa\u00f1a vac\u00eda, vaciada y por vaciar? \u00bfCon la asimetr\u00eda y la desigualdad? \u00bfCon la Espa\u00f1a de las comarcas, rural y despoblada?<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/palacio-rima-con-despacio\/palacio-congresos\/\" rel=\"attachment wp-att-30484\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-30484\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/02\/Palacio-congresos-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/02\/Palacio-congresos-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/02\/Palacio-congresos-768x474.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/02\/Palacio-congresos-644x397.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/02\/Palacio-congresos.jpg 1248w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>No s\u00e9 si esas megainversiones deben pasar por el Congreso, pero me encantar\u00eda ver qu\u00e9 votan los diputados y senadores de Granada y, sobre todo, escucharles decir despu\u00e9s que lo de Rules va despacio porque es una inversi\u00f3n muy costosa.<\/p>\n<p>El alcalde Granada ped\u00eda 3 millones de euros para el Palacio de Congresos a la Junta de Andaluc\u00eda. Lo mismo ser\u00eda m\u00e1s sensato y productivo que se los exija a S\u00e1nchez: el aeropuerto del Prat ya va bien despachado con 1697 millones de euros. O Barajas, con sus 1597 kilos. \u00bfSer\u00e1 por dinero?<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-31101\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31101 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El alcalde nos sorprend\u00eda hace un par de d\u00edas con la petici\u00f3n a la Junta de Andaluc\u00eda de una inversi\u00f3n de tres millones de euros para el Palacio de Congresos de Granada. Digo que nos sorprend\u00eda porque esa cantidad es manifiestamente insuficiente, de acuerdo a las cifras publicadas en meses anteriores. De hecho, el proyecto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[20508,20507,20506,20509,20510],"class_list":["post-31314","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-aeropuerto-barajas","tag-aeropuerto-prat","tag-palacio-congresos-granada","tag-panza-millones","tag-sera-por-dinero"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=31314"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31314\/revisions"}],"predecessor-version":[{"id":31315,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31314\/revisions\/31315"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=31314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=31314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=31314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}