{"id":31215,"date":"2021-07-08T08:25:58","date_gmt":"2021-07-08T07:25:58","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=31215"},"modified":"2021-07-12T08:27:48","modified_gmt":"2021-07-12T07:27:48","slug":"manana-ya-es-tarde","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/manana-ya-es-tarde\/","title":{"rendered":"Ma\u00f1ana ya es tarde"},"content":{"rendered":"<p>Hace una semana escrib\u00eda una columna titulada \u2018Alcalde con altura de miras\u2019, pidi\u00e9ndole a Paco Cuenca que, si volv\u00eda a la alcald\u00eda, propiciara un acuerdo de m\u00ednimos entre PSOE, PP, Podemos-IU, Vox y los restos de Cs sobre el futuro de la ciudad. Un acuerdo con un horizonte que apuntara m\u00e1s all\u00e1 de 2023, cuando habr\u00e1 nuevas elecciones municipales.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/campana-y-se-acabo-2\/luis-salvador-paco-cuenca-3\/\" rel=\"attachment wp-att-31162\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-31162\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/Luis-Salvador-Paco-Cuenca-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/Luis-Salvador-Paco-Cuenca-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/Luis-Salvador-Paco-Cuenca.jpg 575w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>En su discurso de investidura, el reci\u00e9n elegido de nuevo alcalde de la ciudad repiti\u00f3 la palabra \u2018Granada\u2019 una y otra vez. Hizo bien. Los granadinos estamos hartos de que el Ayuntamiento sea un constante pimpampum donde se hable de las cuitas catalanas y madrile\u00f1as y se traten cuestiones partidistas que deber\u00edan quedar para las sedes de las formaciones pol\u00edticas.<\/p>\n<p>Estamos hasta m\u00e1s all\u00e1 del colodrillo de que se tomen decisiones basadas en los vetos personales propiciados por las simpat\u00edas o antipat\u00edas a los indultos y a las ayusadas, morenadas, marinadas, casadas o sanchadas. Los concejales deber\u00edan dejar aparcadas todas esas cuestiones al empezar su jornada de trabajo en plaza del Carmen. All\u00ed se deben \u00fanica y exclusivamente a los intereses de Granada y sus ciudadanos.<\/p>\n<p>Comenz\u00f3 Paco Cuenca su discurso apelando a Machado: \u201cahora es el momento de cumplir las promesas que nos hicimos. Porque ayer no lo hicimos, porque ma\u00f1ana es tarde. Ahora\u201d. Y, de inmediato, su invitaci\u00f3n a los 27 concejales del Ayuntamiento a consensuar un pacto por Granada se sirva para demostrar la utilidad de la pol\u00edtica y la recuperaci\u00f3n de la confianza de la ciudadan\u00eda.<\/p>\n<p>Falta hace. Mucha falta. El PSOE demostr\u00f3 altura de miras, hace unos meses, ayudando a aprobar un nuevo presupuesto para la ciudad. Qu\u00e9 bien le va a venir ahora que recupera el bast\u00f3n de mando. Cuenca apel\u00f3 en su discurso a la ciencia y a la innovaci\u00f3n, a la riqueza cultural y a los creadores, a la Vega y al turismo sostenible, a las pymes, a los barrios y a la Granada metropolitana.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-acelerador-ya-tira\/acelerador-3\/\" rel=\"attachment wp-att-31106\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-31106\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/Acelerador-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/Acelerador-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/Acelerador.jpg 396w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Izquierda Unida-Podemos lleva meses reclamando, tambi\u00e9n, ese pacto de ciudad. Los dos concejales de esa entelequia llamada Ciudadanos, que en un mes va a perder a sus cuatro concejales, ya han anunciado que apoyar\u00e1n los temas de enjundia para la ciudad. Ojal\u00e1 que el PP, despu\u00e9s de la lamentable gesti\u00f3n de las \u00faltimas semanas, recapacite y ponga coto a su iracundo frentismo para sumar. De Vox, m\u00e1s all\u00e1 de sus abusivas analog\u00edas animalistas, poco se puede esperar.<\/p>\n<p>Dos a\u00f1os de mandato tiene Cuenca por delante para sentar las bases de la Granada del futuro. Estaremos atentos y vigilantes tanto a las propuestas que haga como a las contraprestaciones que ofrezca. Estaremos pendientes, tambi\u00e9n, de las actitudes y gestos de los concejales de la oposici\u00f3n. De si creen en Granada o anteponen sus intereses personales y partidistas a los de la ciudad.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-31101\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31101 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace una semana escrib\u00eda una columna titulada \u2018Alcalde con altura de miras\u2019, pidi\u00e9ndole a Paco Cuenca que, si volv\u00eda a la alcald\u00eda, propiciara un acuerdo de m\u00ednimos entre PSOE, PP, Podemos-IU, Vox y los restos de Cs sobre el futuro de la ciudad. Un acuerdo con un horizonte que apuntara m\u00e1s all\u00e1 de 2023, cuando [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[20442,20443,12398],"class_list":["post-31215","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-manana-es-tarde","tag-manana-ya-es-tarde","tag-paco-cuenca-alcalde"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=31215"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31215\/revisions"}],"predecessor-version":[{"id":31216,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31215\/revisions\/31216"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=31215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=31215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=31215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}