{"id":31155,"date":"2021-06-29T08:01:01","date_gmt":"2021-06-29T07:01:01","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=31155"},"modified":"2021-06-28T14:07:48","modified_gmt":"2021-06-28T13:07:48","slug":"jim-thompson-un-clasico-del-noir-mas-desquiciado","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/jim-thompson-un-clasico-del-noir-mas-desquiciado\/","title":{"rendered":"Jim Thompson, un cl\u00e1sico del Noir m\u00e1s desquiciado"},"content":{"rendered":"<p>Como hab\u00edamos tenido dos o tres lecturas m\u00e1s o menos sosegadas, negras y criminales, pero no demasiado salvajes, decidimos meterle heavy metal al Club de Lectura y Cine de Granada Noir y nos lanzamos sobre Jim Thompson y su brutal \u20181280 almas\u2019. En la reuni\u00f3n de esta tarde, por fin presencial, corremos el riesgo de terminar a palos. A m\u00ed me toca hacer de poli malo y defender a Nick Corey, el sheriff protagonista de la novela. Me temo que estar\u00e9 solo. Muy solo.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=31156\" rel=\"attachment wp-att-31156\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-31156\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-Almas-197x300.jpg\" alt=\"\" width=\"197\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-Almas-197x300.jpg 197w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-Almas-768x1170.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-Almas-644x981.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-Almas.jpg 800w\" sizes=\"auto, (max-width: 197px) 100vw, 197px\" \/><\/a><\/p>\n<p>Nick Corey, dig\u00e1moslo desde el principio, es la hez. Se trata de un vago redomado, un sheriff corrupto de un ignoto y perdido pueblucho del sur de los Estados Unidos que no quiere complicaciones. Pero cuando se acerca el momento de la reelecci\u00f3n y se encuentra con un rival en liza, el que parec\u00eda ser un tarugo de tomo lomo, un tonto del haba; se nos ir\u00e1 descubriendo como un maquiav\u00e9lico psic\u00f3pata sin empacho en liquidar a todo el que se le ponga por delante. Y por detr\u00e1s. Incluso al lado.<\/p>\n<p>Escrita en primera persona, \u20181280 almas\u2019 resulta inc\u00f3moda de leer. Porque el narrador, por supuesto, es Nick Corey. Y resulta dif\u00edcil, muy dif\u00edcil, asimilar su verborrea, sus maquinaciones, pensamientos y justificaciones. Y eso que su sentido del humor, negro como la pez, acaba arrancando alguna que otra carcajada c\u00f3mplice del lector m\u00e1s desprejuiciado.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=31157\" rel=\"attachment wp-att-31157\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-31157\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-Jim-Thmpson-300x255.jpg\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-Jim-Thmpson-300x255.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-Jim-Thmpson.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Cuando uno lee la biograf\u00eda del autor, descubre que el padre de Jim Thompson fue sheriff del condado\u2026 y tuvo que huir tras ser acusado de malversaci\u00f3n de caudales p\u00fablicos. Un sujeto alcoh\u00f3lico y violento de vida azarosa que lo mismo gan\u00f3 una fortuna con el petr\u00f3leo que la perdi\u00f3 entre juergas, timbas y p\u00e9simas inversiones.<\/p>\n<p>Thompson, alcoh\u00f3lico tambi\u00e9n, desempe\u00f1\u00f3 mil y un empleos, fue periodista de nota roja y escritor de relatos criminales basados en hechos reales. Con pasi\u00f3n por los personajes m\u00e1s desquiciados, representa el lado oscuro y siniestro del sue\u00f1o americano. Una pesadilla que el mism\u00edsimo Stephen King describe de la siguiente manera: \u201cLo que convierte los libros de Thompson en literatura es su disecci\u00f3n cl\u00ednica de la mente alienada, de la psique trastornada hasta convertirse en una bomba de nitr\u00f3geno, de las personas cuya existencia recuerda a unas c\u00e9lulas enfermas y situadas en el intestino de la sociedad estadounidense\u201d.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=31158\" rel=\"attachment wp-att-31158\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-31158\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-novelas-300x205.jpg\" alt=\"\" width=\"300\" height=\"205\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-novelas-300x205.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-novelas-768x525.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-novelas-644x440.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-novelas.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Con su padre ingresado en un manicomio, Thompson decidi\u00f3 escribir una novela para conseguir dinero y sacarle de all\u00ed. Le prometi\u00f3 que en un mes estar\u00eda fuera. Trabaj\u00f3 de forma enfervorizada en jornadas de hasta 20 horas diarias. En dos semanas ten\u00eda la novela terminada, pero una de sus crisis alcoh\u00f3licas le llev\u00f3 al hospital. Cuando sali\u00f3, el mes prometido hab\u00eda pasado y su padre se hab\u00eda suicidado. Ni que decir tiene que en su literatura, el complejo de Edipo tambi\u00e9n ocupa un papel destacado.<\/p>\n<p>Thompson fue guionista de Stanley Kubrick en \u2018Atraco perfecto\u2019, un noir de manual, y en \u2018Senderos de gloria\u2019. Adem\u00e1s, muchas de sus novelas fueron llevadas al cine, desde \u2018La hu\u00edda\u2019, dirigida por Sam Peckinpah, con Steve McQueen y Ali McGraw a la propia \u20181280 almas\u2019, en la que Betrand Tavernier se lleva la acci\u00f3n al \u00c1frica colonial francesa. Una de las m\u00e1s notables es \u2018Los timadores\u2019, de Stephen Frears, una joya de 1990 muy complicada de encontrar.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=31159\" rel=\"attachment wp-att-31159\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-31159\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-Tavernier-200x300.png\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-Tavernier-200x300.png 200w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-Tavernier-768x1152.png 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-Tavernier-644x966.png 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/1280-Tavernier.png 1000w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<p>No puedo recomendarles que lean \u20181280 almas\u2019. Bastante voy a tener con defenderla esta tarde. Y, desde luego, no osen adentrarse en \u2018El asesino dentro de m\u00ed\u2019. \u00a1Ni se les ocurra! No se dejen influir por Stanley Kubrick cuando sosten\u00eda que es \u201cla historia m\u00e1s escalofriante que haya le\u00eddo jam\u00e1s sobre una mente deformada por el crimen\u201d.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-31101\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31101 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como hab\u00edamos tenido dos o tres lecturas m\u00e1s o menos sosegadas, negras y criminales, pero no demasiado salvajes, decidimos meterle heavy metal al Club de Lectura y Cine de Granada Noir y nos lanzamos sobre Jim Thompson y su brutal \u20181280 almas\u2019. En la reuni\u00f3n de esta tarde, por fin presencial, corremos el riesgo de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10,11144,11774],"tags":[20408,20409,19879,20412,19823,20410,11145,20411,4327],"class_list":["post-31155","post","type-post","status-publish","format-standard","hentry","category-cine","category-granada-noir","category-rincon-oscuro","tag-1280-almas","tag-1280-almas-cine","tag-adictos-al-crimen","tag-betrand-tavernier","tag-club-de-lectura-y-cine-granada-noir","tag-el-asesino-dentro-de-mi","tag-granada-noir-2","tag-jim-thompson-escritor","tag-sam-peckinpah"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=31155"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31155\/revisions"}],"predecessor-version":[{"id":31160,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31155\/revisions\/31160"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=31155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=31155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=31155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}