{"id":31039,"date":"2021-05-31T09:24:37","date_gmt":"2021-05-31T08:24:37","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=31039"},"modified":"2021-06-03T09:27:50","modified_gmt":"2021-06-03T08:27:50","slug":"malaga-golpea-de-nuevo","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/malaga-golpea-de-nuevo\/","title":{"rendered":"M\u00e1laga golpea de nuevo"},"content":{"rendered":"<p>Ya no deber\u00eda ser noticia que M\u00e1laga consiga que una empresa tecnol\u00f3gica de primer orden mundial se instale en sus pagos. Ahora ha sido Vodafone quien ha elegido a nuestros vecinos para abrir un centro de I+D que generar\u00e1 600 puestos de trabajo de alta cualificaci\u00f3n tecnol\u00f3gica.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/malaga-golpea-de-nuevo\/malaga-vodafone\/\" rel=\"attachment wp-att-31040\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-31040\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/M\u00e1laga-Vodafone-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/M\u00e1laga-Vodafone-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/M\u00e1laga-Vodafone.jpg 624w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Siete ciudades del mundo optaban a hacerse con el contrato. M\u00e1laga ha sido la seleccionada y Vodafone se suma a Google, Dekra, Globant o TDK; contribuyendo a la implementaci\u00f3n de un nodo tecnol\u00f3gico de primer orden en la Costa del Sol.<\/p>\n<p>Francisco de la Torre, el alcalde malacitano, lo tiene claro: \u201cLas administraciones han trabajado leal y conjuntamente para que M\u00e1laga se imponga\u201d, se\u00f1al\u00f3.<\/p>\n<p>Hacer la comparaci\u00f3n con lo que est\u00e1 pasando en Granada en estos momentos no ser\u00eda justo. \u00bfO quiz\u00e1 s\u00ed? El vodevil espartano \u00bfo era sainete valyrio? en que ha desembocado el 2+2 es una muestra m\u00e1s de la incapacidad de nuestros mun\u00edcipes de llegar a acuerdos de m\u00ednimos. Y no digamos ya de m\u00e1ximos.<\/p>\n<p>Podr\u00edamos pensar que lo del 2+2 y la operaci\u00f3n \u2018Desalojar al soldado Salvador\u2019 es coyuntural, pero no. Recordemos que Paco Cuenca accedi\u00f3 a la alcald\u00eda tras la esperp\u00e9ntica salida entre cartones de Torres Hurtado y que le hicieron la vida imposible. Fue imposible siquiera sacar adelante un presupuesto.<\/p>\n<p>De los audios hechos p\u00fablicos ayer por IDEAL en una extraordinaria exclusiva, me quedo con una frase de Salvador llevada a portada: \u201cSomos once, tenemos que funcionar igual que en la Junta, entendi\u00e9ndose como un equipo, en un proyecto que tendr\u00e1 que reeditarse en las siguientes elecciones\u201d. \u00a1Ay, Luis, qu\u00e9 cosas!<\/p>\n<p>\u00bfCu\u00e1ntas veces hemos escrito \u2018proyecto de ciudad\u2019? \u00bfCu\u00e1ntas veces lo han le\u00eddo\/escuchado ustedes? M\u00e1laga tiene un proyecto de ciudad. Granada es un reino de Taifas donde, nada m\u00e1s darte la vuelta, te clavan siete pu\u00f1ales antes de ser abrasado por el fuego amigo, el que m\u00e1s quema.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/malaga-golpea-de-nuevo\/malaga-tech\/\" rel=\"attachment wp-att-31041\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-31041\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/M\u00e1laga-tech-300x176.jpg\" alt=\"\" width=\"300\" height=\"176\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/M\u00e1laga-tech-300x176.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/M\u00e1laga-tech-768x452.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/M\u00e1laga-tech-644x379.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/06\/M\u00e1laga-tech.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>En Granada, nuestros pol\u00edticos hacen la guerra por su cuenta y cotiza m\u00e1s destruir al otro que construir nada m\u00ednimamente s\u00f3lido o duradero. Tierra de ide\u00edtas y proyectos personalistas, unos proponen la construcci\u00f3n de un gran espacio esc\u00e9nico y otros, desembovedar el Darro.<\/p>\n<p>El alcalde que sobreviva al \u2018Juego de Tronos\u2019 que estamos viviendo estos d\u00edas se encontrar\u00e1 con la plaza del Carmen arrasada y a los concejales personal y pol\u00edticamente enemistados entre s\u00ed. El resultado ser\u00e1n otros dos a\u00f1o perdidos entre broncas e insultos. Lo mismo que en M\u00e1laga, vamos.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-30936\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-30936 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/05\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya no deber\u00eda ser noticia que M\u00e1laga consiga que una empresa tecnol\u00f3gica de primer orden mundial se instale en sus pagos. Ahora ha sido Vodafone quien ha elegido a nuestros vecinos para abrir un centro de I+D que generar\u00e1 600 puestos de trabajo de alta cualificaci\u00f3n tecnol\u00f3gica. Siete ciudades del mundo optaban a hacerse con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[20357,20358,20356],"class_list":["post-31039","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-malaga-da-dos-veces","tag-malaga-granada","tag-malaga-tecnologica"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=31039"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31039\/revisions"}],"predecessor-version":[{"id":31043,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/31039\/revisions\/31043"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=31039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=31039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=31039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}