{"id":30935,"date":"2021-05-11T07:59:30","date_gmt":"2021-05-11T06:59:30","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=30935"},"modified":"2021-05-10T19:21:36","modified_gmt":"2021-05-10T18:21:36","slug":"la-ciudad-de-las-almas-tristes","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-ciudad-de-las-almas-tristes\/","title":{"rendered":"La ciudad de las almas tristes"},"content":{"rendered":"<p>Yo creo que \u00e9l ya no se acuerda, pero Javier M\u00e1rquez S\u00e1nchez me envi\u00f3 hace ya a\u00f1os, tres, cuatro o cinco; el primer borrador de lo que hoy es \u2018La ciudad de las almas tristes\u2019, excelente y can\u00f3nica novela negra protagonizada por periodistas.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=30937\" rel=\"attachment wp-att-30937\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-30937\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/05\/La-ciudad-de-las-almas-tristes-186x300.jpg\" alt=\"\" width=\"186\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/05\/La-ciudad-de-las-almas-tristes-186x300.jpg 186w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/05\/La-ciudad-de-las-almas-tristes.jpg 229w\" sizes=\"auto, (max-width: 186px) 100vw, 186px\" \/><\/a><\/p>\n<p>La publica Almuzara y no solo me lo he pasado estupendamente ley\u00e9ndola, sino que se la he recomendado vivamente a mis alumnos de pr\u00e1ctica period\u00edstica de ESCO. De hecho, en clase pasamos un rato comentando el siguiente p\u00e1rrafo: \u201cEllos tambi\u00e9n estuvieron metidos en aquella dichosa investigaci\u00f3n. A m\u00ed me alcanz\u00f3 la mierda y tuve que largarme. Ellos se quedaron. Nunca llegu\u00e9 a saber si consiguieron no pringarse o lo evitaron, que aunque suena igual no es lo mismo ni de cojones\u201d.<\/p>\n<p>Les pongo en antecedentes: Jos\u00e9 Luis Ballesteros, periodista de raza, se tuvo que marchar de Sevilla tras desvelar una trama de corrupci\u00f3n de menores que acab\u00f3 de la peor manera posible. Instalado en Madrid, demasiado joven para el periodismo cl\u00e1sico, pero demasiado chapado a la antigua para enarbolar la revoluci\u00f3n digital, sobrevive como periodista de fortuna. O de encargo. Como el que le devuelve a Sevilla y le lleva a contactar con sus antiguos compa\u00f1eros. Esos que no sabe si consiguieron salir a flote por evitar pringarse.<\/p>\n<p>Jos\u00e9 Luis es un personajazo. Va de duro, c\u00ednico y descre\u00eddo por la vida, como un Philip Marlowe del siglo XXI que ha cambiado la Costa Oeste de los Estados Unidos por las orillas del Guadalquivir. Conexi\u00f3n Sausalito-Triana. Pero en el fondo tiene su corazoncito. Y aunque haya renegado del periodismo, sigue siendo periodista por los cuatro costados. Periodista por instinto, convicci\u00f3n y devoci\u00f3n. A su manera, eso s\u00ed. De raza y por libre. Heterodoxo. Pasional.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=30938\" rel=\"attachment wp-att-30938\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-30938\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/05\/Javier-M\u00e1rquez-S\u00e1nchez-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/05\/Javier-M\u00e1rquez-S\u00e1nchez-300x300.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/05\/Javier-M\u00e1rquez-S\u00e1nchez-150x150.jpg 150w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/05\/Javier-M\u00e1rquez-S\u00e1nchez.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>\u201cSi se ha inventado algo absurdo en este mundo, adem\u00e1s de la cerveza con lim\u00f3n y la televisi\u00f3n 3D, es la carrera de periodismo. Para ser periodista hay que tener curiosidad, instinto de investigaci\u00f3n y capacidad para narrar. Y desde luego ninguna de esas tres cosas las ense\u00f1aban en la carrera cuando yo estudio\u2026 El hambre por contar historias, como por las manitas de cerdo, se tiene o no se tiene. El periodismo fue y ser\u00e1 un oficio. Lo de la filigrana universitaria es otro cantar\u201d. Ah\u00ed est\u00e1 el Toque M\u00e1rquez, meti\u00e9ndole sorna y humor a frases que, sin ellos, quedar\u00edan demasiado sentenciosas.<\/p>\n<p>En su vuelta a Sevilla Jos\u00e9 Luis recupera las calles, garitos y locales de su \u00e9poca y se pone al d\u00eda con amigos, familiares, amantes y colegas de anta\u00f1o. No es f\u00e1cil, que dej\u00f3 algunos cad\u00e1veres a su paso. La mayor\u00eda metaf\u00f3ricos, pero tambi\u00e9n alguno real. Un deambular, siempre, de lo m\u00e1s revelador e inspirador para el lector.<\/p>\n<p>El protagonista de \u2018La ciudad de las almas tristes\u2019 se ve metido en un \u2018embolao\u2019 que afecta a las esferas m\u00e1s altas de la Junta de Andaluc\u00eda. Hay sobresueldos, mordidas y enchufes. Negocios legales, alegales y paralegales en torno a, por ejemplo, un parque de atracciones con nombre de isla.<\/p>\n<p>No recuerdo exactamente qu\u00e9 le dije a Javier sobre aquella lejana lectura del borrador de esta novela. S\u00e9 que le anim\u00e9 a darle otra vuelta y a publicarla s\u00ed o tambi\u00e9n, a pesar de ser pol\u00e9mica, que lo es. \u00a1O precisamente por eso! Y es que algunos pol\u00edticos y sus corruptelas son (im)perfectamente reconocibles. Y algunas pol\u00edticas, tambi\u00e9n.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=30939\" rel=\"attachment wp-att-30939\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-30939\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/05\/Javier-M\u00e1rquez-S\u00e1nchez-autor-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/05\/Javier-M\u00e1rquez-S\u00e1nchez-autor-300x300.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/05\/Javier-M\u00e1rquez-S\u00e1nchez-autor-150x150.jpg 150w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/05\/Javier-M\u00e1rquez-S\u00e1nchez-autor.jpg 330w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Resultar\u00e1 inc\u00f3moda para el poder establecido. Pero eso es lo bueno, lo necesario de la novela negra en la que creo: alumbra esos rincones oscuros que, los de arriba, tratan de que sigan en penumbra. Y sin barrer.<\/p>\n<p>(M\u00e1s novelas que he le\u00eddo y comentado de Javier M\u00e1rquez S\u00e1nchez: <a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-fiesta-de-orfeo\/\" target=\"_blank\" rel=\"noopener\">La fiesta de Orfeo<\/a>, <a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/letal-como-un-solo-de-charlie-parker\/\" target=\"_blank\" rel=\"noopener\">Letal como un solo de Charlie Parker<\/a>, <a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/tag\/afilado-como-un-blues-a-medianoche\/\" target=\"_blank\" rel=\"noopener\">Afilado como un blues a medianoche<\/a>,<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-30936\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-30936 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/05\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yo creo que \u00e9l ya no se acuerda, pero Javier M\u00e1rquez S\u00e1nchez me envi\u00f3 hace ya a\u00f1os, tres, cuatro o cinco; el primer borrador de lo que hoy es \u2018La ciudad de las almas tristes\u2019, excelente y can\u00f3nica novela negra protagonizada por periodistas. La publica Almuzara y no solo me lo he pasado estupendamente ley\u00e9ndola, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11144,21,11774],"tags":[48,2443,20299,20300],"class_list":["post-30935","post","type-post","status-publish","format-standard","hentry","category-granada-noir","category-negra-y-criminal","category-rincon-oscuro","tag-almuzara","tag-javier-marquez-sanchez","tag-la-ciudad-de-las-almas-tristes","tag-sevilla-connection"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/30935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=30935"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/30935\/revisions"}],"predecessor-version":[{"id":30942,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/30935\/revisions\/30942"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=30935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=30935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=30935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}