{"id":30729,"date":"2021-04-05T08:02:34","date_gmt":"2021-04-05T07:02:34","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=30729"},"modified":"2021-04-04T17:06:01","modified_gmt":"2021-04-04T16:06:01","slug":"lunes-que-hacen-la-pascua","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/lunes-que-hacen-la-pascua\/","title":{"rendered":"Lunes que hacen la pascua"},"content":{"rendered":"<p>Hac\u00eda tiempo que no ten\u00eda tanta sensaci\u00f3n de domingo por la tarde. Pienso en ma\u00f1ana lunes (por hoy) mientras escribo y no voy a decir que me corre un sudor fr\u00edo por la espalda, tampoco es cuesti\u00f3n de exagerar, pero s\u00ed que siento algo parecido a una comez\u00f3n, s\u00edntoma inequ\u00edvoco de que me va a hacer la pascua.<\/p>\n<figure id=\"attachment_30730\" aria-describedby=\"caption-attachment-30730\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=30730\" rel=\"attachment wp-att-30730\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-30730\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/04\/juanma-moreno-cuarta-ola-kMsF-U1301028581920ByE-1248x770@Ideal-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/04\/juanma-moreno-cuarta-ola-kMsF-U1301028581920ByE-1248x770@Ideal-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/04\/juanma-moreno-cuarta-ola-kMsF-U1301028581920ByE-1248x770@Ideal-768x474.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/04\/juanma-moreno-cuarta-ola-kMsF-U1301028581920ByE-1248x770@Ideal-644x397.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/04\/juanma-moreno-cuarta-ola-kMsF-U1301028581920ByE-1248x770@Ideal.jpg 1248w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-30730\" class=\"wp-caption-text\">Juanma ya ha empezado a avisar&#8230;<\/figcaption><\/figure>\n<p>Asueto. \u201cInterrupci\u00f3n temporal por descanso del trabajo, los estudios u otra actividad habitual, especialmente si dura un d\u00eda o unas horas\u201d, lo define la RAE. Esta Semana Santa ha supuesto un asueto mental que me ha mantenido alejado de la informaci\u00f3n sobre La Cosa. Y es por eso que le tengo tanto recelo a hoy lunes, cuando los datos actualizados empiecen a caer en cascada y la cuarta ola se convierta en el tema central de conversaciones, tertulias, art\u00edculos y tribunas de opini\u00f3n. \u00a1Qu\u00e9 pereza!<\/p>\n<p>Eso, y la reanudaci\u00f3n de la polarizaci\u00f3n informativa sobre las elecciones en Madrid y Catalu\u00f1a, el agujero de gusano que nos conduce a esa realidad paralela y alternativa en que parecen vivir la mayor parte de nuestros pol\u00edticos. \u00a1Qu\u00e9 perez\u00f3n!<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=30731\" rel=\"attachment wp-att-30731\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-30731\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/04\/Vacunas-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/04\/Vacunas-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/04\/Vacunas-768x474.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/04\/Vacunas-644x397.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/04\/Vacunas.jpg 1248w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Estos d\u00edas he caminado por nuestra tierra con las lentes de los viajeros rom\u00e1nticos, de la Madraza a la Casa de los Tiros, con sus exposiciones, paseando por la Alcaicer\u00eda y el Realejo. La \u2018nueva\u2019 Ribera del Genil que, a la espera de los \u00e1rboles, integra mucho mejor su Alc\u00e1zar y la Ermita de San Sebasti\u00e1n. O la Granada m\u00e1s contempor\u00e1nea, la del siglo XXI, la del PTS, su arquitectura de vanguardia y su galer\u00eda de arte urbano al aire libre, de la que un d\u00eda de estos tenemos que hablar en profundidad.<\/p>\n<p>Toca cambiar de gafas y ponerse, de nuevo, las de diario. \u00a1Qu\u00e9 requetepereza! \u00bfEn qu\u00e9 cuitas andar\u00e1n nuestros pr\u00f3ceres locales? M\u00e1s all\u00e1 del 2+2, quiero decir, que encara su recta definitiva. \u00bfCon qu\u00e9 cruces de acusaciones nos sorprender\u00e1n estas semanas? Les reconozco que ah\u00ed s\u00ed me pica la curiosidad. Eso y el as de Espadas que una parte del PSOE quiere poner sobre la mesa para cortarle la cabeza a Susana D\u00edaz de una vez por todas.<\/p>\n<figure id=\"attachment_30732\" aria-describedby=\"caption-attachment-30732\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=30732\" rel=\"attachment wp-att-30732\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-30732\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/04\/Espadas-Susana-D\u00edaz-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/04\/Espadas-Susana-D\u00edaz-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/04\/Espadas-Susana-D\u00edaz.jpg 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-30732\" class=\"wp-caption-text\">Espadas mira a Susana D\u00edaz<\/figcaption><\/figure>\n<p>\u00bfVen? Cuando deber\u00edamos estar pendientes de las vacunas, los Juegos de Cromos de los unos y los otros nos hacen desviar la atenci\u00f3n de lo aut\u00e9nticamente importante a lo que debiera ser accesorio. En fin. Que es lunes de Pascua y mucha pascua. Valor y al toro.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\/\" target=\"_blank\" rel=\"attachment noopener wp-att-30632\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-30632 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/00000-Twitter-1.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hac\u00eda tiempo que no ten\u00eda tanta sensaci\u00f3n de domingo por la tarde. Pienso en ma\u00f1ana lunes (por hoy) mientras escribo y no voy a decir que me corre un sudor fr\u00edo por la espalda, tampoco es cuesti\u00f3n de exagerar, pero s\u00ed que siento algo parecido a una comez\u00f3n, s\u00edntoma inequ\u00edvoco de que me va a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[20169,20168,20171,20170],"class_list":["post-30729","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-espadas-susana-diaz-cuarta-ola","tag-juan-espadas","tag-la-cuarta-ola","tag-vacuna-coronavirus"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/30729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=30729"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/30729\/revisions"}],"predecessor-version":[{"id":30733,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/30729\/revisions\/30733"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=30729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=30729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=30729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}