{"id":30571,"date":"2021-03-07T08:13:26","date_gmt":"2021-03-07T07:13:26","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=30571"},"modified":"2021-03-06T13:13:46","modified_gmt":"2021-03-06T12:13:46","slug":"estrategia-para-la-industria","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/estrategia-para-la-industria\/","title":{"rendered":"Estrategia para la industria"},"content":{"rendered":"<p>Hace unas semanas, trabajando en el suplemento especial para el D\u00eda de Andaluc\u00eda de este peri\u00f3dico, tuve ocasi\u00f3n de conversar con Jos\u00e9 Manuel Cassinello, director general de Jalsosa, una empresa de trayectoria impecable. Hablamos largo y tendido sobre este a\u00f1o tan complicado y al transcribir sus palabras, ca\u00ed en la cuenta de que no le hab\u00eda preguntado sobre el futuro de la industria en Espa\u00f1a.<\/p>\n<figure id=\"attachment_30572\" aria-describedby=\"caption-attachment-30572\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/estrategia-para-la-industria\/cassinello\/\" rel=\"attachment wp-att-30572\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-30572\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Cassinello-300x186.jpg\" alt=\"\" width=\"300\" height=\"186\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Cassinello-300x186.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Cassinello-768x476.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Cassinello-644x399.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Cassinello.jpg 981w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-30572\" class=\"wp-caption-text\">Foto: Alfredo Aguilar<\/figcaption><\/figure>\n<p>Ah\u00ed arranc\u00f3 una nueva y larga conversaci\u00f3n que me vi obligado a resumir en apenas un pu\u00f1ado de palabras sobre la peligrosa dependencia de Asia y una reclamaci\u00f3n final por parte del empresario: \u201cEs necesario que las autoridades sean tan celosas y exigentes en el cumplimiento de la normativa comunitaria con las empresas que producen fuera de Europa como lo son con nosotros\u201d.<\/p>\n<p>Como Jos\u00e9 Manuel tiene tan buena pluma como bien ordenada la cabeza y es un habitual de la secci\u00f3n de Opini\u00f3n de IDEAL, le anim\u00e9 a que pusiera negro sobre blanco sus interesantes reflexiones, cosa hizo en una tribuna titulada \u2018En defensa de nuestra industria estrat\u00e9gica\u2019 y que les animo a leer en la edici\u00f3n digital del peri\u00f3dico, si no lo hicieron en su momento.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/estrategia-para-la-industria\/cassinello-jalsosa\/\" rel=\"attachment wp-att-30573\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-30573\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Cassinello-Jalsosa-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Cassinello-Jalsosa-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Cassinello-Jalsosa-768x432.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Cassinello-Jalsosa-644x362.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Cassinello-Jalsosa.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Por una parte, Cassinello considera esencial \u201cpotenciar y tutelar nuestra industria en aquellos sectores especialmente sensibles en tiempos de pandemia\u201d, dado que los especialistas no dudan que habr\u00e1 m\u00e1s en el futuro. Para ello, y tras descartar un caduco proteccionismo arancelario que se ha demostrado in\u00fatil a lo largo de la historia, pon\u00eda el acento en cuatro medidas tan concretas como sensatas.<\/p>\n<p>La primera, la anunciada en la entrevista antes rese\u00f1ada. Muy relacionada con ella, modernizar la legislaci\u00f3n sobre contratos p\u00fablicos de forma que primen la sostenibilidad y el cumplimiento de la normativa laboral y medioambiental. La tercera medida: potenciar la colaboraci\u00f3n p\u00fablico-privada. Por \u00faltimo, \u201calinear los fines y objetivos de los centros de promoci\u00f3n de la investigaci\u00f3n, el desarrollo y la innovaci\u00f3n (CDTI, IDEA, ENISA\u2026), con las materias que permitir\u00e1n el desarrollo de productos y servicios que puedan ser esenciales en momentos cr\u00edticos como las pandemias o cualesquiera otros que pretendamos gestionar de forma adecuada\u201d.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/estrategia-para-la-industria\/casi\/\" rel=\"attachment wp-att-30574\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-30574\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Casi-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Casi-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Casi.jpg 624w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Espero que Jos\u00e9 Manuel me disculpe por comprimir de esta manera sus propuestas, ampliamente desarrolladas y argumentadas en un art\u00edculo que, como les dec\u00eda, me parece esencial. Reflexionar sobre las fallas y debilidades de nuestro pa\u00eds durante la pandemia deber\u00eda ser obligatorio para buscar soluciones y, llegado el caso, no volver a incurrir en los mismos errores.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-30278\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-30278 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/01\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace unas semanas, trabajando en el suplemento especial para el D\u00eda de Andaluc\u00eda de este peri\u00f3dico, tuve ocasi\u00f3n de conversar con Jos\u00e9 Manuel Cassinello, director general de Jalsosa, una empresa de trayectoria impecable. Hablamos largo y tendido sobre este a\u00f1o tan complicado y al transcribir sus palabras, ca\u00ed en la cuenta de que no le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[20054,20057,20056,20055,20053,20058],"class_list":["post-30571","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-cassinello-jalsosa","tag-industria-espana-postcovid","tag-industria-espanola","tag-jalsosa","tag-jose-manuel-cassinello","tag-que-hacer-con-la-industria-espanola"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/30571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=30571"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/30571\/revisions"}],"predecessor-version":[{"id":30576,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/30571\/revisions\/30576"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=30571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=30571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=30571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}