{"id":30558,"date":"2021-03-04T09:12:49","date_gmt":"2021-03-04T08:12:49","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=30558"},"modified":"2021-03-04T09:12:49","modified_gmt":"2021-03-04T08:12:49","slug":"ponganmela-pongansela","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/ponganmela-pongansela\/","title":{"rendered":"\u00a1P\u00f3nganmela! \u00a1P\u00f3ngansela!"},"content":{"rendered":"<p>Para viajar al Mal\u00ed, hace ya la intemerata de a\u00f1os, me tuve que poner mil y una vacunas. La mayor\u00eda eran voluntarias, aunque recomendables, incluyendo la profilaxis de la malaria, enfermedad que sigue sin vacuna. Pero hab\u00eda una sin la que no pod\u00edas entrar a la mayor\u00eda de pa\u00edses de \u00c1frica: la de la fiebre amarilla. Era requisito sine qua non. Como tener el pasaporte en regla y pagar una morterada por los visados.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/ponganmela-pongansela\/astra-cartilla\/\" rel=\"attachment wp-att-30559\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-30559\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Astra-Cartilla.jpg\" alt=\"\" width=\"215\" height=\"241\" \/><\/a><\/p>\n<p>Nunca dud\u00e9 en pincharme todo lo que me propon\u00edan los expertos del Centro de Vacunaci\u00f3n Internacional, de la polio a la hepatitis A, el tifus o el c\u00f3lera. Y la fiebre amarilla, claro. Porque, insisto, si no ten\u00edas tu carn\u00e9 de vacunaci\u00f3n en perfecto estado de revista, te quedabas en tierra.<\/p>\n<p>Qui\u00e9n me iba a decir, tantos a\u00f1os despu\u00e9s, que volver\u00eda a estar preocupado por las vacunas y que la cuesti\u00f3n del certificado iba a generar tanta controversia en la Europa del siglo XXI. Vaya por delante que me quiero vacunar. Cuanto antes, mejor. Por edad me toca la AstraZeneca, que no parece tan buena y resolutiva como otras, pero entre el 0% de protecci\u00f3n y el 75%, \u00bfqu\u00e9 quieren que les diga? Ojal\u00e1 hubiera barra libre de Moderna y Pfizer, pero no es el caso.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/ponganmela-pongansela\/astrazeneca\/\" rel=\"attachment wp-att-30560\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-30560\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/AstraZeneca-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/AstraZeneca-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/AstraZeneca-768x512.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/AstraZeneca-644x429.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/AstraZeneca.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Sorprende que muchos de los que hace unos meses dudaban de que las vacunas para la Covid-19 se pudieran desarrollar en tampoco tiempo, ahora se muestren desde\u00f1osos ante una protecci\u00f3n del 75%, mir\u00e1ndola por encima del hombro. Con cuatro millones de personas paradas y otro mill\u00f3n en ERTE, ponernos de forma masiva toda vacuna testada que est\u00e9 disponible en el mercado es un ejercicio de responsabilidad social y solidaridad comunitaria. Y si ahora no nos toca la mejor, ya que hay personas de riesgo que la necesitan antes que nosotros, que nos pongan la siguiente en el escalaf\u00f3n.<\/p>\n<p>\u00bfY la obligatoriedad? Tema espinoso. Ya antes de la pandemia detestaba furibundamente a los antivacunas por ser unos magufos ego\u00edstas que se aprovechaban de la inmunidad del reba\u00f1o, el ejemplo mejor acabado de los progres-regres, como los llamar\u00eda el hermano \u00c1ngel, c\u00e9lebre profesor de los Maristas.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/ponganmela-pongansela\/astra-pasaporte\/\" rel=\"attachment wp-att-30561\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-30561\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Astra-pasaporte-300x158.jpg\" alt=\"\" width=\"300\" height=\"158\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Astra-pasaporte-300x158.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Astra-pasaporte-768x403.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Astra-pasaporte-644x338.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/03\/Astra-pasaporte.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Ser\u00e1 complicado obligar a que todo el mundo se vacune, pero el cartel de \u2018Reservado el derecho de admisi\u00f3n\u2019 va a adquirir una nueva dimensi\u00f3n, har\u00e1 correr r\u00edos de tinta y no tardar\u00e1 en judicializarse. Yo, por si acaso, ya he desempolvado mi vieja cartilla de vacunaci\u00f3n, tan bonica ella.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\/\" target=\"_blank\" rel=\"attachment noopener wp-att-30278\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-30278 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2021\/01\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para viajar al Mal\u00ed, hace ya la intemerata de a\u00f1os, me tuve que poner mil y una vacunas. La mayor\u00eda eran voluntarias, aunque recomendables, incluyendo la profilaxis de la malaria, enfermedad que sigue sin vacuna. Pero hab\u00eda una sin la que no pod\u00edas entrar a la mayor\u00eda de pa\u00edses de \u00c1frica: la de la fiebre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[20042,20047,20046,20043,20045,20044],"class_list":["post-30558","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-astrazeneca","tag-carne-vacunacion-internacional","tag-fiebre-amarilla","tag-pasaporte-covid","tag-ponganmela-pongansela","tag-vacunas-covid"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/30558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=30558"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/30558\/revisions"}],"predecessor-version":[{"id":30563,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/30558\/revisions\/30563"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=30558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=30558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=30558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}