{"id":30159,"date":"2020-12-17T19:27:27","date_gmt":"2020-12-17T18:27:27","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=30159"},"modified":"2020-12-17T19:27:48","modified_gmt":"2020-12-17T18:27:48","slug":"volver-a-las-librerias","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/volver-a-las-librerias\/","title":{"rendered":"Volver a las librer\u00edas"},"content":{"rendered":"<p>Lo que nos ped\u00eda el cuerpo era esperar a que los artistas terminaran de firmar sus tebeos, reci\u00e9n sacados del horno, e irnos a tomar unas ca\u00f1as todos juntos. Pero sigue sin poder ser. Por prudencia. Por sentido com\u00fan.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/volver-a-las-librerias\/enrique-bonet\/\" rel=\"attachment wp-att-30160\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-30160\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/12\/Enrique-Bonet-300x240.jpg\" alt=\"\" width=\"300\" height=\"240\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/12\/Enrique-Bonet-300x240.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/12\/Enrique-Bonet-768x614.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/12\/Enrique-Bonet-644x515.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Est\u00e1bamos en el exterior de la puerta de la librer\u00eda Subterr\u00e1nea, hablando de todo lo divino y lo humano con dibujantes, ilustradores y aficionados al c\u00f3mic mientras Enrique Bonet y Chema Garc\u00eda se afanaban sobre sus obras m\u00e1s recientes, ambas publicadas por la editorial granadina Karras, dedic\u00e1ndolas con trazos, dibujos, interjecciones y bocadillos.<\/p>\n<p>En \u2018Grandes preguntas que se contestan en otros sitios\u2019, Bonet da rienda suelta a su pasi\u00f3n por el universo m\u00edtico de Bruguera a trav\u00e9s de un personaje memorable: Apolonio Martirio, vendedor a domicilio. Son historietas cortas del pasado que, por su humor universal, se disfrutan igual a\u00f1os y a\u00f1os despu\u00e9s. Como las cr\u00f3nicas del desamor de Pepi por Manolo, pasadas por el div\u00e1n contempor\u00e1neo de un descacharrante psiquiatra en riesgo de perder el juicio. Historietas llamadas a hacer pasar un rato delicioso y encantador al lector, nada m\u00e1s y nada menos.<\/p>\n<p>\u2018Una temporada en el desierto\u2019, por su parte, es otra recopilaci\u00f3n. En este caso, de parte del trabajo de Chema Garc\u00eda comprendido entre 2013 y 2020. Surrealismo con toques simp\u00e1ticamente gore, neozombis en busca de autor, homenajes a maestros\u2026 un sabroso y sugerente popurr\u00ed de historietas e ilustraciones que dorm\u00edan el sue\u00f1o de los justos en el disco duro del ordenador hasta que les ha llegado el momento de ver la luz.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/volver-a-las-librerias\/chema-garcia\/\" rel=\"attachment wp-att-30161\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-30161\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/12\/Chema-Garc\u00eda-300x227.jpg\" alt=\"\" width=\"300\" height=\"227\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/12\/Chema-Garc\u00eda-300x227.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/12\/Chema-Garc\u00eda-768x581.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/12\/Chema-Garc\u00eda-644x487.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Qu\u00e9 gustazo volver a juntarse, aunque fuera plantados en mitad de la calle y embozados (casi) hasta los ojos, y hablar de libros reci\u00e9n publicados y de proyectos de futuro. Durante un rato, pareci\u00f3 que salt\u00e1bamos a una realidad paralela, dejando atr\u00e1s curvas y estad\u00edsticas de contagios y muertes.<\/p>\n<p>Es uno de los efectos colaterales de La Cosa: nos mantiene amarrados a un desalentador e interminable presente en el que pensar m\u00e1s all\u00e1 de las pr\u00f3ximas dos semanas se antoja algo quim\u00e9rico.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/volver-a-las-librerias\/subterranea-comics\/\" rel=\"attachment wp-att-30162\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-30162\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/12\/Subterr\u00e1nea-C\u00f3mics-300x212.jpg\" alt=\"\" width=\"300\" height=\"212\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/12\/Subterr\u00e1nea-C\u00f3mics-300x212.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/12\/Subterr\u00e1nea-C\u00f3mics-768x543.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/12\/Subterr\u00e1nea-C\u00f3mics-644x455.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/12\/Subterr\u00e1nea-C\u00f3mics.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Muchas gracias a la editorial Karras por lanzarse a esta locurilla editorial precisamente en estos momentos. A Enrique Bonet y Chema Garc\u00eda por brindarse a firmar y dedicar sus libros. A Paco, el fact\u00f3tum de la librer\u00eda Subterr\u00e1nea, por acoger un evento cultural que, con todas las medidas sanitarias, nos reconcilia con quienes fuimos un d\u00eda y aspiramos a volver a ser. A no mucho tardar, vacuna mediante.<\/p>\n<p>Este fin de semana, antes de que todo se desmande, dos citas presenciales: el el Teatro CajaGranada, el s\u00e1bado a las 12 del mediod\u00eda, Memorial Antonio Lozano de Granada Noir, hablando de c\u00f3mics con Bonet y Chema, con El Bute, Hern\u00e1ndez Walta, Joaqu\u00edn L\u00f3pez Cruces y Olga de Castro. Y el domingo, en Subterr\u00e1nea, firma de tebeos con Gabriel Hern\u00e1ndez Walta y El Torres. \u00a1Si pod\u00e9is, venid!<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/notifications\" target=\"_blank\" rel=\"attachment noopener wp-att-30094\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-30094 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/12\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo que nos ped\u00eda el cuerpo era esperar a que los artistas terminaran de firmar sus tebeos, reci\u00e9n sacados del horno, e irnos a tomar unas ca\u00f1as todos juntos. Pero sigue sin poder ser. Por prudencia. Por sentido com\u00fan. Est\u00e1bamos en el exterior de la puerta de la librer\u00eda Subterr\u00e1nea, hablando de todo lo divino [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,19],"tags":[10664,19230,2874,15001,19779,15387,18229,19780],"class_list":["post-30159","post","type-post","status-publish","format-standard","hentry","category-opinion","category-tebeos","tag-cajagranada-fundacion","tag-el-bute","tag-enrique-bonet","tag-gabriel-hernandez-walta","tag-karras-comics","tag-librerias-picasso","tag-memorial-antonio-lozano","tag-volver-a-las-librerias"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/30159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=30159"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/30159\/revisions"}],"predecessor-version":[{"id":30164,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/30159\/revisions\/30164"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=30159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=30159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=30159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}