{"id":29819,"date":"2020-10-18T10:40:18","date_gmt":"2020-10-18T09:40:18","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=29819"},"modified":"2020-10-19T10:45:11","modified_gmt":"2020-10-19T09:45:11","slug":"movimiento-explosivo-de-contagios","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/movimiento-explosivo-de-contagios\/","title":{"rendered":"Movimiento explosivo de contagios"},"content":{"rendered":"<p>As\u00ed defini\u00f3 el consejero de Salud de la Junta de Andaluc\u00eda lo que est\u00e1 ocurriendo en Granada. De ah\u00ed sus igualmente impactantes declaraciones, recogidas en la portada del IDEAL de ayer: \u00abRogamos a los granadinos que se queden en sus casas\u00bb.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/movimiento-explosivo-de-contagios\/0-ex\/\" rel=\"attachment wp-att-29820\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-29820\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/10\/0-Ex-228x300.jpg\" alt=\"\" width=\"228\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/10\/0-Ex-228x300.jpg 228w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/10\/0-Ex-644x846.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/10\/0-Ex.jpg 731w\" sizes=\"auto, (max-width: 228px) 100vw, 228px\" \/><\/a><\/p>\n<p>Contrasta este dramatismo con la laxitud con la que se ha gestionado la segunda ola de la pandemia en las \u00faltimas semanas, con el mantra \u2018Granada es una ciudad segura\u2019 enarbolado hasta el hartazgo de una forma a todas luces irresponsable. Daba igual que el \u00edndice de contagios estuviera disparado muy por encima de 500. Lo \u00fanico importante era petarlo en el puente del Pilar. Y se consigui\u00f3. \u00a1Vaya si se consigui\u00f3! \u00bfA qu\u00e9 precio? Ahora nos estamos cobrando la factura.<\/p>\n<p>Pero esto ya va m\u00e1s all\u00e1 de Granada y \u00e1rea metropolitana. La pandemia est\u00e1 descontrolada en toda Espa\u00f1a y, de momento, cada comunidad aut\u00f3noma hace la guerra por su cuenta, implantando toques de queda, cierres parciales y limitaciones a la movilidad. O no, que esa es otra.<\/p>\n<p>En Madrid, por ejemplo, puedes zamparte un cocido con tres vuelcos en una tasca del barrio, pero nada de salir fuera de los l\u00edmites perimetrales. En Catalunya, sin embargo, aunque puedes viajar a Valencia a tomarte una paella del se\u00f1oret, no te puedes desayunar un pantumaca en el bar de la esquina, que est\u00e1 chapada toda la hosteler\u00eda.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/menos-turistas-mas-vecinos\/jardin-estres\/\" rel=\"attachment wp-att-29644\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-29644\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/Jard\u00edn-estr\u00e9s-300x214.jpg\" alt=\"\" width=\"300\" height=\"214\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/Jard\u00edn-estr\u00e9s-300x214.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/Jard\u00edn-estr\u00e9s.jpg 512w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>\u00a1Qu\u00e9 tocado va a salir de la pandemia el estado de las autonom\u00edas! Como dec\u00eda Saza al final de \u2018Amanece que no es poco\u2019, no hay quien aguante este sindi\u00f3s. \u00bfA qu\u00e9 espera el ministerio de Sanidad para marcar unas directrices claras sobre qu\u00e9 hacer en el futuro inmediato? Todos los cient\u00edficos a los que he le\u00eddo estos d\u00edas alertan de lo extremadamente duros que van a ser los pr\u00f3ximos meses. Ya lo est\u00e1n siendo. \u00bfHar\u00e1 algo el gobierno de S\u00e1nchez o seguir\u00e1 ensimismado en su juego de jueces con Casado?<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-29227\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29227 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed defini\u00f3 el consejero de Salud de la Junta de Andaluc\u00eda lo que est\u00e1 ocurriendo en Granada. De ah\u00ed sus igualmente impactantes declaraciones, recogidas en la portada del IDEAL de ayer: \u00abRogamos a los granadinos que se queden en sus casas\u00bb. Contrasta este dramatismo con la laxitud con la que se ha gestionado la segunda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[18202,19560,19561],"class_list":["post-29819","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-jesus-aguirre","tag-movimiento-explosivo-de-contagios","tag-si-me-quereis-quedarse"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/29819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=29819"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/29819\/revisions"}],"predecessor-version":[{"id":29822,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/29819\/revisions\/29822"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=29819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=29819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=29819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}