{"id":29719,"date":"2020-09-30T11:06:09","date_gmt":"2020-09-30T10:06:09","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=29719"},"modified":"2020-09-30T11:06:09","modified_gmt":"2020-09-30T10:06:09","slug":"una-de-q-onspiraciones","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/una-de-q-onspiraciones\/","title":{"rendered":"Una de Q-onspiraciones"},"content":{"rendered":"<p>Llevo varios d\u00edas dudando si escribir o no escribir esta columna, absurda y conspiranoica, porque servir\u00e1 para darle algo m\u00e1s de visibilidad a uno de los grandes disparates del momento que, sin embargo, puede tener incidencia en las elecciones norteamericanas.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/una-de-q-onspiraciones\/qanon\/\" rel=\"attachment wp-att-29720\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-29720\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/QAnon-232x300.jpg\" alt=\"\" width=\"232\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/QAnon-232x300.jpg 232w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/QAnon.jpg 387w\" sizes=\"auto, (max-width: 232px) 100vw, 232px\" \/><\/a><\/p>\n<p>Que dir\u00e1n ustedes que, con la que tenemos encima, aqu\u00ed y ahora, a qui\u00e9n le importa Trump y sus cosillas. Y no les faltar\u00e1 raz\u00f3n. Pero es sintom\u00e1tico sobre el peligro de las redes que avientan incendios y propagan informaci\u00f3n t\u00f3xica sin ton ni son.<\/p>\n<p>La teor\u00eda conspiranoica del momento en Estados Unidos se llama QAnon y ya tiene su propia entrada en la Wikipedia, faltar\u00eda m\u00e1s. En breve: los sectores liberales de los Estados Unidos, entre ellos ciertas luminarias de Hollywood, George Soros, Obama y Hillary Clinton; formar\u00edan parte de una red internacional de tr\u00e1fico sexual de ni\u00f1os para la realizaci\u00f3n de actos ped\u00f3filos.<\/p>\n<p>\u00bfC\u00f3mo se quedan? Ni que decir tiene, Trump ser\u00eda el adalid de la lucha contra esos monstruos, que forman parte del llamado Deep State, el Estado Profundo que lucha para sacar a los republicanos de la Casa Blanca. Es lo que tienen los pozos sin fondo de la red oscura y paralela a la realidad.<\/p>\n<p>Lo s\u00e9, lo s\u00e9. Es demencial. Y parad\u00f3jico: cada vez que escribimos \u2018QAnon\u2019 le damos alas a sus oligofr\u00e9nicas teor\u00edas. La cuesti\u00f3n no es balad\u00ed, sin embargo, dado que una candidata al senado por Oreg\u00f3n es fiel seguidora y adalid de la Q-onspiraci\u00f3n y podr\u00eda acabar llegando al Capitolio.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/una-de-q-onspiraciones\/qanon-trump\/\" rel=\"attachment wp-att-29721\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-29721\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/QAnon-Trump-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/QAnon-Trump-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/QAnon-Trump-644x362.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/QAnon-Trump.jpg 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Vivimos tiempos extra\u00f1os y confusos. Esto se parece cada vez m\u00e1s al t\u00e9trico universo retratado en \u2018El nombre de la rosa\u2019, con el la imagen de un supuesto Maligno presente en todas las conversaciones. Y mientras, el presidente estadounidense que lleg\u00f3 al cargo con el lema \u2018Make America great again\u2019, solo pag\u00f3 750 d\u00f3lares de impuestos en los ejercicios fiscales 2016 y 2017, seg\u00fan The New York Times. Poco se puede empujar con esa contribuci\u00f3n a las arcas del estado\u2026<\/p>\n<p>Dir\u00e1n ustedes que, ampar\u00e1ndome en la Q, estoy soslayando la cuesti\u00f3n de la S de Salvador, Luis Salvador. Y no es as\u00ed. Son muy graves las acusaciones que se est\u00e1n haciendo sobre su forma de gestionar su positivo y el de su colaborador m\u00e1s cercano. De confirmarse que, a pesar de tener s\u00edntomas apreciables de Covid, siguieron con su agenda, no va a hacer falta apelar al 2+2 para que se abra una grave crisis en el gobierno municipal.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-29227\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29227 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llevo varios d\u00edas dudando si escribir o no escribir esta columna, absurda y conspiranoica, porque servir\u00e1 para darle algo m\u00e1s de visibilidad a uno de los grandes disparates del momento que, sin embargo, puede tener incidencia en las elecciones norteamericanas. Que dir\u00e1n ustedes que, con la que tenemos encima, aqu\u00ed y ahora, a qui\u00e9n le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[19498,19496,19497],"class_list":["post-29719","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-make-america-great-again","tag-qanon","tag-qanon-trump"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/29719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=29719"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/29719\/revisions"}],"predecessor-version":[{"id":29723,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/29719\/revisions\/29723"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=29719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=29719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=29719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}